{"id":89727,"date":"2018-02-14T17:40:02","date_gmt":"2018-02-14T16:40:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nuovo-crollo-a-cosenza-vecchia-cede-un-muro-due-famiglie-in-strada\/"},"modified":"2023-01-16T18:49:44","modified_gmt":"2023-01-16T17:49:44","slug":"202145-nuovo-crollo-a-cosenza-vecchia-cede-un-muro-due-famiglie-in-strada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202145-nuovo-crollo-a-cosenza-vecchia-cede-un-muro-due-famiglie-in-strada\/","title":{"rendered":"Ancora crolli a Cosenza Vecchia: cede un muro, strada bloccata e famiglie evacuate (FOTO)"},"content":{"rendered":"<h4>I residenti da mesi avevano segnalato il rischio senza ottenere alcun tipo di intervento di messa in sicurezza<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Un muro si \u00e8 sbriciolato su se stesso oggi nel centro storico di Cosenza. Intorno alle 17.30, nel rione Massa, i residenti sono stati allertati da un boato. Le macerie hanno invaso la carreggiata intasando\u00a0la strada meglio conosciuta come ex salita Sant&#8217;Agostino, poco distante dal museo dei Bretti e degli Enotri, su cui al momento \u00e8 impossibile transitare. Dall&#8217;inizio dell&#8217;estate gli abitanti del quartiere avevano provveduto a segnalare al Comune di Cosenza l&#8217;abbassamento del manto stradale, con il muro che risultava ormai distaccato dal suolo per almeno dieci centimetri. L&#8217;intervento della polizia municipale si era limitato ad apporre due transenne in ferro e del nastro rosso di plastica, scomparsi dopo pochissime settimane. Una messa in sicurezza non solo poco efficace, ma<strong> anche pericolosa visto che lo spazio su cui il muro \u00e8 crollato viene usato sia come parcheggio sia come area giochi per i bimbi<\/strong>. La struttura che ha ceduto confina con un&#8217;abitazione che ospita due famiglie, riversatesi ora in strada in attesa di capire se le proprie case sono agibili o meno. Sul posto sono prontamente intervenuti i Vigili del Fuoco, mentre la Polizia municipale ha raggiunto il rione Massa dopo circa un&#8217;ora dall&#8217;allerta.<\/p>\n<p>&nbsp;<\/p>\n<p>In merito la Polizia Municipale ha inteso precisare attraverso una nota del\u00a0DICCAP Dipartimento Autonomie Locali e Polizie Locali Segreteria Regionale Calabria che: &#8220;in caso di crolli, ha come <strong>compito esclusivo quello di evitare che, nelle zone pericolose, indicate dai Vigili del Fuoco e dalla protezione civile, possano passare pedoni o mezzi<\/strong>, e, per questo, delimita la zona interessata con transenne e nastro segnaletico. Non ha competenze specifiche tecniche, n\u00e9 tantomeno idonea attrezzatura per individuare le cause dei crolli o rimuovere parti pericolanti dei fabbricati o dei manufatti interessati&#8221;.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>I residenti da mesi avevano segnalato il rischio senza ottenere alcun tipo di intervento di messa in sicurezza<\/p>\n","protected":false},"author":22,"featured_media":89728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-89727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89727"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89728"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}