{"id":89737,"date":"2018-02-15T11:08:54","date_gmt":"2018-02-15T10:08:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/video-le-iene-e-il-parroco-chi-deve-vergognarsi-di-certo-non-francesca\/"},"modified":"2023-01-16T18:49:44","modified_gmt":"2023-01-16T17:49:44","slug":"202212-video-le-iene-e-il-parroco-chi-deve-vergognarsi-di-certo-non-francesca","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202212-video-le-iene-e-il-parroco-chi-deve-vergognarsi-di-certo-non-francesca\/","title":{"rendered":"(VIDEO) Le Iene, il parroco, l&#8217;ex vescovo: chi deve vergognarsi? Di certo non Francesca"},"content":{"rendered":"<h4>Nessuno dei &#8220;protagonisti&#8221; presenti nel servizio trasmesso ieri sera\u00a0su Italia 1, ha provato vergogna e anche un soffio di senso di colpa per quanto fatto a Francesca la vera vittima di tutta questa assurda vicenda<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La <strong>vera vittima \u00e8 lei, Francesca<\/strong>, una giovane donna costretta ad abortire, convinta dall&#8217;uomo-prete e dal Vescovo che ha tutelato gli interessi &#8220;morali&#8221; della sua Chiesa a nascondere cosa aveva fatto un parroco della sua Diocesi. La storia di Francesca \u00e8 molto triste\u00a0oltre che\u00a0grave. Una donna che si invaghisce di un giovane prete, che le fa i complimenti, la bacia, le promette il suo amore e poi dopo averle\u00a0fatto perdere la sua verginit\u00e0 la induce ad abortire\u00a0il\u00a0figlio nato dalla loro relazione. Una storia che ha segnato profondamente\u00a0la ragazza\u00a0che nel servizio andato in onda ieri sera, ha raccontato dei tentativi di\u00a0togliersi la vita per quel figlio che\u00a0la Chiesa, nella quale credeva,\u00a0le ha fatto uccidere.\u00a0Il &#8216;piccolo&#8217; prete che ha<strong> violato la sua &#8216;vocazione&#8217;<\/strong> per avere un rapporto con una giovane donna e che poi, alla notizia di una gravidanza, \u00e8 scappato via vigliaccamente, lasciandola da sola ad affrontare quella terribile situazione. Francesca, racconta, \u00e8 una parrocchiana poco pi\u00f9 che maggiorenne\u00a0quando conosce il giovane &#8220;don Giuseppe&#8221; appena arrivato nella sua parrocchia. In poco tempo &#8220;da guida spirituale per me diventa qualcosa di pi\u00f9. Lui mi diceva che avrebbe lasciato la Chiesa per me&#8221;. E Francesca si affida totalmente a <strong>don Giuseppe, definendolo il suo &#8216;primo&#8217; uomo.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-202229 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/mons-nunnari-.jpg\" alt=\"mons nunnari\" width=\"482\" height=\"267\" title=\"\"><strong>&#8220;Lui era con me quando ho scoperto, di essere incinta facendo\u00a0il test di gravidanza&#8221;<\/strong>\u00a0e Francesca racconta che il prete l&#8217;aveva anche rassicurata: &#8220;avrebbe\u00a0lasciato tutto per quel bambino&#8221;. Ma quando il test risult\u00f2 positivo, lui inizi\u00f2 a piangere e da quel giorno inizi\u00f2 un vero e proprio incubo. Una notizia bella che porta felicit\u00e0, stava per diventare la sua condanna. Quel bimbo, Francesca, avrebbe voluto tenerlo, ma i comportamenti di don Giuseppe cambiano&#8230;\u00a0 nei toni e parole, era diventato aggressivo: &#8220;<strong>venni lasciata sola come una pezza<\/strong>. &#8220;Ed \u00e8 allora &#8211; continua il racconto della ragazza &#8211; che il giovane prete, la spinse ad andare a parlare con il<strong> Vescovo (all&#8217;epoca mons. Salvatore Nunnari)<\/strong> che anzich\u00e9 aiutarla\u00a0<strong>la invit\u00f2 a non far uscire fuori quella storia perch\u00e9 avrebbe rappresentato un duro colpo per la sua Chiesa<\/strong>. &#8220;Nunnari mi diede due possibilit\u00e0: tenere il figlio e partire lontano oppure abortire e continuare a vivere la mia vita cos\u00ec com&#8217;era&#8221;<\/p>\n<p>La ragazza abort\u00ec\u00a0recandosi in un centro: &#8220;<em>quando sono uscita mi sentivo sporca, la mia vita \u00e8 cambiata. Non c&#8217;\u00e8 giorno che non ci penso, questa storia mi ha devastata. Non ero pi\u00f9 considerata una ragazza perbene e non avevo l&#8217;appoggio di nessuno<\/em>&#8220;.<\/p>\n<h4><span style=\"color: #ff0000;\"><strong>IL SERVIZIO\u00a0&#8211;\u00a0Pu\u00f2 la chiesa spingere una donna ad abortire?<\/strong><\/span><br \/>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-89737-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163942_16195d4c7c77d2\/16195d4c7c77d2-20_0.mp4?_=1\" \/><a href=\"http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163942_16195d4c7c77d2\/16195d4c7c77d2-20_0.mp4\" rel=\"noopener\">http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163942_16195d4c7c77d2\/16195d4c7c77d2-20_0.mp4<\/a><\/video><\/div><br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/h4>\n<h4>Il sacerdote che l&#8217;ha difesa: &#8220;il vero nodo \u00e8 al Palazzo, chi \u00e8 pi\u00f9 forte? Io o una Chiesa che ti schiaccia come un carrarmato?&#8221;<\/h4>\n<p>Lo riconosco dalla voce ma ovviamente non diffonderemo il suo nome.\u00a0E&#8217; il sacerdote che Valeria Castellano ha intervistato chiedendo spiegazioni: &#8220;<em>Perch\u00e9 ti fai costringere ad abortire, \u00e8 un vescovo, chi cazzo \u00e8 un vescovo? E&#8217; un porco, scusami la franchezza<\/em> &#8211; dichiara alla giornalista &#8211; <em>Se avesse trovato un vescovo, cio\u00e8 rappresentante di Ges\u00f9, gli avrebbe detto quello che le ha detto? Questo \u00e8 il punto<\/em>.<em> Il vero nodo \u00e8 al Palazzo, invece di trovare un Padre, tu trovi un giudice che ti condanna a morte&#8221;.<\/em>\u00a0Il sacerdote ha dichiarato di avere anche pensato di denunciare la cosa, ma di avere avuto paura di innescare &#8220;meccanismi che possono nuocere\u00a0alla ragazza. &#8220;<em>Chi \u00e8 pi\u00f9 forte, io? O una Chiesa che\u00a0si muove come un carrarmato e ti schiaccia e ti ignora?<\/em>&#8220;.<\/p>\n<h3>L&#8217;aggressione subita dalla giornalista Valeria Castellano e dall&#8217;operatrice Giulia Mascaro<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-202227 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/don-giuseppe-parroco-san-vincenzo.jpg\" alt=\"don giuseppe parroco san vincenzo\" width=\"483\" height=\"269\" title=\"\">Tredici minuti integrali per raccontare come \u00e8 andata veramente e come la Castellano e la Mascaro, sono state fatte oggetto di botte e percosse tali da procurare loro <strong>18 giorni di prognosi<\/strong>. L&#8217;aggressione, dalle immagini, \u00e8 avvenuta ad opera del padre di don Giuseppe. Immagini abbastanza eloquenti definite dai conduttori Blasi, Mammuccari e dalla Gialappa&#8217;s &#8220;uno schifo&#8221; visto\u00a0 che degli uomini si siano scagliati cos\u00ec violentemente contro due ragazze, per giunta anche esili e che chiedevano a gran voce agli aggressori di smetterla. Un servizio finito come la stessa giornalista Castellano, che era intervenuta anche su Rlb in un&#8217;intervista<a href=\"https:\/\/quicosenza.it\/news\/3832\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong> (LEGGI QUI)<\/strong> <\/span><\/a>aveva intenzione di mandare in onda in un altro modo: con il prete reso irriconoscibile, al quale sarebbe stato coperto il volto e cambiata la voce.<\/p>\n<p>Ma \u00e8 andata a finire diversamente, con la <strong>madre del parroco proferire parolacce<\/strong> verso le due ragazze e l&#8217;aggressione che tutti abbiamo visto. Quello che appare molto grave \u00e8 <strong>il silenzio per anni dell&#8217;ex vescovo dell&#8217;arcidiocesi di Cosenza<\/strong>, a conoscenza della storia drammatica di Francesca\u00a0e quello dell&#8217;attuale arcivescovo Nol\u00e8. <strong>Un silenzio imbarazzante <\/strong>che non fa vergognare chi dovrebbe e che di certo non ha nulla a che vedere con quelli che dovrebbero essere i &#8216;dettami&#8217; di un cristiano.<\/p>\n<p>Ed \u00e8 su Francesca che vogliamo porre l&#8217;attenzione, non sulla madre\u00a0ed il padre di don Giuseppe o sul\u00a0Vescovo Emerito Nunnari che alla giornalista Valeria Castellano sulla vicenda nel servizio dichiara:&#8221;<em>Sono passati anni,\u00a0lui ha chiesto il perdono, si \u00e8 confessato. Adesso ha ripreso a fare il prete&#8230; Io non mai detto alla ragazza di abortire e non ho abbandonato nessuno.<strong>\u00a0<\/strong><\/em>&#8220;. Ma in tal caso &#8220;il fondamento della vergogna non \u00e8 lo sbaglio personale, bens\u00ec che l&#8217;umiliazione sia visibile da tutti&#8221;. Ed \u00e8 stata proprio questa la fotografia restituita ieri dal servizio di Valeria Castellano: <strong>un parroco che si \u00e8 vergognato solo perch\u00e9 la storia che lo ha visto protagonista \u00e8 uscita allo scoperto<\/strong>\u00a0e non per aver distrutto la vita di una donna che ha anche tentato di togliersi la vita. La stessa vita che un prete dovrebbe salvaguardare e accudire. La vergogna non era negli occhi delle persone coinvolte in questa triste vicenda, ma purtroppo in quelli di Francesca, anche se non abbiamo potuto vederli.<\/p>\n<h4><\/h4>\n<h4><span style=\"color: #ff0000;\"><strong>VIDEO\u00a0 &#8211;\u00a0Aggressione alla Iena Castellano: filmato integrale<\/strong><\/span><\/h4>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-89737-2\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163977_161960395467d2\/161960395467d2-20_0.mp4?_=2\" \/><a href=\"http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163977_161960395467d2\/161960395467d2-20_0.mp4\" rel=\"noopener\">http:\/\/vod06.msf.ticdn.it\/farmunica\/2018\/02\/163977_161960395467d2\/161960395467d2-20_0.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nessuno dei &#8220;protagonisti&#8221; presenti nel servizio trasmesso ieri sera\u00a0su Italia 1, ha provato vergogna e anche un soffio di senso di colpa per quanto fatto a Francesca la vera vittima di tutta questa assurda vicenda<\/p>\n","protected":false},"author":19,"featured_media":89738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-89737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89737"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}