{"id":89775,"date":"2018-02-15T18:25:17","date_gmt":"2018-02-15T17:25:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/carabinieri-setacciano-le-palazzine-popolari-di-rossano\/"},"modified":"2023-01-16T18:49:47","modified_gmt":"2023-01-16T17:49:47","slug":"202384-carabinieri-setacciano-le-palazzine-popolari-di-rossano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202384-carabinieri-setacciano-le-palazzine-popolari-di-rossano\/","title":{"rendered":"Carabinieri setacciano le palazzine popolari di Rossano per stanare gli occupanti"},"content":{"rendered":"<h4>Un arresto e sette denunciati dopo il blitz. Le accuse:\u00a0furto di energia elettrica, invasione di edifici e abusivismo edilizio<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROSSANO (CS) &#8211; Questa mattina i carabinieri di Rossano hanno perlustrato i quartieri &#8216;caldi&#8217; della citt\u00e0 e gli alloggi popolari. Oltre quaranta militari sono intervenuti insieme ai funzionari dell\u2019Aterp\u00a0e ai tecnici delle societ\u00e0 che gestiscono le reti elettriche e del gas. I controlli sono stati finalizzati a verificare i titoli di occupazione dei residenti e l&#8217;esistenza di eventuali furti di energia elettrica. Piazza Nino Chefalo nella zona \u201cScalo\u201d e via San Nilo, nel Centro Storico, sono state sottoposte ad un accurata ispezione da parte dei carabinieri, i quali hanno riscontrato, grazie agli elenchi forniti dall\u2019Aterp che alcuni degli occupanti erano all\u2019interno degli appartamenti senza averne titolo. Alcuni di loro avevano inoltre effettuato allacci abusivi alla rete elettrica che consentivano di alimentare due appartamenti. I tecnici specializzati hanno cos\u00ec provveduto a rimettere in sicurezza i luoghi. In pi\u00f9 in un caso gli uomini dell\u2019Arma hanno riscontrato la presenza di manufatti abusivi in aree di pubblico passaggio, costruite in beffa ad ogni autorizzazione e ad ogni pagamento di concessioni edilizie.<strong> Il risultato dell\u2019operazione \u00e8 di un arresto in flagranza di reato per furto aggravato di energia elettrica e di sette denunciati in stato di libert\u00e0 alla competente Autorit\u00e0 Giudiziaria per i reati di invasione di edifici e di abusivismo edilizio<\/strong>, ai sensi della vigente normativa. Il Comando Provinciale dei Carabinieri di Cosenza ha annunciato ulteriori controlli nelle prossime settimane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un arresto e sette denunciati dopo il blitz. Le accuse:\u00a0furto di energia elettrica, invasione di edifici e abusivismo edilizio<\/p>\n","protected":false},"author":22,"featured_media":89776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-89775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89775"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89776"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}