{"id":89779,"date":"2018-02-16T05:43:51","date_gmt":"2018-02-16T04:43:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/statale-107-cosenza-paola-oggi-ultimazione-della-messa-sicurezza\/"},"modified":"2023-01-16T18:49:47","modified_gmt":"2023-01-16T17:49:47","slug":"202414-statale-107-cosenza-paola-oggi-ultimazione-della-messa-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202414-statale-107-cosenza-paola-oggi-ultimazione-della-messa-sicurezza\/","title":{"rendered":"Statale 107 Cosenza-Paola, installati container di protezione. I nuovi orari dei bus"},"content":{"rendered":"<h4>La Protezione Civile Regionale ha ultimato ieri sera l&#8217;attivit\u00e0 di installazione di 15 containers metallici che costituiranno una protezione temporanea della sede stradale.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Nella mattinata di oggi i containers saranno zavorrati e resi solidali con funi d&#8217;acciaio. Sempre oggi due squadre di rocciatori ultimeranno la pulizia ed il disgaggio dei massi pericolanti sulla scarpata. Inoltre saranno messe in opera lungo la scarpata delle reti di acciaio ancorate. Ultimate tali attivit\u00e0 potr\u00e0 dirsi conclusa la messa in sicurezza di emergenza e potr\u00e0 essere riaperto al traffico (monitorato e condizionato) il tratto della 107 interessato dal dissesto. Riapertura che, in ogni caso, non potr\u00e0 avvenire prima di questa sera o, al pi\u00f9 tardi, di sabato mattina, secondo quanto previsto da Anas. Successivamente, a traffico aperto, sempre l&#8217;Anas proceder\u00e0 alla messa in sicurezza definitiva.<\/p>\n\n<p>&nbsp;<\/p>\n<h3 dir=\"auto\">Trenitalia e gli orari dei servizi bus sostitutivi<\/h3>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Trenitalia comunica che, a causa\u00a0della frana sulla SS107, i servizi bus sostitutivi attivi sulla Cosenza-Paola subiranno una variazione del percorso (via A3-Svincolo Falerna-SS18) e un conseguente allungamento dei tempi di percorrenza di un&#8217;ora.\u00a0 A seguire il programma orario per la giornata di oggi, in attesa di ulteriori informazioni sul ripristino della strada interrotta.<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-202430 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/bus-trenitalia-02.jpg\" alt=\"bus trenitalia 02\" width=\"705\" height=\"474\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-202429 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/bus-trenitalia-01.jpg\" alt=\"bus trenitalia 01\" width=\"719\" height=\"453\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Protezione Civile Regionale ha ultimato ieri sera l&#8217;attivit\u00e0 di installazione di 15 containers metallici che costituiranno una protezione temporanea della sede stradale.<\/p>\n","protected":false},"author":22,"featured_media":89780,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,28],"tags":[],"class_list":["post-89779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89779"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89780"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}