{"id":89810,"date":"2018-02-16T12:30:32","date_gmt":"2018-02-16T11:30:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/impianti-lorica-consigliere-regionale-le-false-promesse-oliverio\/"},"modified":"2023-01-16T18:49:49","modified_gmt":"2023-01-16T17:49:49","slug":"202496-impianti-lorica-consigliere-regionale-le-false-promesse-oliverio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202496-impianti-lorica-consigliere-regionale-le-false-promesse-oliverio\/","title":{"rendered":"Impianti Lorica, consigliere regionale: &#8220;le false promesse di Oliverio&#8221;"},"content":{"rendered":"<h4>&#8220;G<strong>ennaio \u00e8 passato e febbraio volge al termine ed ancora tutto tace&#8221;<\/strong><\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LORICA (CS) &#8211; &#8220;Dopo proclami e annunci, oggi, pur in presenza di una bellissima coltre di neve, registriamo la <strong>non apertura degli impianti di risalita di Lorica.<\/strong>&#8220;<strong>\u00a0<\/strong>E&#8217; ci\u00f2 che dichiara\u00a0<strong>Fausto Orsomarso, <\/strong>consigliere regionale Fratelli d&#8217;Italia Calabria.\u00a0&#8220;Il presidente Oliverio &#8211; continua &#8211; i primi giorni di novembre durante la conferenza stampa nel Centro canottaggio di Lorica, aveva preannunciato l\u2019inaugurazione degli impianti per dicembre, tuttavia<strong> gennaio \u00e8 passato e febbraio volge al termine ed ancora tutto tace.<\/strong> Una regione ricca di bellezze naturali che potrebbe fare del turismo una delle sue principali fonti di attrazione e di risorsa economica, si ritrova <strong>ferma al punto di partenza con impianti nuovi, mai utilizzati e non ancora collaudati.\u00a0<\/strong> Chiedo fermamente al Presidente della Regione Calabria\u00a0\u00a0di mantenere gli impegni presi e di\u00a0\u00a0intervenire per <strong>velocizzare l\u2019iter di apertura dei nuovi impianti sciistici che rappresenta un importantissimo volano di sviluppo per il nostro territorio.<\/strong> La stagione invernale sta volgendo al termine e ancora una volta la Giunta Oliverio ha generato false aspettative nella popolazione e negli operatori economici che del turismo potrebbero farne la ricchezza pi\u00f9 grande per la nostra Regione.&#8221;<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">LEGGI ANCHE:<\/h3>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3862\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Lorica: arriva la neve, ma gli impianti restano chiusi<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3917\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Impianti Lorica, Oliverio: \u201ccollaudo entro il 15 gennaio, poi l\u2019apertura\u201d. Ma una data non c\u2019\u00e8<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/3918\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Gli impianti di Lorica sono chiusi e non c\u2019\u00e8 ancora data certa per l\u2019apertura (AUDIO)<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Gennaio \u00e8 passato e febbraio volge al termine ed ancora tutto tace&#8221;<\/p>\n","protected":false},"author":21,"featured_media":89811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-89810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89810"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89811"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}