{"id":89883,"date":"2018-02-22T05:30:50","date_gmt":"2018-02-22T04:30:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-via-la-campagna-di-sensibilizzazione-ambientale-per-una-provincia-differente\/"},"modified":"2023-01-16T18:49:54","modified_gmt":"2023-01-16T17:49:54","slug":"202856-al-via-la-campagna-di-sensibilizzazione-ambientale-per-una-provincia-differente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/202856-al-via-la-campagna-di-sensibilizzazione-ambientale-per-una-provincia-differente\/","title":{"rendered":"Al via la campagna di sensibilizzazione ambientale \u201c\u2026per una Provincia Differente\u201d"},"content":{"rendered":"<h4>Il progetto, patrocinato dalla Provincia e promosso da ALESSCO torna a coinvolgere scuole, cittadini e amministratori dei 155 comuni del territorio<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Si alza il sipario sulla seconda edizione della campagna di <strong>sensibilizzazione ambientale alla raccolta differenziata e al riciclo \u201cper una Provincia Differente\u201d<\/strong> promossa da Alessco, Agenzia Locale per l\u2019Energia e lo Sviluppo Sostenibile della Provincia di Cosenza, con il supporto della Provincia. La presentazione del progetto sar\u00e0 ufficializzata nel corso della conferenza stampa prevista per domani,\u00a0<strong>23 febbraio alle ore 12.00 nella Sala degli Stemmi della Provincia di Cosenza<\/strong>. Riprende, pertanto, con grande partecipazione, l\u2019attivit\u00e0 di formazione che nella prima edizione ha coinvolto <strong>oltre quattromila studenti delle scuole primarie e secondarie di primo e secondo grado del territorio provinciale<\/strong>, impegnati non solo in un percorso info-formativo organizzato dallo staff ALESSCO sulla raccolta differenziata e sul riciclo, ma anche in attivit\u00e0 ludiche e in un concorso di idee finalizzato alla premiazione degli istituti pi\u00f9 virtuosi con computer portatili e gadget. <strong>Accanto al tema della raccolta differenziata, quest\u2019anno saranno trattati anche quelli di prevenzione e riciclo<\/strong>; in particolare, si parler\u00e0 di spreco alimentare e compostaggio domestico.<\/p>\n<p>L\u2019impegno della Provincia e di ALESSCO, dunque, riparte proprio dalle scuole. Con una nuova sfida e una nuova rivoluzione culturale per interiorizzare i principi dell\u2019educazione attraverso il coinvolgimento degli studenti &#8211; <strong>si prevedono incontri educativi presso le scuole &#8211; e visite guidate a\u00a0<\/strong>: Rimuseum \u2013 Museo per l\u2019Ambiente dell\u2019Universit\u00e0 della Calabria e all\u2019isola ecologica di Ecologia Oggi e all\u2019impianto di trattamento di Calabra Maceri. Gli stessi saranno nuovamente protagonisti attivi del <strong>\u201cConcorso di idee\u201d<\/strong>\u00a0 attraverso tre differenti percorsi: alle scuole primarie sar\u00e0 affidata la realizzazione del disegno- <strong>\u201cDisegna tu la storia\u201d<\/strong>&#8211; sul tema dello spreco alimentare; alle secondarie di primo grado spetter\u00e0, invece, la prova\u00a0 <strong>\u201cRealizza l\u2019intervista\u201d<\/strong>, mentre alle secondarie di secondo grado <strong>\u201cCrea lo spot\u201d.<\/strong> Ulteriori informazioni verranno rese nel corso della conferenza stampa. Il progetto ha, inoltre, previsto, ancora una volta, una comunicazione differente per gli amministratori locali e i cittadini attraverso incontri ed eventi. In particolare,<strong> la campagna coinvolger\u00e0 le istituzioni locali attraverso due incontri formativi e la cittadinanza attraverso quattro eventi culturali, ambientali ed enogastronomici.\u00a0<\/strong><\/p>\n<p>Hanno patrocinato l\u2019iniziativa: Regione Calabria, Anci Calabria, ArpaCal, Rimuseum-Museo per l\u2019Ambiente, Conai, Corepla, Coreve, Comieco, Ricrea, Cial, Cdc RAEE, Conou, Ecologia Oggi e Calabra Maceri. \u201cLa cultura della differenza fa la differenza &#8211; ha dichiarato nei mesi scorsi il presidente della Proivincia <strong>Francesco Iacucci<\/strong>&#8211; e la vasta iniziativa di sensibilizzazione ambientale deve continuare nel segno della sinergia tra istituzioni e territorio. <strong>Il futuro del pianeta \u00e8 dato dalle giovani generazioni e oggi pi\u00f9 che mai sono loro i testimoni della buona riuscita della manifestazione<\/strong>\u201d. Tutte le attivit\u00e0 svolte nel corso della campagna di sensibilizzazione alla raccolta differenziata e al riciclo saranno a brevi consultabili sul sito <span style=\"text-decoration: underline; color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/3926\" target=\"_blank\" rel=\"noopener\">www.perunaprovinciadifferente.it<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto, patrocinato dalla Provincia e promosso da ALESSCO torna a coinvolgere scuole, cittadini e amministratori dei 155 comuni del territorio<\/p>\n","protected":false},"author":22,"featured_media":89884,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-89883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89883"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89884"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}