{"id":8989,"date":"2012-12-05T07:23:13","date_gmt":"2012-12-05T06:23:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=8989"},"modified":"2023-01-17T13:42:09","modified_gmt":"2023-01-17T12:42:09","slug":"3922-nevica-in-calabria-spalaneve-in-azione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3922-nevica-in-calabria-spalaneve-in-azione\/","title":{"rendered":"Nevica in Calabria, spalaneve in azione"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; Mezzi spalaneve e spargisale dell&#8217;Anas in azione in Calabria sulla strada statale 107 Silana-Crotonese dove sta nevicando.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Analoga situazione, sempre sull&#8217;altipiano silano, sulla 108 bis di Lorica e sulla 177 che da Camigliatello conduce ad Acri. Non si segnalano altri problemi sulla viabilita&#8217; autostradale e ordinaria. Temporali e vento forte, nel resto della regione. A Catanzaro grandine e pioggia si alternano a sprazzi di sole. (Fonte ANSA)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Mezzi spalaneve e spargisale dell&#8217;Anas in azione in Calabria sulla strada statale 107 Silana-Crotonese dove sta nevicando.<\/p>\n","protected":false},"author":22,"featured_media":8990,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-8989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=8989"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/8989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/8990"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=8989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=8989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=8989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}