{"id":89918,"date":"2018-02-20T09:24:28","date_gmt":"2018-02-20T08:24:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/intervista-a-massimo-misiti-movimento-5-stelle-la-calabria-non-e-solo-mafia-audio\/"},"modified":"2023-01-16T18:49:56","modified_gmt":"2023-01-16T17:49:56","slug":"203068-intervista-a-massimo-misiti-movimento-5-stelle-la-calabria-non-e-solo-mafia-audio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/203068-intervista-a-massimo-misiti-movimento-5-stelle-la-calabria-non-e-solo-mafia-audio\/","title":{"rendered":"Intervista a Massimo Misiti &#8211; Movimento 5 Stelle: &#8220;La Calabria non \u00e8 solo mafia&#8221; (AUDIO)"},"content":{"rendered":"<h4>L&#8217;intervista al\u00a0dottore Massimo Misiti, \u00e8 candidato alla Camera, nel collegio uninominale di Castrovillari per il Movimento 5 Stelle.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Massimo Misiti, noto chirurgo ortopedico cosentino, \u00e8 anche membro del direttivo del Collegio Italiano Chirurghi e direttore scientifico della Societ\u00e0 Italiana di Artroscopia e svolge la sua professione a Rende, nel suo studio di Roges. Per oltre 13 anni ha lavorato, grazie ad Orthopaedics Onlus, associazione di volontariato, in Camerun, Tanzania, Eritrea e Sud America. Il dott. Misiti \u00e8 candidato nel collegio numero 1 Castrovillari per il Movimento Cinque Stelle. Essendo un noto medico ed avendo a cuore la sanit\u00e0, l&#8217;intervista per quicosenza inizia proprio da questo argomento sul quale il dott. Misiti risponde innanzitutto che &#8220;la principale aspettativa del M5S \u00e8 quella di <strong>dare qualit\u00e0 alle prestazioni<\/strong>. L&#8217;erogazione di una qualit\u00e0 di servizi, senza diversit\u00e0 tra una regione o un&#8217;altra. Quindi la possibilit\u00e0 di un accesso a qualunque tipo di servizio a seconda di quelle che sono le esigenze dei territori.<strong> Un piano dell&#8217;emergenza urgenza<\/strong>, la <strong>sistemazione della rete ospedaliera<\/strong> sicuramente pi\u00f9 confacente a quelle che sono adesso le esigenze dei pazienti&#8221;.<\/p>\n<h3>&#8220;La palese ingerenza della politica nel settore della Sanit\u00e0&#8221;<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203079 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/misiti-massimo-700x400.jpg\" alt=\"misiti-massimo-700x400\" width=\"352\" height=\"297\" title=\"\">&#8220;E&#8217; necessario \u00e8 fondamentale che si possa avere la stessa dignit\u00e0 e la stessa possibilit\u00e0 di cure in tutto il territorio nazionale. E questo fino ad oggi in Calabria, non c&#8217;\u00e8 stato dato, anzi;<strong> la Calabria \u00e8 fonte di guadagno per le altre regioni.<\/strong> Abbiamo 300 milioni di euro all&#8217;anno, che vengono dati\u00a0ad altre regioni e nelle altre regioni vengono messe in bilancio preventivo. Spesso siamo noi, cittadini di questa regione, che propendiamo ad andare verso l&#8217;esterno, verso altre regioni, perch\u00e8 non sappiamo a volte, le possibilit\u00e0 che abbiamo di cure nella nostra regione. Perch\u00e8 ci\u00f2 sia fruibile da parte di tutti i cittadini<strong> \u00e8 opportuno che i cittadini sappiano che hanno degli ospedali che hanno la possibilit\u00e0 di curare,<\/strong> che erogano prestazioni degne di qualit\u00e0 e questo perch\u00e8 ci sia, \u00e8 necessario fare una guerra e una battaglia alla politica che fino ad adesso ha rubato nel campo della sanit\u00e0. Questa ingerenza \u00e8 manifesta, \u00e8 di pubblico dominio. Non \u00e8 una mia denuncia personale o del Movimento 5 Stelle.<strong> E&#8217; palese, il cittadino nota come l&#8217;ingerenza della politica crei un&#8217;usurpazione di fondi e possibilit\u00e0 di cure.<\/strong> Se io invece di pagare dei servizi, facessi dei concorsi e potessi potenziare determinate strutture sicuramente quei soldi risparmiati sarebbero fonte di acquisizione di nuovi materiale e tecnologie fruibili per il cittadino calabrese&#8221;.<\/p>\n<h3>La migrazione, dalla sanit\u00e0 al lavoro: &#8220;dalla protesta alla proposta&#8221;<\/h3>\n<p>&#8220;I cittadini migrano. Questo non \u00e8 legato solo al campo della sanit\u00e0. E&#8217; sufficiente leggere il censimento del 2010 quando eravamo 2 milioni e 200 mila abitanti e oggi, nel 2018 siamo un milione e 890 mila. A parte le morti che sono naturali, questo dato fa capire che c&#8217;\u00e8 un alto tasso di migrazione. E non \u00e8 legata<strong> solo all&#8217;esigenza di lavoro, ma soprattutto di prospettive<\/strong>. I giovani spesso si erudiscono, diventano delle menti che sono ambite dalle altre regioni, ma nel proprio territorio non riescono a crescere e a mettere in pratica il risultato dei loro studi. <strong>Il lavoro \u00e8 un problema<\/strong>: per il ragazzo che ha finito il liceo e ha un diploma che permetterebbe di lavorare; \u00e8 un problema per chi ha una laurea, una specializzazione, ma fondamentalmente anche per chi aveva un lavoro e si \u00e8 trovato all&#8217;improvviso senza la possibilit\u00e0 di lavorare. <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-203076 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/Massimo-Misiti-candidato-5-stelle.jpg\" alt=\"Massimo Misiti candidato 5 stelle\" width=\"454\" height=\"363\" title=\"\"><strong>C&#8217;\u00e8 un comparto di &#8216;esodati&#8217; che non hanno n\u00e8 la pensione e non hanno il lavoro.<\/strong> Sono tutte problematiche che il Movimento 5 Stelle non sta affrontando da oggi, ma da anni. Si \u00e8 passati dal momento della protesta al momento della proposta. Sta crescendo ed \u00e8 sempre pi\u00f9 vicino alla gente e a chi ha bisogno. E&#8217; il momento della proposta e dei dati di fatto e questa tornata elettorale \u00e8 l&#8217;unico momento che c&#8217;\u00e8. Il dissenso non va cavalcato ma va, curato, vanno capite le esigenze e chi ha governato fino ad adesso non ha dimostrato di comprendere quali sono le esigenze dei territori&#8221;.<\/p>\n<p>&#8220;E&#8217; stato stilato un programma sulla piattaforma Rousseau, che \u00e8 fruibile da tutti, dove ci sono <strong>venti punti<\/strong>; si parla di <strong>famiglia<\/strong>, si parla di <strong>reddito minimo<\/strong>, di <strong>pensione minima<\/strong> che \u00e8 fruibile da chi ha bisogno di aiuto in un momento di difficolt\u00e0. Il <strong>piano famiglia<\/strong> che prevede, ad esempio, degli asili aperti a tutti e non a pagamento. La possibilit\u00e0 di avere la valorizzazione del bambino che viene curato, esigenze e sistema famiglia che \u00e8 stato molto attenzionato dal Movimento 5 Stelle&#8221;.<\/p>\n<h3><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA INTEGRALE al candidato Massimo Misiti\u00a0<\/span><\/h3>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/misiti-completa.mp3&#8243;]<\/p>\n<h3><\/h3>\n<h3>Immigrazione: &#8220;basta con il business e con il mercato delle persone&#8221;<\/h3>\n<p>&#8220;Anche questo \u00e8 nel programma dei 5 Stelle &#8211; spiega il candidato Misiti &#8211; Si parla di una cooperazione internazionale che \u00e8 finalizzata alla stipula di trattati per i rimpatri. Si vorrebbe avere la possibilit\u00e0 di assumere 10mila nuove forze dell&#8217;ordine e in questa maniera c&#8217;\u00e8 un controllo dell&#8217;ordine e altrettante diecimila per le commissioni territoriali che hanno l&#8217;obbligo dovere di valutare in un solo mese se il migrante ha diritto o no alla possibilit\u00e0 di stare in Italia. E&#8217; importante far capire che il Movimento 5 Stelle denuncia<strong> il commercio che c&#8217;\u00e8 nell&#8217;ambito dell&#8217;immigrazione<\/strong>. Non \u00e8 possibile avere un business che \u00e8 basato sulla necessit\u00e0 di queste persone di passare e transitare dall&#8217;Italia. Sappiamo tutti quanti quello che viene creato in queste case d&#8217;accoglienza dove avrebbero diritto a 38 euro al giorno, vero, discutibile o meno, ma \u00e8 altrettanto vero che ci sono business gestiti in maniera non corretta; furti che il cittadino italiano conosce e vorrebbe sicuramente denunciare. Il M5S, da questa possibilit\u00e0 di denunciare, di far sospendere questo mercato delle persone&#8221;.<\/p>\n<h3>La sicurezza: &#8220;la possibilit\u00e0 di assumere diecimila nuove forze dell&#8217;ordine&#8221;<\/h3>\n<p>Tanti nostri giovani cercano di entrare nelle forze dell&#8217;ordine perch\u00e8 ambiscono ad uno stipendio ed il Movimento ha proposto 10 mila assunzioni nelle forze dell&#8217;ordine; questo perch\u00e8 si avverte l&#8217;esigenza di essere protetti. E&#8217; necessario solo dare alle forze dell&#8217;ordine di tutelare i territori. Non \u00e8 possibile che non abbiano mezzi a sufficenza per controllare le citt\u00e0 durante la notte. A volte vivono la difficolt\u00e0 anche di pagare la benzina alle auto che adoperano. E&#8217; necessario dar loro la possibilit\u00e0 di sorvegliare la nostra sicurezza.<\/p>\n<h4>Il primo passo al Parlamento per la Calabria? &#8220;Far capire che i calabresi non sono mafia&#8221;<\/h4>\n<p>&#8220;Quello che vorrei riuscire a far capire \u00e8 che i calabresi non sono delinquenti, e vorrei cominciare a togliere questa logica che hanno in molti, ovvero che i calabresi non sono lavoratori, che sono degli ignoranti, che sono mafia, che sono &#8216;ndrangheta&#8230; Il calabrese ha il diritto dovere di far capire (e io lo farei) che la Calabria \u00e8 una terra meravigliosa, fatta di gente che vuole lavorare, che ha solo bisogno di essere valorizzata per quella che ha, senza essere assolutamente accomunata a quelle che sono le mafie. Chiaramente tutto ci\u00f2 si pu\u00f2 fare solo in un modo, dimostrandolo fattivamente e per fare ci\u00f2, c&#8217;\u00e8 bisogno di entrare nelle Istituzioni, e far capire che la Calabria non \u00e8 solo mafia&#8230; non \u00e8 mafia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intervista al\u00a0dottore Massimo Misiti, \u00e8 candidato alla Camera, nel collegio uninominale di Castrovillari per il Movimento 5 Stelle.<\/p>\n","protected":false},"author":22,"featured_media":89919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,369],"tags":[],"class_list":["post-89918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-speciale-elezioni-2018"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=89918"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/89918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/89919"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=89918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=89918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=89918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}