{"id":90133,"date":"2018-02-23T14:44:33","date_gmt":"2018-02-23T13:44:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cinque-sensi-riprende-la-marcia-in-un-percorso-darte\/"},"modified":"2023-01-16T18:50:11","modified_gmt":"2023-01-16T17:50:11","slug":"203805-cinque-sensi-riprende-la-marcia-in-un-percorso-darte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/203805-cinque-sensi-riprende-la-marcia-in-un-percorso-darte\/","title":{"rendered":"&#8220;Cinque sensi&#8221; riprende la marcia in un percorso d&#8217;arte"},"content":{"rendered":"<h4>Il nuovo itinerario di trekking urbano, attraverso i luoghi pi\u00f9 suggestivi della Cosenza antica, si conclude con un concerto di piano e flauto al Rendano<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Si rinnova domani, sabato 24 febbraio, l\u2019appuntamento con \u201cCinque sensi di marcia\u201d, l\u2019iniziativa, promossa dall\u2019Assessorato al turismo e marketing territoriale di Palazzo dei Bruzi, guidato da Rosaria Succurro ed organizzata in collaborazione con l&#8217;Associazione Apt \u201c Citt\u00e0 di Cosenza\u201d.<br \/>\nIl nuovo itinerario di trekking urbano, attraverso i luoghi pi\u00f9 suggestivi della Cosenza antica, si articoler\u00e0 in un vero e proprio percorso d\u2019arte, da Piazza Tommaso Campanella a Piazza XV Marzo, conducendo i partecipanti alla riscoperta del <strong>centro storico<\/strong>, con le sue <strong>chiese, i suoi vicoli, le piazze, i palazzi e i teatri<\/strong>.<br \/>\n\u201cRiaccendiamo i riflettori sulla citt\u00e0 storica \u2013 sottolinea l&#8217;Assessore al turismo Rosaria Succurro &#8211; \u00a0per rimetterla al centro dell\u2019attenzione anzitutto dei cosentini, ma anche di tutti gli altri visitatori. La nostra Amministrazione ha puntato e continua a puntare molto sulla bellezza dei luoghi e dei monumenti della citt\u00e0 e sta investendo tanto in arte e cultura. Occorrer\u00e0 <strong>far leva sempre di pi\u00f9 sul turismo culturale ribadendo la presenza, nella nostra citt\u00e0, di forti attrattori, da quelli pi\u00f9 visibili a quelli pi\u00f9 nascosti, in grado di aumentarne la destination reputation che, come \u00e8 stato rilevato anche alla recente Borsa del Turismo di Milano, \u00e8 in continua crescita<\/strong>. Ecco perch\u00e9 \u201cCinque sensi di marcia\u201d si conferma occasione utile a ribadire la vocazione e la credibilit\u00e0 turistica della nostra citt\u00e0\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-203809 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/cinque-sensi2-440x250.jpg\" alt=\"cinque sensi2\" width=\"440\" height=\"250\" title=\"\">Il raduno del trekking urbano \u00e8 previsto per le <strong>ore 16,00 in Piazza Tommaso Campanella<\/strong>. La visita avr\u00e0 inizio dalla <strong>Chiesa di San Domenico<\/strong>, rivestita di forme barocche nel 1700, ma ancora ricca di strutture gotiche originali e di cappelle rinascimentali. Si proseguir\u00e0 poi con una sosta sul <strong>ponte Mario Martire<\/strong> per ribadire l\u2019importanza che i fiumi, nel corso dei secoli, hanno avuto per Cosenza. Attraverso <strong>Piazza dei Valdesi prima e Corso Telesio dopo<\/strong>, si giunger\u00e0 alla <strong>Casa delle Culture<\/strong>, sede del vecchio municipio di Cosenza, dove \u00e8 prevista una visita alle sue esposizioni. La passeggiata nel centro storico continuer\u00e0 \u00a0lungo l\u2019antica <strong>via dei Mercanti e degli Orefici e tra i vicoli, fino al Teatro Real Ferdinando, conosciuto come il vecchio Liceo Classico \u201cTelesio\u201d<\/strong>, che sovrasta la facciata rinascimentale della <strong>Chiesa di S. Chiara<\/strong>.<\/p>\n<p>Subito dopo, i partecipanti si ritroveranno in <strong>piazza XV Marzo<\/strong> per richiamare alla memoria i principali momenti storici e culturali legati a questo luogo ricco di fascino. Ultima tappa dell\u2019itinerario, il <strong>Teatro \u201cRendano\u201d<\/strong> dove, a conclusione della visita, la pianista Alessia Petrone e il flautista Luigi Marchese, giovani musicisti allievi del Conservatorio di Musica \u201cS. Giacomantonio \u201c di Cosenza, eseguiranno <strong>musiche di Francis Poulenc nella Sala \u201cQuintieri\u201d<\/strong>.<br \/>\nLe prenotazioni per partecipare al percorso si raccolgono al punto informativo di Piazza XI Settembre o presso l&#8217;Ufficio Turismo di San Domenico,oppure telefonando al numero 328.1754422 o inviando una mail all&#8217;indirizzo\u00a0<a href=\"mailto:info@cosenzaturismo.it\">info@cosenzaturismo.it<\/a>\u00a0.<br \/>\nLa\u00a0partecipazione\u00a0all&#8217;iniziativa\u00a0\u00e8\u00a0completamente\u00a0gratuita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nuovo itinerario di trekking urbano, attraverso i luoghi pi\u00f9 suggestivi della Cosenza antica, si conclude con un concerto di piano e flauto al Rendano<\/p>\n","protected":false},"author":37,"featured_media":90134,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-90133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90133"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90134"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}