{"id":90420,"date":"2018-03-04T18:58:45","date_gmt":"2018-03-04T17:58:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/elezioni-affluenza-ore-19-00-calabria-al-4955-a-rende-lunghe-code-in-due-sezioni\/"},"modified":"2023-01-16T18:50:29","modified_gmt":"2023-01-16T17:50:29","slug":"205267-elezioni-affluenza-ore-19-00-calabria-al-4955-a-rende-lunghe-code-in-due-sezioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/205267-elezioni-affluenza-ore-19-00-calabria-al-4955-a-rende-lunghe-code-in-due-sezioni\/","title":{"rendered":"Elezioni, affluenza ore 19.00: Calabria al 49,55%. A Rende lunghe code in due sezioni"},"content":{"rendered":"<h4><span style=\"color: #000000;\">I dati dell&#8217;affluenza alle ore 19,00 portano la soglia dei votanti poco sotto il 50% . Peggio di noi solo la Sicilia con il 47,06%. Operazioni a rilento e code in due sezioni di Rende\u00a0<\/span><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #000000;\">COSENZA &#8211;\u00a0 Il Viminale ha appena comunicato i dati definitivi relativi all&#8217;<strong>affluenza delle ore 19.00<\/strong>. La Calabria si conferma <strong>penultima regione italiana<\/strong> per numero di persone che su sono recati alle urne. I nuovi dati confermano che ad andare a votare nella nostra regione \u00e8 stato il 49,55% degli aventi diritto.\u00a0<strong>La provincia di Cosenza \u00e8 quella\u00a0 dove si si \u00e8 votato di pi\u00f9 con un dato poco sopra il 52%<\/strong>. Segue Catanzaro con il 51,06%<\/span><span style=\"color: #000000;\">. Reggio e Crotone le peggiori con il 45,95% e il 46,36%. A Cosenza citt\u00e0 ha votato il\u00a054,42%, a Rende il\u00a053,31%, a Montalto Uffugo il\u00a054,00%, a Castrolibero il 63,62%.\u00a0<\/span><span style=\"color: #000000;\">In Italia il dato totale sull&#8217;affluenza alle ore 19.00 \u00e8 stato del\u00a0<strong>58,51%<\/strong>. L&#8217;Umbria al 64,86% \u00e8 la regione con il pi\u00f9 alto dato.<\/span><\/p>\n<div class=\"row\">\n<div class=\"col-md-12 col-sm-12\">\n<div id=\"headEnti\">\n<h3><span style=\"color: #000000;\">CALABRIA affluenza ore 19.00\u00a0<span style=\"color: #0000ff;\">49,55%<\/span><\/span><\/h3>\n<\/div>\n<\/div>\n<div class=\"col-md-12 col-sm-12\">\n<table width=\"409\">\n<tbody>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\"><strong>Citt\u00e0<\/strong><\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><strong><span style=\"color: #000000;\">Ore 12<\/span><\/strong><\/td>\n<td width=\"98\"><strong><span style=\"color: #000000;\">Ore 19<\/span><\/strong><\/td>\n<td width=\"64\"><strong><span style=\"color: #000000;\">Ore 23<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\">CATANZARO<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">16,02%<\/span><\/td>\n<td width=\"98\"><span style=\"color: #000000;\">51,06%<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\">COSENZA<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">16,42%<\/span><\/td>\n<td width=\"98\"><span style=\"color: #000000;\">52,12%<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\">CROTONE<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">14,08%<\/span><\/td>\n<td width=\"98\"><span style=\"color: #000000;\">46,36%<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\">REGGIO CALABRIA<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">13,29%<\/span><\/td>\n<td width=\"98\"><span style=\"color: #000000;\">45,95%<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">&#8211;<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"119\"><span style=\"color: #000000;\">VIBO VALENTIA<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<td width=\"64\"><span style=\"color: #000000;\">14,44%<\/span><\/td>\n<td width=\"98\"><span style=\"color: #000000;\">50,03%<\/span><\/td>\n<td><span style=\"color: #000000;\">\u00a0<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div id=\"restfulData\" class=\"clear-both\"><\/div>\n<h4 class=\"chapter-title\"><span style=\"color: #000000;\">Nuovo tagliando antifrode:\u00a0voto a rilento in alcuni seggi di Rende<\/span><\/h4>\n<p><span style=\"color: #000000;\">Una delle novit\u00e0 introdotte con la\u00a0nuova legge elettorale \u00e8 il cosiddetto <strong>\u201ctagliando antifrode\u201d<\/strong>.\u00a0Ai cittadini\u00a0che da questa mattina si stanno recando alle urne, <strong>viene fornita una sola scheda alla volta<\/strong>. Le schede di Camera e Senato sono\u00a0dotate di un \u201ctagliando\u201d\u00a0sul quale \u00e8 riportato con un c<strong>odice alfanumerico, identico a quello identificativo della scheda stessa<\/strong>. Il presidente del seggio ne prende nota prima di consegnarla all&#8217;elettore\u00a0e poi, prima che il foglio finisca nell&#8217;urna per mano dello stesso presidente e non pi\u00f9 dagli elettori, <strong>rileggere il codice assicurandosi che coincida<\/strong>. Insomma un&#8217;operazione sicura contro i furbetti ma che sta provocando inevitabili rallentamenti nelle operazioni di voto un po&#8217; ovunque. Problemi, in particolare, vengono segnalati in due sezioni di Rende dove sono segnalate lunghe code.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-204271\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/02\/schede-elezioni-2018.jpg\" alt=\"schede-elezioni-2018\" width=\"561\" height=\"420\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dati dell&#8217;affluenza alle ore 19,00 portano la soglia dei votanti poco sotto il 50% . Peggio di noi solo la Sicilia con il 47,06%. Operazioni a rilento e code in due sezioni di Rende\u00a0<\/p>\n","protected":false},"author":22,"featured_media":90421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571,369],"tags":[],"class_list":["post-90420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza","category-speciale-elezioni-2018"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90420"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90421"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}