{"id":90476,"date":"2018-03-06T15:55:32","date_gmt":"2018-03-06T14:55:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coppa-italia-cosenza-perde-la-testa-anche-la-gara-la-viterbese-passa-3-1\/"},"modified":"2023-01-16T18:50:33","modified_gmt":"2023-01-16T17:50:33","slug":"205630-coppa-italia-cosenza-perde-la-testa-anche-la-gara-la-viterbese-passa-3-1","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/205630-coppa-italia-cosenza-perde-la-testa-anche-la-gara-la-viterbese-passa-3-1\/","title":{"rendered":"Coppa Italia, il Cosenza perde la testa e anche la gara. La Viterbese passa 3 a 1"},"content":{"rendered":"<h4><span style=\"color: #000000;\">Gara giocata su un terreno ai limiti della praticabilit\u00e0 che premia i laziali\u00a0bravi e fortunati a sfruttare due clamorosi errori del portiere Zommers e la doppia superiorit\u00e0 numerica. Nel primo tempo vantaggio al 5&#8242; su autorete di Pascali, raddoppio di Jefferson\u00a0e rete di Bruccini. Nel finale De Sousa su rigore\u00a0sigla il 3 a 1 finale. Pessimo l&#8217;arbitraggio del signor\u00a0<strong>Proietti<\/strong><\/span><br \/>\n<!--more--><\/h4>\n<p>.<\/p>\n<p><span style=\"color: #000000;\">VITERBO &#8211; Va alla Viterbese la <strong>gara di andata della semifinale di<\/strong>\u00a0<strong>Coppa Italia Serie C. <\/strong>I laziali\u00a0battono un\u00a0Cosenza nervoso e ingenuo con un 3 a 1 che lascia comunque qualche speranza ai rossoblu per la gara di ritorno. Cosenza penalizzato dalla <strong>doppia espulsione<\/strong> di Mungo nel primo tempo e di Loviso nella ripresa, ma sopratutto da <strong>due clamorose topiche del portiere Zommers<\/strong> e dall&#8217;<strong>ingenuo fallo da rigore di Dermaku<\/strong> in zona cesarini, quando la gara ormai si avvivava a conclusione sul risultato di 2 a 1<strong>. <\/strong>Pi\u00f9 che una partita di calcio, quella andata in scena allo stadio Rocchi \u00e8 stata una vera e propria battaglia. <\/span><\/p>\n<p><span style=\"color: #000000;\">Complice un\u00a0<strong>terreno di gioco impossibile<\/strong> ai limiti della praticabilit\u00e0 per la pioggia, i laziali passano in vantaggio al 5&#8242; con un clamoroso liscio del portiere Zommers su retropassaggio su Pascali. <strong>Mungo manda a quel paese l&#8217;arbitro e si becca il rosso<\/strong> diretto. La Viterbese ne approfitta e trova il raddoppio con un <strong>colpo di testa del brasiliano Jefferson<\/strong> ma anche in questo caso c&#8217;\u00e8 lo zampino del portiere lettone che dopo essersi superato su Calderini, giudica fuori il pallone che invece finisce in rete. Il Cosenza sul finire del primo tempo riesce prima ad accorciare le distanze con un <strong>sinistro chirurgico di Bruccini<\/strong>, poi sfiora anche il pari con Calamai che manda fuori a porta vuota. Nella ripresa si scatena il diluvio e il terreno del Rocchi diventa un pantano<strong>. Loviso entra duro su San\u00e8 e finisce anche lui negli spogliatoi per il rosso diretto ritenuto eccessivo<\/strong>. C&#8217;\u00e8 tutto il secondo tempo da giocare ma i rossoblu, complice anche il terreno intriso d&#8217;acqua, non corrono rischi. Ma a complicare tutto arriva l&#8217;<strong>ingenuit\u00e0 di Dermaku che stende in area Bismak<\/strong>. <strong>Dal dischetto De Sousa fa tris<\/strong> e indirizza la finale verso Viterbo complice anche il <strong>pessimo signor<\/strong> <strong>Proietti<\/strong>.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/507\" rel=\"attachment wp-att-49952\"><br \/>\n<\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-205628 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/Viterbese-Castrense.png\" width=\"123\" height=\"188\" alt=\"\" title=\"\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/quicosenza.it\/news\/859\" rel=\"attachment wp-att-49958\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38351 alignnone\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/logo-Cosenza Calcio.png\" alt=\"logo-Cosenza Calcio\" width=\"143\" height=\"186\" title=\"\"><\/a><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 18pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Viterbese\u00a0 \u00a0 \u00a0&#8211;\u00a0 \u00a0<\/span><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0Cosenza\u00a0<\/span><\/span><\/span><\/strong><\/span><span style=\"color: #ff0000; font-size: 20pt; text-decoration: blink;\"><a target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000; text-decoration: blink;\">3-1<\/span><\/a><\/span><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 14pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\"><script type=\"text\/javascript\">\/\/ \nfunction blink_one() { document.getElementById('blink').style.visibility='visible'; setTimeout('blink_two()',1000); } function blink_two() { document.getElementById('blink').style.visibility='hidden'; setTimeout('blink_one()',1000); } blink_one();\n\/\/ <\/script><\/span><\/span><\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Marcatori<\/strong>: 5&#8242; Pascali (aut.), 33, Jefferson, 40 Bruccini, 90&#8242; De sousa (r)<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_205904\" style=\"width: 601px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-205904\" class=\"wp-image-205904\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/Viterbese-Cosenza1.jpg\" alt=\"Viterbese Cosenza1\" width=\"591\" height=\"343\" title=\"\"><p id=\"caption-attachment-205904\" class=\"wp-caption-text\"><em>Foto Newtuscia<\/em><\/p><\/div>\n<h4><span style=\"color: #000000;\">Primo tempo,\u00a0il liscio di Zommers\u00a0e il rosso a Mungo<\/span><\/h4>\n<p><span style=\"color: #000000;\">La prima\u00a0conclusione della gara \u00e8 del Cosenza. Azione sulla sinistra di\u00a0D&#8217;Orazio e pallone, che dopo un liscio di Tutino, finisce sui pedi di\u00a0<strong>Baclet che gira subito verso la porta di Pini <\/strong>che<strong>\u00a0<\/strong>si allunga e manda in angolo. <strong>Al 6&#8242;\u00a0improvviso arriva il vantaggio della Viterbese<\/strong> con un goal da Gialappas Band.\u00a0Pascali serve il <strong>pallone indietro al portiere Zommers che, complice anche un rimbalzo assassino, liscia clamorosamente la sfera<\/strong> che lemme lemme finisce in porta tra la disperazione del portiere del Cosenza e l&#8217;incredulit\u00e0 dei tifosi di casa che quasi non riescono a credere del gentile omaggio concesso. Passano poco pi\u00f9 di 5 minuti e<strong> il Cosenza rimane in 10<\/strong>. <strong>Mungo protesta <\/strong>per un fallo non fischiato, pronunciando forse qualche parola di troppo all&#8217;indirizzo del <strong>signor\u00a0Proietti di Terni<\/strong> che per tutta risposta gli sventola il rosso diretto. Nonostante l&#8217;inferiorit\u00e0 numerica <strong>Tutino ha subito l&#8217;occasione del pareggio<\/strong>, ma l&#8217;attaccante napoletano, imbeccato alla perfezione da\u00a0Baclet, si fa ipnotizzare da Pini che si salva. La partita \u00e8 nervosissima e al 20&#8242; Dermaku\u00a0viene a contatti con Rinaldi che stramazza a terra. Per la Viterbese si tratta di un pugno non visto dalla terna arbitrale. Si accende un furioso parapiglia con le panchina in campo.\u00a0A farne le spese\u00a0\u00e8\u00a0solo Corsi\u00a0che viene ammonto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_205905\" style=\"width: 599px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-205905\" class=\"wp-image-205905\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/Viterbese-Cosenza2.jpg\" alt=\"Viterbese Cosenza2\" width=\"589\" height=\"369\" title=\"\"><p id=\"caption-attachment-205905\" class=\"wp-caption-text\"><em>Foto Newtuscia<\/em><\/p><\/div>\n<h4><span style=\"color: #000000;\">Raddoppio di Jefferson, Bruccini accorcia con un gran sinistro<\/span><\/h4>\n<p><span style=\"color: #000000;\"><strong>Al 25&#8242; Viterbese Calderini<\/strong>\u00a0in mezza rovesciata spara sotto la traversa\u00a0un pallone messo in area\u00a0da Cenciarelli, Zommers questa volta \u00e8 miracoloso e vola a deviare. <strong>Alla mezzora\u00a0ancora una conclusione velenosa dell&#8217;ex rossoblu<\/strong>\u00a0che da ottima posizione manda fuori. <strong>Al 33&#8242;\u00a0la Viterbese trova il raddoppio con un colpo di testa di Jefferson<\/strong> su cross di\u00a0Celiento. Il brasiliano\u00a0in torsione manda il pallone a morire nell&#8217;angolo ma anche questa volta c&#8217;\u00e8 la complicit\u00e0<strong>\u00a0del portiere Zommers che valuta fuori<\/strong> il pallone che invece si insacca in rete.\u00a0Gara chiusa? Neanche per sogno, visto che al 40 i rossoblu\u00a0la riaprono con<strong> una magia di\u00a0Bruccini <\/strong>che con un preciso sinistro infila il pallone nel sette. Passano due minuti e<strong> Calamai ha sui piedi il pallone del pareggio<\/strong>, ma il centrocampista rossoblu manda fuori a porta vuota un pallone d&#8217;oro servitogli da Baclet. Il primo tempo si chiude con una parata di Zommers su punizione battuta da Sini.<\/span><\/p>\n<h4><span style=\"color: #000000;\">Ripresa: Rosso a Loviso e tris della viterbese su rigore<\/span><\/h4>\n<p><span style=\"color: #000000;\">La ripresa si apre sotto un vero e proprio diluvio con il terreno del Rocchi gi\u00e0\u00a0in condizioni pessime, che si trasforma in una risaia. Il Cosenza prova ad arrivare al pareggio anche rischiando qualcosina\u00a0in difesa. Al 51&#8242; sventola di Calamai bloccata a terra da Pini. Al 56 la pioggia diventa gelata perch\u00e9 <strong>il Cosenza rimane\u00a0in 9 uomini per il rosso diretto a Loviso<\/strong> punito per un duro intervento sul neo entrato San\u00e8.<strong> Zommers con un prodigioso intervento su Bismark tiene a galla i rossoblu<\/strong> che nonostante la doppia inferiorit\u00e0 numerica si riorganizzano riuscendo a tenere lontani i gialloblu dalla propria area di rigore, complice anche il terreno zuppo d&#8217;acqua che rende impossibile qualsiasi manovra di gioco. Ma a dare una mano ai padroni di casa ci pensa una<strong> sciocchezza di Dermaku a poco pi\u00f9 di due minuti dalla fine<\/strong>. Il difensore del Cosenza prima liscia\u00a0un pallone in area, poi combina la frittata aggrappandosi alla maglia di Bismark. Inevitabile <strong>il calcio di rigore che De Sousa trasforma<\/strong> spiazzando Zommers. La gara finisce qui, con il Cosenza chiamato all&#8217;impresa tra una settimana.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<div id=\"attachment_205907\" style=\"width: 598px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-205907\" class=\"wp-image-205907\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/Viterbese-Cosenza4.jpg\" alt=\"Viterbese Cosenza4\" width=\"588\" height=\"333\" title=\"\"><p id=\"caption-attachment-205907\" class=\"wp-caption-text\"><em>Foto Newtuscia<\/em><\/p><\/div>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014-<\/p>\n<p><span style=\"color: #000000;\"><strong>VITERBESE CASTRENSE\u00a0(4-3-3):<\/strong>\u00a0 Pini, Cenciarelli, Celiento, Rinaldi, Vandeputte, Sini, Baldassin, Jefferson (45&#8242; Bismark), Calderini (62&#8242; De Souza), De Vito (48 San\u00e8), Benedetti<\/span><br \/>\n<span style=\"color: #000000;\"> <strong>Panchina<\/strong>:\u00a0Iannarilli, Micheli, Peverelli, Ngissah, De Souza, Mendez, Mbaye, Zenuni, San\u00e8, Di Paolantonio, Antanassov, Mosti, Bismark<\/span><br \/>\n<span style=\"color: #000000;\"> <strong>Allenatore<\/strong>: Stefano Sottili\u00a0Sottil<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>COSENZA CALCIO\u00a0(3-5-2):\u00a0 <\/strong>Zommers, Corsi, Mungo, Boniotti (29&#8242; Calamai), Baclet (64&#8242; Perez), Bruccini, Tutino (59&#8242; Tutino), Loviso, Pascali, D&#8217;Orazio, Dermaku<\/span><br \/>\n<span style=\"color: #000000;\"> <strong>Panchina:<\/strong> Saracco, Idda, Palmiero, Ramos, Perez, Pasqualoni, Okerke, Calami<\/span><br \/>\n<span style=\"color: #000000;\"> <strong>Allenatore:\u00a0<\/strong>Piero Braglia<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Arbitro<\/strong>: Signor\u00a0Matteo Proietti di Terni<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Assistenti:\u00a0<\/strong>Signor\u00a0Giuseppe Perotti di Campobasso e signor Michele Pizzi di Termoli<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Ammoniti<\/strong>: Corsi (C), Pascali (C), Palmiero (C), Bismark (V)<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Espulsi<\/strong>: Mungo (C),\u00a0Loviso (C)<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Angoli<\/strong>: 1-2<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Note<\/strong>: Giornata\u00a0grigia con la pioggia caduta in modo incessante per tutta la mattina e in alcuni tratti della gara. Terreno del Rocchi in\u00a0condizioni disastrose. Presenti poco pi\u00f9 di 500 spettatori con una cinquantina di tifosi del Cosenza<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gara giocata su un terreno ai limiti della praticabilit\u00e0 che premia i laziali\u00a0bravi e fortunati a sfruttare due clamorosi errori del portiere Zommers e la doppia superiorit\u00e0 numerica. Nel primo tempo vantaggio al 5&#8242; su autorete di Pascali, raddoppio di Jefferson\u00a0e rete di Bruccini. Nel finale De Sousa su rigore\u00a0sigla il 3 a 1 finale. [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":90477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-90476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90476"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90477"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}