{"id":90608,"date":"2018-03-09T15:00:08","date_gmt":"2018-03-09T14:00:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coppa-italia-mercoledi-prezzi-simbolici-allo-stadio-per-spingere-i-lupi-alla-remuntada\/"},"modified":"2023-01-16T18:50:42","modified_gmt":"2023-01-16T17:50:42","slug":"206187-coppa-italia-mercoledi-prezzi-simbolici-allo-stadio-per-spingere-i-lupi-alla-remuntada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/206187-coppa-italia-mercoledi-prezzi-simbolici-allo-stadio-per-spingere-i-lupi-alla-remuntada\/","title":{"rendered":"Coppa Italia, mercoled\u00ec prezzi simbolici allo stadio per spingere i lupi alla &#8220;remuntada&#8221;"},"content":{"rendered":"<h4>La societ\u00e0 chiama a raccolta i tifosi. Per la semifinale di ritorno di Coppa Italia contro la Viterbese, in programma mercoled\u00ec allo stadio Marulla, tagliandi in vendita a prezzi simbolici<\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Il\u00a0Cosenza ha bisogno del calore dei suoi tifosi perch\u00e9 <strong>l&#8217;impresa \u00e8 difficile ma non impossibile<\/strong>. Stiamo parlando della <strong>semifinale di ritorno di Coppa Italia di Serie C<\/strong> contro la <strong>Viterbese<\/strong>, in programma <strong>mercoled\u00ec 14 marzo alle ore 14.30 allo stadio &#8220;San Vito-Marulla&#8221;<\/strong>. I rossoblu, sconfitti 3 a 1 all&#8217;andata ma penalizzati oltremodo dal pessimo arbitraggio del <strong>signor\u00a0Proietti di Terni<\/strong>, proveranno a ribaltare il risultato ed\u00a0accedere alla\u00a0finale che si disputer\u00e0 contro l&#8217;Alessandria che di fatto \u00e8 la prima finalista. Se vorr\u00e0 passare il turno il Cosenza dovr\u00e0 segnare due reti senza subirne. Per questo la societ\u00e0\u00a0ha voluto chiamare a raccolta i tifosi e deciso di <strong>applicare ai tagliandi di ingresso, un prezzo davvero simbolico<\/strong>. La Curva Sud &#8220;Bergamini&#8221;, ad esempio, <strong>coster\u00e0 solo 1 euro<\/strong>, la <strong>Tribuna A 2 euro<\/strong>.<\/p>\n<p><strong>Questo il comunicato della societ\u00e0 rossoblu<\/strong>:\u00a0<em>La Societ\u00e0 Cosenza Calcio comunica che \u00e8 attiva la prevendita per la gara Cosenza \u2013 Viterbese Castrense, valida per la gara di ritorno della semifinale di Coppa Italia di\u00a0 Serie C 2017\/2018, in programma allo Stadio San Vito \u2013 \u201cGigi Marulla\u201d alle ore 14:30 di mercoled\u00ec 14 marzo 2018.\u00a0<\/em><strong><em>Per la gara in questione la Societ\u00e0 ha deciso di applicare dei prezzi simbolici nei settori \u201cpopolari\u201d e una scontistica del 50% nei restanti, per favorire un maggiore afflusso di pubblico<\/em>. &#8220;<\/strong><\/p>\n<p><strong>PREZZI BIGLIETTI:<\/strong><\/p>\n<p>CURVA SUD EURO 1,00 \u2013 (NO RIDOTTO)<br \/>\nTRIBUNA A EURO 2,00 \u2013 (NO RIDOTTO)<br \/>\nTRIBUNA ROSSA: EURO 12,00 \u2013 (NO RIDOTTO)<br \/>\nTRIBUNA BLU CENTRALE: EURO 15,00 \u2013 (NO RIDOTTO)<br \/>\nBIGLIETTO \u201cLUPACCHIOTTO\u201d UNDER 14 (TUTTI I SETTORI): EURO 1,00<\/p>\n<p>Si fa presente che, in considerazione dei lavori di adeguamento e ristrutturazione in corso all\u2019interno dell\u2019impianto, n<strong>on \u00e8 attiva la vendita dei tagliandi del settore Tribuna Rao<\/strong>. Si ribadisce che l\u2019acquisto del tagliando e l\u2019ingresso allo Stadio sono consentiti esclusivamente previa esibizione di un documento di identit\u00e0 valido (non sono utili le patenti prive di indicazione della residenza). Di seguito gli orari d\u2019apertura dello Store<\/p>\n<p>Venerd\u00ec\u00a0\u00a0\u00a0\u00a0 10:00\/13:00, 16:00\/19:00<br \/>\nSabato\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 10:00\/13:00, 16:00\/19:00<br \/>\nDomenica 10:00\/13:00<br \/>\nLuned\u00ec\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 10:00\/13:00, 16:00\/19:00<br \/>\nMarted\u00ec\u00a0\u00a0\u00a0\u00a0 10:00\/13:00, 16:00\/19:00<\/p>\n<p>BOTTEGHINI<\/p>\n<p>Mercoled\u00ec\u00a0 10:00\/15:15<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La societ\u00e0 chiama a raccolta i tifosi. Per la semifinale di ritorno di Coppa Italia contro la Viterbese, in programma mercoled\u00ec allo stadio Marulla, tagliandi in vendita a prezzi simbolici<\/p>\n","protected":false},"author":24,"featured_media":90609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-90608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90608"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90609"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}