{"id":90632,"date":"2018-03-10T07:18:36","date_gmt":"2018-03-10T06:18:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-due-arresti-milano-pestaggio-del-figlio-del-boss-novella\/"},"modified":"2023-01-16T18:50:43","modified_gmt":"2023-01-16T17:50:43","slug":"206298-ndrangheta-due-arresti-milano-pestaggio-del-figlio-del-boss-novella","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/206298-ndrangheta-due-arresti-milano-pestaggio-del-figlio-del-boss-novella\/","title":{"rendered":"&#8216;Ndrangheta: due arresti a Milano per il pestaggio del figlio del boss Novella"},"content":{"rendered":"<h4>Due persone sono state arrestate a Milano nell&#8217;ambito della lotta alla &#8216;ndrangheta in Lombardia: si tratta del 58enne Francesco Cicino e il 37enne Vincenzo Montemurro, ex braccio destro del boss Carmelo Novella, ucciso nel 2008.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MILANO &#8211; I due ono accusati di tentata estorsione e di essere i responsabili del pestaggio nel maggio scorso a Legnano di Edoardo Novella, figlio del boss, che si era appropriato di 250.000 euro. Gli arresti sono stati eseguiti dal Centro Operativo Dia di Milano, coordinato dalla locale Direzione Distrettuale Antimafia, e fanno seguito alle operazioni &#8220;Linfa&#8221; e &#8220;Kerina 2&#8221;, che, nei mesi scorsi, avevano portato complessivamente all&#8217;arresto di 15 persone, principalmente di origini calabresi, indagate per associazione finalizzata al traffico e alla detenzione di sostanze stupefacenti. Le indagini avevano portato in precedenza al sequestro complessivo di oltre 150 chili di droga. Il processo e&#8217; iniziato a febbraio.<br \/>\nIl 27 gennaio era stato arrestato proprio Edoardo Novella, figlio di Carmelo, gia&#8217; reggente della struttura di &#8216;ndrangheta denominata &#8220;Lombardia&#8221;, ucciso in un agguato il 14 luglio 2008 a San Vittore Olona, nel Milanese. Edoardo Novella rivestiva un ruolo di spicco nell&#8217;organizzazione, mettendo anche a disposizione, per il traffico di droga, i locali di una societa&#8217; a lui riconducibile.<br \/>\nL&#8217;aggressione al figlio del boss era avvenuta la mattina del 13 maggio 2017, dentro la Tremont Car di Legnano, all&#8217;interno della quale, e&#8217; stato accertato nel corso delle indagini, si riunivano gli appartenenti all&#8217;associazione criminale dedita al narcotraffico, alla quale lo stesso Novella \u00e8\u00a0accusato di appartenere. Con la fondamentale complicita&#8217; di Cicino &#8211; che faceva in modo di far rimanere Edoardo Novella da solo, in un vero e proprio agguato &#8211; al suo arrivo presso la Tremont Car, Montemurro lo aveva aggredito, minacciandolo e colpendolo violentemente piu&#8217; volte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due persone sono state arrestate a Milano nell&#8217;ambito della lotta alla &#8216;ndrangheta in Lombardia: si tratta del 58enne Francesco Cicino e il 37enne Vincenzo Montemurro, ex braccio destro del boss Carmelo Novella, ucciso nel 2008.<\/p>\n","protected":false},"author":22,"featured_media":90633,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-90632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90632"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90633"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}