{"id":9067,"date":"2012-12-06T07:59:30","date_gmt":"2012-12-06T06:59:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9067"},"modified":"2023-01-17T13:42:14","modified_gmt":"2023-01-17T12:42:14","slug":"3967-allordine-dei-medici-si-discute-di-ricetta-telematica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3967-allordine-dei-medici-si-discute-di-ricetta-telematica\/","title":{"rendered":"All\u2019Ordine dei Medici si discute di ricetta telematica"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>REGGIO CALABRIA<\/strong> &#8211; La trasmissione dei dati delle ricette \u00e8 stato il tema di un incontro promosso dall\u2019Ordine dei medici della Provincia di Reggio<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Calabria, in collaborazione col Dipartimento Salute della Regione Calabria, al fine di rendere edotti tutti i medici prescrittori sulle nuove frontiere della ricetta telematica e dematerializzata. All\u2019incontro, a cui hanno partecipato anche il Direttore Sanitario dell\u2019Azienda Ospedaliera di Reggio Calabria, Domenico Carbone ed il presidente dell\u2019Ordine reggino, Pasquale Veneziano, ad aprire l\u2019assise \u00e8 stato il vicepresidente dell\u2019Ordine dei Medici, Giuseppe Zampogna, che nel porgere i propri saluti ai relatori ed al ricco uditorio, ha auspicato \u201cuna riedizione dell\u2019iniziativa nella Piana e nel comprensorio della Locride in modo da consentire a tutti i medici di medicina generale di poter essere informati su queste importanti e rivoluzionarie novit\u00e0\u201d.&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u201cCon il Decreto della Presidenza del Consiglio dei Ministri del 26 marzo 2008 \u2013 ha evidenziato Rosalba Barone del Dipartimento Regionale della Salute \u2013 tutti i medici prescrittori avrebbero dovuto provvedere all\u2019invio telematico delle ricette. I ritardi registrati in tal senso, nella nostra Regione, hanno determinato anche il blocco di alcuni fondi Fas, poich\u00e9 non sono stati raggiunti i livelli richiesti dal Ministero in relazione all\u2019invio telematico delle ricette. Chiediamo, pertanto, uno sforzo da parte di tutti i medici per metterci a regime con la normativa in quanto almeno il 40% dei medici deve aver provveduto all\u2019invio delle ricette in forma telematica ed ancora siamo lontani dal raggiungere questo traguardo a cui auguriamo di arrivare entro marzo, pena delle sanzioni\u201d.&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">E\u2019 intervenuto, quindi, a relazionare sul tema di giornata, Giuseppe Cesaretti, della Sogei, la Societ\u00e0 Informatica del Ministero delle Finanze il quale \u00e8 partito dal progetto tessera sanitaria per delineare il quadro normativo e tecnico della ricetta telematica e dematerializzata.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u201cQuasi tutta l\u2019Italia, a differenza della Calabria \u2013 ha evidenziato Cesaretti \u2013 \u00e8 a regime su questo progetto. I primi segnali, in questa direzione, furono contenuti nella finanziaria del 2003 che impose un monitoraggio della spesa sanitaria con il primo atto che va individuato nell\u2019emissione della tessera sanitaria. Tuttavia, per la prima volta nel 2010, il legislatore ha dato avvio all\u2019iter vero e proprio di quella che un giorno sar\u00e0 la ricetta elettronica. Il decreto del 2011, invece, ha introdotto il concetto di ricetta dematerializzata che dovrebbe portare, nel tempo, all\u2019abolizione della ricetta cartacea. Tra qualche mese, su questo punto, il Molise, e qualche altra regione, inizier\u00e0 con una fase sperimentale. Tuttavia, dal mese di Aprile prossimo inizieranno ad essere erogate le sanzioni nei confronti delle Regioni che non adempiranno alla trasmissione telematica delle ricette. Nonostante ci\u00f2, il ricettario rosso non andr\u00e0 mai in pensione poich\u00e9 servir\u00e0 a sopperire ad eventuali intoppi di carattere tecnico; inoltre, alcune prescrizioni, come la terapia del dolore, per decisione ministeriale, continueranno ad essere effettuate in forma cartacea\u201d.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">\u201cTra i riverberi di questo progetto \u2013 ha aggiunto, infine, Giuseppe Cesaretti \u2013 ci sar\u00e0 l\u2019utile possibilit\u00e0 di effettuare con puntualit\u00e0 indagini epidemiologiche\u201d.<\/p>\n<p><span style=\"font-size: 12px; line-height: 18.66666603088379px; background-color: #ffffff;\"><br \/><\/span><span style=\"font-size: 12px; line-height: 18.66666603088379px; background-color: #ffffff;\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; REGGIO CALABRIA &#8211; La trasmissione dei dati delle ricette \u00e8 stato il tema di un incontro promosso dall\u2019Ordine dei medici della Provincia di Reggio<\/p>\n","protected":false},"author":22,"featured_media":9068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9067"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9068"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}