{"id":90752,"date":"2018-03-13T12:12:50","date_gmt":"2018-03-13T11:12:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/controlli-dei-carabinieri-a-cosenza-nel-mirino-via-degli-stadi\/"},"modified":"2023-01-16T18:50:51","modified_gmt":"2023-01-16T17:50:51","slug":"206788-controlli-dei-carabinieri-a-cosenza-nel-mirino-via-degli-stadi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/206788-controlli-dei-carabinieri-a-cosenza-nel-mirino-via-degli-stadi\/","title":{"rendered":"Controlli dei carabinieri a Cosenza, nel mirino via degli Stadi (VIDEO)"},"content":{"rendered":"<h4>Un imponente dispiegamento di forze dall&#8217;alba\u00a0fino al primo pomeriggio ha perlustrato i quartieri nell&#8217;ambito di un servizio preventivo di controllo del territorio<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA -Blitz dell&#8217;Arma alle prime ore dell&#8217;alba nel quartiere di San Vito, una citt\u00e0 nella citt\u00e0, in cui si vive una vita diversa con regole diverse. Un servizio preventivo strutturato dal comando provinciale dei Carabinieri di Cosenza con il tenente colonnello Piero Sutera, d\u2019intesa con la Procura della Repubblica\u00a0bruzia, sotto il coordinamento del procuratore capo Mario Spagnuolo,\u00a0che ha visto coinvolti 150 carabinieri della compagnia cittadina coordinata dal capitano Jacopo Passaquieti, supportati\u00a0dalla squadriglia\u00a0dei cacciatori di Calabria, dalle unit\u00e0 cinofile e dai carabinieri Forestali. Un&#8217;azione preventiva quella esercitata ieri, che ha voluto sottolineare\u00a0 &#8220;<strong>la presenza dello Stato anche in circuiti cittadini che appaiono un po\u2019 al di fuori della legalit\u00e0&#8221;.\u00a0Sei le persone arrestate per furto di energia elettrica, note alle forze dell\u2019ordine per precedenti penali, nove le persone denunciate sempre per energia elettrica e occupazione abusiva. Settanta le utenze gas controllate di cui 37 staccate, 17 i veicoli posti sotto sequestro e portati via con carro attrezzi. Sequestrata anche una piazzetta piena di rifiuti speciali.\u00a0<\/strong><\/p>\n<p>Sono state perlustrate <strong>due aree al di fuori del circuito cittadino<\/strong>, 70 appartamenti (<strong>zona piazza Da Locri<\/strong>, dove si trovano gli alloggi gestiti dall\u2019<strong>Aterp,<\/strong>\u00a0considerata la <strong>parte\u00a0bassa\u00a0di San Vito<\/strong>\u00a0e <strong>piazza Silvio Taranto, la parte alta del quartiere<\/strong> ormai in gestione al <strong>Comune<\/strong>), unitamente ai funzionari degli enti, accompagnati dai tecnici dell\u2019Enel e dell\u2019Italgas.\u00a0La presenza massiccia dell&#8217;Arma, con un numero cospicuo di carabinieri schierati, con una zona di cinturazione, filtraggio, ha da subito fatto venire meno qualsiasi idea della turbativa dell\u2019ordine pubblico, per cui alla fine <strong>chi si trovava in quel momento all\u2019interno degli alloggi ha accettato di essere parte di questa verifica<\/strong>.\u00a0Il servizio non \u00e8 ancora terminato.\u00a0I dati forniti potrebbero essere provvisori, i carabinieri attendono ulteriori verifiche demandate ad altri organi competenti, quale il comune e l&#8217;Aterp. Particolare attenzione \u00e8 stata data all&#8217;<strong>aspetto ambientale sfruttando la competenza dei carabinieri Forestali di Cosenza<\/strong>; <strong>sequestrate\u00a0due aree con enormi rifiuti speciali e pericolosi, tra cui carcasse di auto e pneumatici. Si proceder\u00e0 alla bonifica nei giorni prossimi.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Il blitz per ripulire dall&#8217;illegalit\u00e0<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<div style=\"width: 432px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-206961 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/SUTERA-PICCOLA-440x264.png\" alt=\"SUTERA PICCOLA\" width=\"422\" height=\"253\" title=\"\"><p class=\"wp-caption-text\"><\/strong> Il comandante provinciale dell&#8217;Arma dei Carabinieri di Cosenza, il tenente colonnello Piero Sutera<\/p><\/div>\n<p><strong>L&#8217;obiettivo dell&#8217;operazione\u00a0<\/strong>\u00e8 stato spiegato dal comandante provinciale dell&#8217;Arma, il tenente colonnello Piero <strong>Sutera<\/strong>:\u00a0\u00abLa cosa pi\u00f9 importante oggi non \u00e8 parlare di dati e risultati, ma quanto sottolineare\u00a0 <strong>la presenza dello Stato anche in circuiti cittadini che appaiono un po\u2019 al di fuori della legalit\u00e0<\/strong>. E\u2019 importante per i cittadini sapere che <strong>quando si parla di legalit\u00e0 lo si fa non con uno slogan ma con delle azioni concrete.<\/strong> <strong>E questo servizio vuole affermarlo in maniera forte e perentoria<\/strong>\u00bb. \u00abI risultati sono una serie di allacci abusivi alla rete elettrica, idrica, del gas, sulle occupazioni abusive di alloggi, accertamenti che sono chiaramente ancora in divenire. Ad oggi posso dire che abbiamo arrestato sei soggetti gi\u00e0 con pregiudizi penali per furto di energia elettrica, altri sette deferiti in stato di libert\u00e0 per una serie di reati ma soprattutto <strong>riaffermare la presenza dello Stato<\/strong>. Si \u00e8 guardato ad una serie di elementi che apparentemente potrebbero apparire secondari; per esempio l\u2019aspetto ambientale. Sono state rinvenute numerose carcasse di auto depredate e abbandonate sul suolo pubblico e abbiamo inteso coinvolgere i carabinieri Forestali sfruttando la loro specifica mirata competenza. Sono state trovate numerose auto sprovviste di copertura assicurativa\u00a0 per cui si fa riferimento ad un servizio dell\u2019Arma effettuato con una copertura di 360 gradi\u00bb<\/p>\n<p>&nbsp;<\/p>\n<h2>San Vito, &#8220;una citt\u00e0 nella citt\u00e0&#8221;<\/h2>\n<p>\u00ab<strong>Ha una funzione preventiva e di riaffermazione dello Stato l\u00e0 dove si parla di ambienti che appaiono ormai totalmente fuori\u00a0 da ogni forma di legalit\u00e0<\/strong>\u00a0&#8211; spiega il tenente colonnello Sutera -; 37 distacchi del gas, 10 distacchi Enel, procedimenti amministrativi per morosit\u00e0: ci sono gli organi preposti che stanno verificando \u00a0(da una parte il comune, dall\u2019altra l\u2019Aterp) se gli originari assegnatari di questi alloggi coincidono con quelli che sono gli attuali possessori. Noi abbiamo<strong> identificato centinaia di persone<\/strong>\u00a0 oltre a valutare numerosi mezzi parcheggiati, proprio per capire effettivamente se chi occupa questi alloggi lo fa con un titolo\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00a0Abusi edilizi, nuove costruzioni al posto di giardini<\/h2>\n<p>\u00abGli alloggi sono stati trasformati &#8211; spiega Sutera-, sia\u00a0nelle palazzine poste nella parte alta del quartiere, ma anche all\u2019interno con muri abbattuti; sono stati uniti due alloggi per farne uno formato \u201cmagnum\u201d, che da un\u2019idea di come <strong>quell\u2019ambito territoriale non sia stato mai evidentemente attenzionato con il dovuto impegno dagli addetti ai controlli<\/strong>\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<h2>Il lavoro di prevenzione<\/h2>\n<p>\u00abLavoreremo su due fronti &#8211; ha concluso il comandante provinciale dell&#8217;Arma di Cosenza-: il primo \u00e8 attendere <strong>l\u2019esito di queste verifiche<\/strong> che \u201csfuggono alla nostra competenza\u201d. Spero che ci sia una adeguata ed immediata risposta da parte degli organi competenti, per esempio il comune \u00a0in ordine agli alloggi. Poi da qui capiremo quali <strong>altri provvedimenti saranno necessari<\/strong> . Sul fatto che ci saranno <strong>altri servizi non posso escluderlo<\/strong>. <strong>Ci sono altre aree da non sottovalutare<\/strong>. <strong>L\u2019operazione di oggi \u00e8 soltanto un inizio, non abbiamo risolto definitivamente la problematica ma abbiamo iniziato\u00a0 a parlare di legalit\u00e0\u00a0concretamente<\/strong>\u00bb<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\">GUARDA LE FOTO<\/span><\/h2>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\">GUARDA IL VIDEO<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Controlli carabinieri via degli stadi\" width=\"740\" height=\"555\" src=\"https:\/\/www.youtube.com\/embed\/xalrpjIkrEE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un imponente dispiegamento di forze dall&#8217;alba\u00a0fino al primo pomeriggio ha perlustrato i quartieri nell&#8217;ambito di un servizio preventivo di controllo del territorio<\/p>\n","protected":false},"author":22,"featured_media":90753,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-90752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90752"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90753"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}