{"id":90838,"date":"2018-03-15T13:59:33","date_gmt":"2018-03-15T12:59:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caso-bernaudo-lasp-e-la-dottoressa-autodenunciatasi-continunano-a-litigare\/"},"modified":"2023-01-16T18:50:56","modified_gmt":"2023-01-16T17:50:56","slug":"207197-caso-bernaudo-lasp-e-la-dottoressa-autodenunciatasi-continunano-a-litigare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/207197-caso-bernaudo-lasp-e-la-dottoressa-autodenunciatasi-continunano-a-litigare\/","title":{"rendered":"Caso Bernaudo: l&#8217;Asp e la dottoressa autodenunciatasi continunano a &#8216;litigare&#8217;"},"content":{"rendered":"<p><strong>Dagli atti si evince la rinuncia alla compensazione delle spese, ma la dottoressa Bernaudo pare voglia chiedere di accertare l&#8217;illegittimit\u00e0 dei provvedimenti assunti dall&#8217;ASP di Cosenza<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; A dimostrazione di quanto dichiarato dall\u2019Azienda Sanitaria Provinciale di Cosenza, in relazione la nota vicenda che la dott.ssa Giuliana Bernaudo ha intrapresa contro l\u2019ASP, a riprova della veridicit\u00e0 e della bont\u00e0 dell\u2019agire della stessa ASP, si allega alla presente il verbale di udienza della causa N.R.G 251\/2018 dalla quale <strong>si evince chiaramente la \u201crinuncia alla domanda cautelare verso la compensazione delle spese di lite\u201d della stessa dott.ssa Bernaudo.<\/strong> Nello specifico si evince che \u00e8 la stessa dottoressa ad aver rinunciato alla sospensiva e che l\u2019ASP ha accettato la sua rinuncia. Questi i termini esatti del giudizio in corso. Nel verbale della causa tra Giuliana Bernaudo e l&#8217;ASP di Cosenza depositato presso la cancelleria Lavoro del Tribunale di Paola si legge che\u00a0&#8220;la parte ricorrente (dottoressa Bernaudo) rinuncia alla domanda cautelare verso la compensazione delle spese di lite. La parte convenuta accetta la rinuncia dopo essere stata autorizzata dal Direttore generale dell\u2019ASP di Cosenza, verso compensazione delle spese di lite&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>La dottoressa autodenunciatasi per esercizio abusivo della professione rifiuta tale versione dei fatti. &#8220;E&#8217; opportuno smentire nel modo pi\u00f9 assoluto quanto affermato dall&#8217;Asp di Cosenza circa il fatto che la dott.ssa Bernaudo &#8211; scrivono in una nota i suoi legali difensori &#8211; avrebbe <strong>improvvisamente rinunciato all&#8217;azione cautelare avente ad oggetto l&#8217;impugnazione del nuovo incarico affidatole in quanto l&#8217;esito del giudizio avrebbe assunto un esito per lei sfavorevole<\/strong>. Ricomponendo la realt\u00e0 dei fatti si ricorda alla Direzione strategica dell&#8217;Asp di Cosenza (che probabilmente non si \u00e8 ben informata presso i suoi legali presenti all&#8217;udienza) che il giudizio svoltosi il 13 marzo dinnanzi al Giudice del Lavoro del Tribunale di Paola non aveva ad oggetto l&#8217;affidamento del nuovo incarico assegnato illegittimamente alla dott. Bernaudo, bens\u00ec l&#8217;avviso con cui l&#8217;Asp nel novembre 2017 aveva indetto la procedura per ricoprire gli incarichi (gi\u00e0 peraltro regolarmente ricoperti) di Direttore di Distretto.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nPertanto il primo punto da smentire \u00e8 che la dott.ssa Bernaudo abbia rinunciato all&#8217;azione relativa al nuovo incarico affidatole di direttore dell&#8217;Unit\u00e0 operativa igiene ed alimenti. Inoltre, \u00e8 da aggiungere che nel ricorso cautelare tenuto il 13 marzo \u00e8 stato il Giudice del Lavoro del Tribunale di Paola che ha invitato le parti presenti, dott.ssa Bernaudo e ASP di Cosenza, a trovare un accordo sulla richiesta cautelare (salvo ed impregiudicato il merito della richiesta di accertamento della legittimit\u00e0 dell&#8217;avviso del novembre 2017 e risarcimento dei danni) e in tal senso sia la dott.ssa Bernaudo che i legali dell&#8217;ASP, espressamente autorizzati dal Direttore Generale, <strong>hanno accolto la proposta conciliativa del Giudice e accordato di accettare consensualmente alla pronuncia di non luogo a procedere<\/strong>; ci\u00f2 perch\u00e8 il danno grave ed irreparabile che si era profilato alla data del deposito del ricorso (ossia l&#8217;assegnazione dell&#8217;incarico di Direttore di Distretto ad altro soggetto) non si era ancora verificato, mentre purtroppo alla data di trattazione del ricorso il danno si era gi\u00e0 consumato, in quanto l&#8217;ASP aveva gi\u00e0 proceduto all&#8217;assegnazione dell&#8217;incarico e alla stipula del contratto con altro soggetto e pertanto il Giudice del Lavoro ha dichiarato che non rientrava nei suoi poteri sospendere detti atti.<\/p>\n<p>&nbsp;<\/p>\n<p>Non ci resta a questo punto che ringraziare la direzione strategica dell&#8217;ASP di Cosenza che, con la diffusione del verbale di udienza non ha fatto altro che confermare quanto da noi dichiarato. E tanto vale quanto anche il fatto che l&#8217;ASP non ha smentito (n\u00e9 avrebbe potuto farlo) le nostre contestazioni e cio\u00e8 che la dott. Bernaudo avesse rinunciato all&#8217;impugnazione del nuovo incarico, non corrispondesse alla realt\u00e0 dei fatti.<strong> La dott.ssa Bernaudo non rinuncia e non ha alcun timore di proporre una causa di merito al fine di accertare l&#8217;assoluta illegittimit\u00e0 dei plurimi provvedimenti dell&#8217;ASP di Cosenza<\/strong> in relazione sia all&#8217;avviso di conferimento incarico di Direttore di Distretto, sia al nuovo incarico illegittimamente assegnato sia ancora al risarcimento di tutti i danni subiti a causa del comportamento dell&#8217;ASP gravemente lesivo della sua persona\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dagli atti si evince la rinuncia alla compensazione delle spese, ma la dottoressa Bernaudo pare voglia chiedere di accertare l&#8217;illegittimit\u00e0 dei provvedimenti assunti dall&#8217;ASP di Cosenza<\/p>\n","protected":false},"author":21,"featured_media":90839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-90838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=90838"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/90838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/90839"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=90838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=90838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=90838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}