{"id":91059,"date":"2018-03-22T09:42:46","date_gmt":"2018-03-22T08:42:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tornato-dal-canada-e-stato-arrestato-a-fiumicino-latitante-in-manette\/"},"modified":"2023-01-16T18:51:12","modified_gmt":"2023-01-16T17:51:12","slug":"208289-tornato-dal-canada-e-stato-arrestato-a-fiumicino-latitante-in-manette","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/208289-tornato-dal-canada-e-stato-arrestato-a-fiumicino-latitante-in-manette\/","title":{"rendered":"Tornato dal Canada \u00e8 stato arrestato a Fiumicino, latitante in manette"},"content":{"rendered":"<h4>La Polizia ha arrestato questa mattina all&#8217;aeroporto di Fiumicino l&#8217;esponente della &#8216;ndrangheta, Tito Figliomeni, latitante da sette anni.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; I poliziotti del Servizio Centrale Operativo e della Squadra Mobile di Reggio Calabria hanno arrestato il 49enne Tito Figliomeni eseguendo un&#8217;ordinanza di custodia cautelare in carcere, emessa dal Giudice delle Indagini Preliminari di Reggio Calabria. Le accuse nei suoi confronti sono di associazione di tipo mafioso e intestazione fittizia di beni nell&#8217;ambito dell&#8217;operazione &#8220;Bene Comune&#8221;, compiuta nel <strong>dicembre 2010<\/strong> e coordinata dai magistrati della Procura della Repubblica di Reggio Calabria.<\/p>\n<p>Figliomeni, latitante dal dicembre 2010, \u00e8 giunto a Fiumicino a bordo di un volo intercontinentale proveniente da Toronto. L&#8217;uomo aveva lasciato l&#8217;Italia nel settembre 2010, pochi mesi prima dell&#8217;operazione<strong> &#8220;Bene Comune&#8221;<\/strong>, e dopo il suo ingresso in Canada, ha dimorato stabilmente nella<strong> Greater Toronto Area<\/strong>, avvalendosi di una fitta rete di appoggi logistici.<strong> In Canada<\/strong> il latitante utilizzava false generalit\u00e0 per impedire la sua identificazione e la conseguente espulsione verso l&#8217;Italia.<\/p>\n<p><strong>Gi\u00e0 il 10 marzo scorso Figliomeni era stato arrestato in Canada<\/strong>, dalla polizia locale, per<strong> violazione della normativa sull&#8217;immigrazione<\/strong> e cos\u00ec quando stamattina \u00e8 giunto all&#8217;aeroporto di Roma-Fiumicino, investigatori del Servizio Centrale Operativo e della Squadra Mobile di Reggio Calabria lo hanno preso in consegna. L&#8217;esponente della cosca della &#8216;ndrangheta Commisso di Siderno il 10 marzo era stato arrestato dal Custom and Border Force canadese, nel quadro di una diretta collaborazione tra il Servizio Centrale Operativo della Polizia di Stato, la Squadra Mobile di Reggio Calabria, la Royal Canadian Mounted Police e la Polizia Metropolitana di Toronto, d&#8217;intesa con l&#8217;esperto per la sicurezza italiano ad <strong>Ottawa (Canada).<\/strong><\/p>\n<p>A seguito del perfezionamento dell&#8217;iter procedurale \u00e8 stata decretata la sua espulsione dal Canada, le cui fasi esecutive sono state gestite congiuntamente dalle autorita&#8217; italiane e canadesi. Tito Figliomeni e&#8217; ritenuto uno tra i principali esponenti del gruppo mafioso dei &#8220;Rumbo-Galea-Figliomeni&#8221;, confederato alla potente cosca &#8220;commisso&#8221; di Siderno, una delle piu&#8217; importanti famiglie della &#8216;ndrangheta operante sulla fascia ionica reggina. Il latitante arrestato, secondo gli inquirenti, operava in modo fittizio come socio di maggioranza in una societa&#8217; di Siderno operante nel settore dello smaltimento-inerti e movimento-terra. Dalle indagini sarebbe emerso che in Canada, a causa di divergenze sulla gestione degli affari derivanti dall&#8217;apertura di alcuni esercizi pubblici nel settore delle<strong> &#8220;slot machine<\/strong>&#8221; e del gioco d&#8217;azzardo, erano sorti contrasti in seno alla &#8216;ndrina, che l&#8217;hanno coinvolto insieme ad altri indagati.<\/p>\n<p>In particolare, l&#8217;apertura di un bar, avvenuta probabilmente in una zona non di competenza della cosca, aveva rischiato di condizionare negativamente gli interessi economici di altre componenti &#8216;ndranghetiste operanti nel distretto dell&#8217;Ontario. Da cio&#8217; era derivato l&#8217;intervento pacificatore dei vertici calabresi della cosca commisso, per dirimere la controversia sorta oltreoceano al fine di riportare la pace ritenuta indispensabile per il perseguimento del &#8220;bene comune&#8221;. Tito Figliomeni e&#8217; cugino di Angelo e Cosimo Figliomeni, tuttora latitanti e dimoranti in Canada, nonche&#8217; cugino di Maria Frasca&#8217;, donna di origini calabresi assassinata a colpi di pistola il 24 giugno 2015, nel corso di un agguato mafioso avvenuto all&#8217;interno del bar di Woodbridge (Toronto-Canada). L&#8217;arresto rappresenta, secondo gli inquirenti, un importante tassello nell&#8217;ambito della cooperazione investigativa tra Italia e Canada sul fronte del contrasto alle proiezioni internazionali della &#8216;ndrangheta in Nord America, avviata dal Servizio Centrale Operativo e dalla Squadra Mobile di Reggio Calabria, con il coordinamento della Procura Distrettuale di Reggio Calabria e della Procura Nazionale Antimafia e Antiterrorismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polizia ha arrestato questa mattina all&#8217;aeroporto di Fiumicino l&#8217;esponente della &#8216;ndrangheta, Tito Figliomeni, latitante da sette anni.<\/p>\n","protected":false},"author":22,"featured_media":91060,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-91059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91059"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91060"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}