{"id":91215,"date":"2018-03-26T11:30:59","date_gmt":"2018-03-26T09:30:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/santa-pasqua-orari-celebrazioni-cosenza-vescovo\/"},"modified":"2023-01-16T18:51:22","modified_gmt":"2023-01-16T17:51:22","slug":"208897-santa-pasqua-orari-celebrazioni-cosenza-vescovo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/208897-santa-pasqua-orari-celebrazioni-cosenza-vescovo\/","title":{"rendered":"Santa Pasqua, al via la Settimana Santa: le celebrazioni della Diocesi di Cosenza"},"content":{"rendered":"<h4>La settimana Santa che porter\u00e0 alla Pasqua \u00e8 iniziata. Tutti gli orari delle celebrazioni presiedute dall\u2019Arcivescovo di Cosenza Mons. Francesco Nol\u00e8<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Si inizia il 28 marzo alle 17.00 nella Cattedrale di Cosenza. L\u2019Arcivescovo presieder\u00e0, nel giorno del <strong>Mercoled\u00ec Santo<\/strong>,\u00a0 la Santa Messa Crismale concelebrata da tutti i sacerdoti della diocesi. Il <strong>Gioved\u00ec Santo<\/strong> alle 18.00 sempre nella Cattedrale l\u2019Arcivescovo presieder\u00e0 la Santa Messa \u201cNella Cena del Signore\u201d con la riposizione del Santissimo sacramento all\u2019altare appositamente preparato. Seguir\u00e0 l&#8217;adorazione notturna.<\/p>\n<p><strong>Venerd\u00ec Santo<\/strong>, 30 Marzo alle 18.00 mons. Nol\u00e8 presieder\u00e0 la Celebrazione della Passione e morte di Nostro Signore Ges\u00f9 Cristo con la venerazione della Croce. Alle 20.30 partir\u00e0 la Via Crucis per le strade della citt\u00e0 ma il raduno \u00e8 previsto alle ore 20.00 da Piazza Loreto. Si concluder\u00e0 davanti alla Chiesa di San Nicola in Piazza Cenisio. Le meditazioni delle stazioni sono state scritte dai parroci della Citt\u00e0 di Cosenza. Il prossimo 31 marzo, <strong>Sabato Santo<\/strong> alle 23.30 l&#8217;inizio della solenne Veglia Pasquale che sar\u00e0 sempre presieduta dall\u2019Arcivescovo in Cattedrale. E infine <strong>domenica 1 aprile<\/strong> di Resurrezione, giorno della Pasqua del Signore, mons. Nol\u00e8 presieder\u00e0 alle 11.0 in Cattedrale la Santa Messa Solenne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La settimana Santa che porter\u00e0 alla Pasqua \u00e8 iniziata. Tutti gli orari delle celebrazioni presiedute dall\u2019Arcivescovo di Cosenza Mons. Francesco Nol\u00e8<\/p>\n","protected":false},"author":22,"featured_media":91216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-91215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91215"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91216"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}