{"id":91288,"date":"2018-03-27T19:08:44","date_gmt":"2018-03-27T17:08:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-varchi-zone-a-traffico-limitato-dal-1-aprile-tolleranza-zero\/"},"modified":"2023-01-16T18:51:26","modified_gmt":"2023-01-16T17:51:26","slug":"209120-cosenza-varchi-zone-a-traffico-limitato-dal-1-aprile-tolleranza-zero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/209120-cosenza-varchi-zone-a-traffico-limitato-dal-1-aprile-tolleranza-zero\/","title":{"rendered":"Cosenza, varchi zone a traffico limitato: dal 1\u00b0 Aprile tolleranza zero"},"content":{"rendered":"<h4>Resta da sciogliere il paradosso dei disabili non residenti. Intanto il Comune di Cosenza incassa 120mila euro grazie alle parking card<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Tra pochi giorni l&#8217;accesso ai varchi di via Isonzo e via Piave dovr\u00e0 essere rispettato. Inderogabilmente. Dopo tre mesi di sperimentazione, il Comune di Cosenza ha deciso che a partire dal 1\u00b0 Aprile i veicoli non autorizzati ad entrare nelle due nuove Zone a Traffico Limitato saranno multati. Ad oggi infatti i cittadini &#8216;distratti&#8217; non hanno mai ricevuto sanzioni. Dal prossimo mese saranno invece monitorati ed immortalati dai sistemi elettronici di sorveglianza. Resta da risolvere il problema dei disabili non residenti nelle strade interdette al transito. Anche se in possesso del certificato unificato disabili europeo, CUDE, non \u00e8 consentito loro attraversare sia le <strong>due nuove ZTL di via Isonzo-Conforti e via Piave, sia le ZTL &#8216;storiche&#8217; delle traverse che da via XXIV Maggio, via Montesanto e via Alimena affacciano su Corso Mazzini (via Montesanto non \u00e8 ZTL il cartello luminoso che confonde gli automobilisti riguarda solo via Arabia)<\/strong>. Due sono le opportunit\u00e0 che si presentano di fronte a chi viola l&#8217;accesso alla ZTL. La prima, come spiegano dal comando di Polizia Municipale, consiste nell&#8217;inviare una mail comunicando la data in cui si accede al varco. La seconda invece consiste nel richiedere, una volta ricevuta la multa, l&#8217;archiviazione in autotutela che sar\u00e0 poi valutata e &#8220;sempre accolta&#8221; chiarisce il responsabile del comando Giovanni De Rose. Una condizione poco gradita per i disabili che spesso si trovano a dover passare pi\u00f9 volte, nell&#8217;arco della stessa giornata, dalle ZTL e a ricevere una raffica di multe.<\/p>\n<p>&nbsp;<\/p>\n<h3>IL PARADOSSO DEI DISABILI<\/h3>\n<p>E&#8217; il caso di un signore residente a Cosenza, ma non nelle strade in cui sono attivi i varchi. &#8220;Negli ultimi mesi &#8211; racconta &#8211; ho ricevuto 15 multe. Ho presentato istanza per l&#8217;archiviazione e mi \u00e8 stata accettata. E&#8217; per\u00f2 assurdo che ogni volta che devo passare per andare dal medico o in posta debba inviare una mail. Quando vado a Roma, per esempio, comunico che transiter\u00f2 nelle ZTL e il mio permesso vale per i giorni in cui soggiorno l\u00ec. Sembra paradossale che una citt\u00e0 come Cosenza, che ama definirsi &#8216;europea&#8217;, non abbia contemplato nel proprio regolamento le normative europee che prevedono il transito dei disabili in tutte le Zone a Traffico Limitato. In pi\u00f9 c&#8217;\u00e8 da rilevare anche pur volendo parcheggiare su via XXIV Maggio, via Alimena o via Montesanto (e con estrema fatica arrivare a destinazione a piedi) gli stalli dedicati ai disabili si contano sulla punta delle dita e sono sempre occupati. <strong>Chi come me ha problemi a camminare cosa deve fare? Inviare dieci mail al giorno? E chi invece non sa usare le mail come fa?<\/strong>&#8220;. A rispondere \u00e8 l&#8217;asssessore alla Mobilit\u00e0 Sostenibile del Comune di Cosenza Michelangelo Spataro che oggi al termine della commissione consiliare Trasporti ha chiarito che &#8220;la questione sar\u00e0 affrontata nei prossimi giorni, insieme alle associazioni cittadine che si occupano di disabilit\u00e0&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3>PARCHEGGI<\/h3>\n<p>In scadenza, al termine del mese di Marzo, anche le parking card del 2017. Gli uffici da gennaio sono al lavoro per il rilascio delle nuove tessere per residenti ed abbonati che consentono di parcheggiare anche sulle strisce blu. In totale sono state, ad oggi, distribuite 3.671 parking card con un incasso per il Comune di Cosenza di 120mila euro a fronte di una spesa per la loro stampa di 1.000 euro. A questa entrata sono da aggiungere gli importi derivanti al Comune dagli abbonamenti sottoscritti dai corrieri che accedono alla ZTL, \u201cun&#8217;entrata che prima non c&#8217;era \u2013 ha sottolineato l&#8217;Assessore Spataro\u00a0&#8211; e che ora \u00e8 destinata ad aumentare\u201d. Le altre novit\u00e0 riguardano i 70 stalli eliminati su viale della Repubblica, mentre la gestione di altri 250 \u00e8 passata amministrativamente da Amaco alla ditta privata Saba.<strong> Alcuni residenti, in particolare nella zona dell&#8217;Ospedale Civile in via Talarico hanno rinunciato ad acquistare la parking card consapevoli che n\u00e9 sulle strisce blu, n\u00e9 sulle strisce bianche troveranno mai parcheggio<\/strong> rientrando a casa. Un problema che riguarda anche i dipendenti dell&#8217;Azienda Ospedaliera che ritengono poco vantaggiosi i prezzi offerti dal parcheggio di via Migliori, gestito come i Due Fiumi e Tribunale dalla societ\u00e0 privata SABA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resta da sciogliere il paradosso dei disabili non residenti. Intanto il Comune di Cosenza incassa 120mila euro grazie alle parking card<\/p>\n","protected":false},"author":22,"featured_media":91289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-91288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91288"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91289"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}