{"id":91321,"date":"2018-03-28T16:56:21","date_gmt":"2018-03-28T14:56:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/impianto-celico-conferiti-carta-cartone-e-plastica\/"},"modified":"2023-01-16T18:51:28","modified_gmt":"2023-01-16T17:51:28","slug":"209264-impianto-celico-conferiti-carta-cartone-e-plastica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/209264-impianto-celico-conferiti-carta-cartone-e-plastica\/","title":{"rendered":"Impianto Celico, conferiti carta, cartone e plastica"},"content":{"rendered":"<h4>Lo comunica la Regione impegnatasi a monitorare le emissioni odorifere utilizzando il &#8220;naso elettronico&#8221; e i volontari &#8220;vedette&#8221; per gli odori sospetti<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CELICO (CS) &#8211; Nei giorni scorsi l\u2019assessore regionale all\u2019ambiente Antonella Rizzo ha presieduto una <strong>riunione con i sindaci dei \u00a0Comuni della Presila cosentina<\/strong> e con l\u2019<strong>Arpacal<\/strong> con all\u2019ordine del giorno il <strong>Piano di monitoraggio<\/strong> per l&#8217;impianto di Celico. Nel corso della riunione si \u00e8\u00a0 concordato un Piano di monitoraggio delle <strong>emissione odorifere sull\u2019area che coinvolge i comuni di Celico, Rovito, Lappano e Spezzano Sila.\u00a0<\/strong>Le amministrazioni\u00a0 comunali si sono impegnate a fornire al Dipartimento regionale dell\u2019ambiente una mappa dei siti da indagare sia attraverso <strong>l\u2019utilizzo del \u201cnaso elettronico\u201d e sia con l\u2019individuazione di volontari<\/strong>, appositamente formati dall\u2019Agenzia regionale per la protezione dell\u2019ambiente per la Calabria e a cui verr\u00e0 assicurato l&#8217;anonimato, che avranno il compito di <strong>allertare le istituzioni nel caso di odori sospetti<\/strong>.<\/p>\n<p>Si \u00e8 anche entrati nel merito del contenuto della <strong>lettera a firma del Comitato ambientale Presilano<\/strong>\u00a0con la quale, tra l\u2019altro, si chiede al Dipartimento regionale \u201ca seguito dell\u2019individuazione di alcuni mezzi della Maya di Casalnuovo di Napoli che nella giornata del 22 marzo 2018 percorrevano la SS107 in direzione di Celico di verificare se nell\u2019impianto siano iniziate le lavorazioni e\/o lo sversamento dei rifiuti e il tipo del rifiuto conferito\u2026\u201d. L\u2019assessore Rizzo ha subito tranquillizzato gli amministratore degli enti locali presenti alla riunione mostrando <strong>copia del verbale<\/strong>\u00a0 di controllo del 23 marzo scorso inviato dall\u2019<strong>Arpacal<\/strong> dal quale si evince che, in seguito all\u2019ultima verifica effettuata nei giorni <strong>19, 20, 21 \u00e8 22 marzo, i rifiuti\u00a0 conferiti nell\u2019impianto sono costituiti da scarti di plastica, carta e cartone proveniente dal circuito Corepla.<\/strong><\/p>\n<p>L\u2019assessore Rizzo, nell\u2019evidenziare che proprio nel segno della trasparenza l\u2019amministrazione Oliverio non ha paura di mostrare gli atti, ricorda che \u201c<strong>per come concordato con i sindaci in un\u2019altra precedente riunione, alla presenza anche del presidente della Regione Mario Oliverio, l&#8217;attivit\u00e0 di conferimento nell&#8217;impianto di Celico viene monitorata attraverso due distinte fasi<\/strong>. La prima stabilisce <strong>l\u2019intervento di Arpa Piemonte e dell\u2019Arpacal con l&#8217;utilizzo di strumentazioni elettroniche di ultima generazione<\/strong>; la seconda, con durata di circa 10\/12 mesi, prevede una <strong>mappatura odorigena di tutta l\u2019area della Presila con campionamenti e controlli presso la struttura<\/strong>. Ribadisco pertanto che l\u2019impianto, cos\u00ec come concordato con i sindaci, \u00e8 costantemente ispezionato da Arpacal e sar\u00e0 anche oggetto di un\u2019attivit\u00e0 di controllo che durer\u00e0\u00a0 12 mesi e che avr\u00e0\u00a0 il compito di assicurare la corretta gestione dell&#8217;impianto e la tutela della salute pubblica\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\">LEGGI ANCHE\u00a0<\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/4055\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">VIDEO \u2013 A Celico i camion dalla \u201cTerra dei Fuochi\u201d: la Presila non \u00e8 disposta a tollerare<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Lo comunica la Regione impegnatasi a monitorare le emissioni odorifere utilizzando il &#8220;naso elettronico&#8221; e i volontari &#8220;vedette&#8221; per gli odori sospetti<\/p>\n","protected":false},"author":37,"featured_media":91322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-91321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91321"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91322"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}