{"id":91573,"date":"2018-04-07T10:48:44","date_gmt":"2018-04-07T08:48:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/stasera-la-rassegna-laltroteatro-ospitera-viaggio-al-termine-della-notte\/"},"modified":"2023-01-16T18:51:45","modified_gmt":"2023-01-16T17:51:45","slug":"210379-stasera-la-rassegna-laltroteatro-ospitera-viaggio-al-termine-della-notte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/210379-stasera-la-rassegna-laltroteatro-ospitera-viaggio-al-termine-della-notte\/","title":{"rendered":"Stasera la \u201cRassegna L&#8217;AltroTeatro\u201d ospiter\u00e0 \u201cViaggio al termine della notte\u201d"},"content":{"rendered":"<h4>Di e con Elio Germano accompagnato dalla chitarra di Theo Teardo. La lettura-concerto che porta in scena il capolavoro di Loius-Ferdinand C\u00e9line.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Finanziato dalla Regione Calabria, quale evento storicizzato- sull&#8217;avviso pubblico per la selezione e finanziamento di interventi per la valorizzazione del sistema dei beni culturali, la qualificazione e il rafforzamento dell&#8217;offerta culturale- vede, inotre, il supporto dell\u2019Amministrazione comunale di Cosenza. Organizzato dalla societ\u00e0 <strong>\u201cL&#8217;AltroTeatro\u201d<\/strong> guidata dal gruppo di operatori del mondo dello spettacolo locale: Enzo Noce, Giuseppe Citrigno e Gianluigi Fabiano. Sul palco del Teatro A. Rendano 14 appuntamenti all\u2019insegna della grande drammaturgia senza dimenticare, per\u00f2, il divertimento e il puro spettacolo. Prosa, dai grandi classici agli autori contemporanei e poi, commedie e musical questi gli ingredienti del cartellone ideato da \u201cL\u2019AltroTeatro\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-210382 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/04\/foto-scena-VIAGGO-AL-TERMINE-DELLA-NOTTE-633x400.jpg\" alt=\"foto-scena-VIAGGO-AL-TERMINE-DELLA-NOTTE\" width=\"428\" height=\"290\" title=\"\"><\/p>\n<p>Elio Germano e Teho Teardo portano in scena &#8220;Viaggio al termine della notte&#8221; di Louis-Ferdinand C\u00e9line in una versione completamente rinnovata nelle musiche e nei testi. Avvalendosi della straordinaria sensibilit\u00e0 interpretativa di <strong>Elio Germano<\/strong> (protagonisti di pellicole come \u201cMio fratello \u00e8 figlio unico\u201d, \u201cIl giovane Favoloso\u201d, \u201cLa Tenerezza\u201d)<strong> Teho Teardo<\/strong> ripercorre musicalmente alcuni frammenti del &#8220;Viaggio&#8221; restituendo, in una partitura inedita, la disperazione grottesca di questo capolavoro di scrittura che ritrova nuove dinamiche espressive nella combinazione di archi, chitarra e live electronics.<\/p>\n<p>Una fusione di sonorit\u00e0 cameristiche che guardano a un futuro tecnologico nel quale, le immagini evocate dal testo interpretato da Germano, si inseriscono nelle atmosfere cinematiche di Teardo; un succedersi di eventi sonori e verbali dove la voce esce dalla sua dimensione tradizionale fino a divenire suono. In quel suono Teardo crea un ambiente nel quale la voce di Germano pu\u00f2 suggerirci nuove prospettive sulle disavventure di Bardamu e gli orrori della guerra mondiale che travolge le relazioni tra gli uomini quanto i continenti. Il pessimismo sulla natura umana, sulle istituzioni, sulla societ\u00e0 e sulla vita in generale, diviene inconsolabile fino a non conceder pi\u00f9 alcuna speranza al consorzio umano. La scenografia \u00e8 quasi inesistente. Il palco, scarno e immerso nel buio, lascia spazio a una scrittura dalla spiccatissima natura, una partitura &#8220;impressionista&#8221; che diventa essa stessa narrazione e si fa interprete del genio di C\u00e9line.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di e con Elio Germano accompagnato dalla chitarra di Theo Teardo. La lettura-concerto che porta in scena il capolavoro di Loius-Ferdinand C\u00e9line.<\/p>\n","protected":false},"author":20,"featured_media":91574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-91573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91573"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91574"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}