{"id":91871,"date":"2018-04-13T13:15:27","date_gmt":"2018-04-13T11:15:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nuova-giunta-della-regione-calabria-in-carica-tre-donne\/"},"modified":"2023-01-16T18:52:06","modified_gmt":"2023-01-16T17:52:06","slug":"211787-nuova-giunta-della-regione-calabria-in-carica-tre-donne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/211787-nuova-giunta-della-regione-calabria-in-carica-tre-donne\/","title":{"rendered":"Nuova Giunta della Regione Calabria, nominate tre donne"},"content":{"rendered":"<h4>Ufficializzato il rinnovo della Giunta Oliverio con i suoi sei assessori<\/h4>\n<p><!--more--><br \/>\nCATANZARO &#8211; Un altro &#8216;rimpasto&#8217; nella Giunta Oliverio. Il primo era avvenuto a pochi mesi dall&#8217;insediamento del presidente Oliverio dopo delle indagini della Direzione distrettuale Antimafia in cui appariva il nome dell&#8217;ex assessore alle Infrastrutture e Trasporti Nino De Gaetano e alle dimissioni dell&#8217;ex assessore ed ex ministro Maria Carmela Lanzetta.\u00a0Oggi il presidente della Regione Calabria, Mario Oliverio, ha nominato la nuova Giunta, la terza. Anche in questo caso le vicende giudiziarie hanno un&#8217;influenza. Un a<strong>vviso di garanzia emesso dalla Procura di Reggio Calabria aveva gi\u00e0 portato alle dimissioni dell&#8217;assessore Barbalace,<\/strong> mentre ai primi di gennaio Oliverio ha revocato le deleghe all&#8217;assessore al Lavoro Roccisano colpevole di aver alimentato le ire dei cittadini della Regione con il pi\u00f9 alto tasso di disoccupazione d&#8217;Europa. L&#8217;ultima novita&#8217; e&#8217; l&#8217;elezione alla Camera del vicepresidente della Giunta, Antonio Viscomi, candidato alle Politiche dello scorso 4 marzo con il Pd.<\/p>\n<p>&nbsp;<\/p>\n<p>Nuovo vicepresidente dell&#8217;esecutivo \u00e9 stato nominato Francesco Russo, che subentra ad Antonio Viscomi, eletto deputato. A Russo, docente dell&#8217;Universit\u00e0 Mediterranea di Reggio Calabria e che era gi\u00e0\u00a0assessore al &#8220;Sistema della logistica&#8221;, al &#8220;Sistema portuale regionale&#8221; ed al &#8220;Sistema Gioia Tauro&#8221;, \u00e8 stato affidato l&#8217;assessorato allo Sviluppo economico ed alle Attivit\u00e0 produttive prima di competenza di Antonella Barbalace. Oliverio, inoltre, ha nominato assessori tre donne, Maria Francesca Corigliano, cui sono attribuite le deleghe alla Cultura, ai Beni culturali ed all&#8217;Istruzione; Maria Teresa Fragomeni Bilancio e programmazione economica e finanziaria, politiche del personale assessorato prima di competenza di Antonio Viscomi ed Angela Robbe al Lavoro, formazione e Politiche Sociali che sostituisce Federica Roccisano. <strong>Confermati come assessori Roberto Musmanno ai Trasporti e Infrastrutture, Antonietta Rizzo all&#8217;Ambiente e Franco Rossi.\u00a0<\/strong>La nuova Giunta sar\u00e0 presentata dal presidente della Regione, Mario Oliverio, in una conferenza stampa che si terr\u00e0 luned\u00ec pomeriggio, alle 17.00 a Catanzaro nella Sala Oro nella Cittadella regionale.<\/p>\n<p>&nbsp;<\/p>\n<h3>LE DICHIARAZIONI DI MARIO OLIVERIO<\/h3>\n<p>&nbsp;<\/p>\n<p>&#8220;La nomina di Russo non e&#8217; una semplice o ordinaria sostituzione. La sua attivita&#8217; svolta in qualita&#8217; di assessore &#8211; ha proseguito Oliverio &#8211; ha registrato unanimi apprezzamenti non solo in Calabria ma anche oltre i confini regionali. Ho inteso compiere questa scelta &#8211; ha affermato Oliverio &#8211; per dare maggiore impulso alla nostra azione di governo affinche&#8217;, a compimento del mandato elettorale conferitomi, i cittadini possano toccare con mano il mutamento della condizione in cui versa la Calabria. Vogliamo dimostrare &#8211; ha continuato Mario Oliverio &#8211; che nonostante le macerie ereditate stiamo lavorando con successo per restituire alla nostra terra il diritto ad avere speranza e fiducia verso il futuro. <strong>I primi timidi segnali di ripresa si vanno gia&#8217; registrando. Dopo oltre un decennio compare il segno positivo davanti ad alcuni indicatori economici<\/strong>. Questa prima inversione di tendenza non puo&#8217; essere ritenuta, pero&#8217;, ancora soddisfacente. Siamo impegnati a fare ancora di piu&#8217; e meglio e a dare una forte accelerazione per determinare il miglioramento della condizione di vita dei calabresi e per l&#8217;affermazione di una positiva reputazione della Calabria&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Anche le nomine di\u00a0Maria Teresa Fragomeni, Angela Robbe e Maria Francesca Corigliano non sono casuali &#8211; ha proseguito Mario Oliverio &#8211; ho inteso dare fiducia ed investire su un esecutivo di governo a maggioranza femminile. <strong>Ritengo che la nostra Giunta regionale sia l&#8217;unica in Italia ad essere colorata prevalentemente di rosa.<\/strong> Anche in un organo di governo, l&#8217;impegno delle donne e&#8217; garanzia di innovazione ed operativita&#8217;. Le scelte fatte &#8211; ha affermato Oliverio &#8211; sono di una effettiva rappresentanza territoriale ed espressione di sperimentate competenze ed esperienze tecniche, professionali ed amministrative&#8221;. Il primo atto della nuova Giunta regionale &#8220;sara&#8217; un profondo riordino organizzativo e della macchina amministrativa&#8221;. Lo annuncia il presidente Mario Oliverio. &#8220;Saranno azzerati &#8211; spiega &#8211; gli attuali incarichi di tutte le strutture speciali, si provvedera&#8217; ad operare un&#8217;ampia rotazione nella dirigenza dei dipartimenti e dei settori, a definire un riassetto degli Enti subregionali e a portare a compimento la definitiva liquidazione delle aziende soppresse&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ufficializzato il rinnovo della Giunta Oliverio con i suoi sei assessori<\/p>\n","protected":false},"author":22,"featured_media":91872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-91871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=91871"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/91871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/91872"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=91871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=91871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=91871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}