{"id":9209,"date":"2012-12-07T15:02:08","date_gmt":"2012-12-07T14:02:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9209"},"modified":"2023-01-17T13:42:23","modified_gmt":"2023-01-17T12:42:23","slug":"4046-sanita-golfo-pdl-ottima-notizia-su-nuovi-ospedali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4046-sanita-golfo-pdl-ottima-notizia-su-nuovi-ospedali\/","title":{"rendered":"Sanit\u00e0&#8217;: Golfo (PDL), ottima notizia su nuovi ospedali"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>REGGIO CALABRIA<\/b>&nbsp;&#8211; &#8220;Il riavvio dell&#8217;iter di realizzazione dei nuovi ospedali in Calabria appena annunciato dal Presidente Scopelliti e&#8217; una splendida notizia e<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">rappresenta una svolta per il sistema sanitario della nostra Regione. Oggi ha vinto la politica concreta che mette al primo posto i cittadini e i loro diritti&#8221;. Sono le dichiarazioni dell&#8217;Onorevole Lella Golfo, deputata Pdl &#8220;La firma da parte del Capo della Protezione Civile &#8211; continua Golfo &#8211; dell&#8217;ordinanza che restituisce alla Regione la competenza per la realizzazione dei nuovi quattro Ospedali di Vibo, della Sibaritide, della Piana di Gioia Tauro e di Catanzaro, e&#8217; il frutto delle pressanti iniziative e sollecitazioni rivolte al Governo e della determinazione di questa giunta a farsi carico della salute e del benessere dei propri i cittadini, assicurando standard che non possono e non devono essere inferiori a quelli del resto del Paese, perche&#8217; i cittadini calabresi devono poter trovare nel loro territorio le fondamentali risposte di cura. Dopo undici mesi di gravissimo stallo potra&#8217; finalmente ripartire quel percorso virtuoso finalizzato alla modernizzazione della sanita&#8217; calabrese che ha tanto impegnato questa giunta regionale e sono certa che il programma dei lavori ricomincera&#8217; con ancora maggior lena. I nuovi ospedali rappresentano un volano non solo per la sanita&#8217; calabrese ma per la crescita della Regione tutta aprendo nuovi e interessanti fronti d&#8217;occupazione e sviluppo dell&#8217;economia calabrese. In un momento economico cosi&#8217; delicato, che la nostra Regione possa riprendere in mano l&#8217;iniziativa e governare in prima persona e senza interferenze i processi di sviluppo e&#8217; una garanzia di crescita che apre importantissimi orizzonti&#8221;. (Fonte AGI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA&nbsp;&#8211; &#8220;Il riavvio dell&#8217;iter di realizzazione dei nuovi ospedali in Calabria appena annunciato dal Presidente Scopelliti e&#8217; una splendida notizia e<\/p>\n","protected":false},"author":22,"featured_media":9210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9209"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9210"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}