{"id":92233,"date":"2018-04-23T20:53:38","date_gmt":"2018-04-23T18:53:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-il-csv-presenta-bando-ambiente-di-fondazione-con-il-sud\/"},"modified":"2023-01-16T18:52:30","modified_gmt":"2023-01-16T17:52:30","slug":"213246-cosenza-il-csv-presenta-bando-ambiente-di-fondazione-con-il-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/213246-cosenza-il-csv-presenta-bando-ambiente-di-fondazione-con-il-sud\/","title":{"rendered":"Cosenza, il CSV presenta Bando Ambiente di Fondazione &#8216;Con il Sud&#8217;"},"content":{"rendered":"<h4>L&#8217;obiettivo \u00e8 quello di\u00a0presentare progetti per prevenzione e riduzione rischi ambientali.\u00a0<!--more--><\/h4>\n<p>COSENZA &#8211; La Fondazione &#8216;Con il Sud&#8217; promuove la quarta edizione del Bando Ambiente invitando le<br \/>\norganizzazioni del Terzo settore di Basilicata, Calabria, Campania, Puglia, Sardegna e Sicilia a<br \/>\npresentare progetti esemplari per la prevenzione e riduzione dei rischi ambientali all\u2019interno dei<br \/>\nParchi e delle Aree naturali protette meridionali. Il bando scade l\u20198 giugno e mette a disposizione,<br \/>\ncomplessivamente, 5 milioni di euro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-213251 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/04\/csv-cs-723x400.jpg\" alt=\"csv-cs\" width=\"723\" height=\"400\" title=\"\"><br \/>\nIl CSV (Centro Servizi per il Volontariato) presenter\u00e0 il bando\u00a0oggi\u00a0alle 16, nei locali della Cittadella del Volontariato di via degli Stadi, a Cosenza. Il bando sar\u00e0 illustrato da\u00a0<strong>Mariacarla Coscarella<\/strong> e da <strong>Carlo Lo Prete<\/strong>, rispettivamente direttore e referente della progettazione del CSV Cosenza. All\u2019incontro di Cosenza sar\u00e0 presente <strong>Giuseppe Luzzi<\/strong>, direttore dell\u2019Ente Parco Nazionale della Sila e il presidente di Volont\u00e0 Solidale \u2013 CSV Cosenza, <strong>Gianni\u00a0<\/strong><strong>Romeo.\u00a0<\/strong>Oltre alla presentazione del bando, obiettivo dell\u2019incontro, \u00e8 mettere insieme organizzazioni di volontariato, enti non profit e profit ed istituzioni locali per elaborare idee e proposte condivise capaci di generare valore sociale ed economico sul territorio. La Fondazione &#8216;Con il Sud&#8217;, infatti, punta molto su partenariati ampi e competenti, sulla mobilitazione del territorio e sulla sostenibilit\u00e0 dei progetti che saranno finanziati. Il CSV Cosenza si \u00e8 gi\u00e0 attivato per avviare un&#8217;interlocuzione con gli enti che possono essere coinvolti direttamente nei progetti, in particolare con i Parchi e i Gal. Si rafforza cos\u00ec il ruolo di facilitatore di rete del Centro servizi che, non solo vuole sostenere le associazioni nella progettazione, ma lavora al fine di creare e rafforzare relazioni tra enti pubblici e organizzazioni non profit con l&#8217;obiettivo di favorire lo sviluppo delle comunit\u00e0 locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;obiettivo \u00e8 quello di\u00a0presentare progetti per prevenzione e riduzione rischi ambientali.\u00a0<\/p>\n","protected":false},"author":20,"featured_media":92234,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-92233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=92233"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/92234"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=92233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=92233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=92233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}