{"id":92263,"date":"2018-04-24T09:00:58","date_gmt":"2018-04-24T07:00:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/donare-sangue-25-aprile-raccolta-san-marco-argentano\/"},"modified":"2023-01-16T18:52:31","modified_gmt":"2023-01-16T17:52:31","slug":"213319-donare-sangue-25-aprile-raccolta-san-marco-argentano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/213319-donare-sangue-25-aprile-raccolta-san-marco-argentano\/","title":{"rendered":"Donare il sangue il 25 aprile, raccolta a San Marco Argentano"},"content":{"rendered":"<h4>Domani, mercoled\u00ec 25 Aprile presso largo Fragomeni (fermata dei bus) in San Marco Argentano si terr\u00e0 la consueta raccolta sangue organizzata dalla Fidas della sezione normanna.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SAN MARCO ARGENTANO (CS) &#8211; L&#8217;iniziativa si terr\u00e0<strong> dalle ore 8:00 alle ore 12:00<\/strong> con l&#8217;obiettivo di &#8220;unire la raccolta sangue in occasione della festa del santo patrono che \u00e8 ormai una tradizione. La Fidas di San Marco Argentano sta diventando ormai punto di riferimento sul territorio, \u2013 dichiara Elia russo, vicepresidente della sezione- ma nonostante gli sforzi delle piccole realt\u00e0 locali l\u2019emergenza sangue \u00e8 sempre presente a livello regionale&#8221;.<\/p>\n<p>&#8220;La <strong>Calabria \u00e8 tra gli ultimi posti in Italia per produzione di unit\u00e0 di sangue,<\/strong> aggiungendo poi la disaffezione delle nuove generazioni al dono e al prolungamento dell\u2019et\u00e0 media della vita ci ritroviamo in situazioni davvero difficili. Non ultimo l\u2019appello dagli amici reggini, dove al Riuniti, tra i reparti di oncoematologia e cardiochirurgia la necessit\u00e0 di sangue \u00e8 quotidiana ed elevata. Dobbiamo avere questo scatto d\u2019orgoglio di dare il nostro contributo per questa nostra terra. <strong>L\u2019appello<\/strong> quindi a <strong>donare<\/strong> il sangue, possono donare tutti i maggiorenni, che pesano almeno <strong>50kg e che siano, ovviamente, in buona salute<\/strong>. I malati, stanno aspettando il tuo aiuto&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-213321 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/04\/WhatsApp-Image-2018-02-20-at-12.45.26.jpeg\" alt=\"WhatsApp Image 2018-02-20 at 12.45.26\" width=\"603\" height=\"1229\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, mercoled\u00ec 25 Aprile presso largo Fragomeni (fermata dei bus) in San Marco Argentano si terr\u00e0 la consueta raccolta sangue organizzata dalla Fidas della sezione normanna.<\/p>\n","protected":false},"author":22,"featured_media":92264,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[52],"tags":[],"class_list":["post-92263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=92263"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/92264"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=92263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=92263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=92263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}