{"id":92555,"date":"2018-05-03T08:08:55","date_gmt":"2018-05-03T06:08:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cadavere-trovato-nellandrone-di-un-palazzo-a-roma-e-un-ventunenne-di-rende\/"},"modified":"2023-01-16T18:52:51","modified_gmt":"2023-01-16T17:52:51","slug":"214569-cadavere-trovato-nellandrone-di-un-palazzo-a-roma-e-un-ventunenne-di-rende","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/214569-cadavere-trovato-nellandrone-di-un-palazzo-a-roma-e-un-ventunenne-di-rende\/","title":{"rendered":"Cadavere trovato nell&#8217;androne di un palazzo a Roma, \u00e8 un ventunenne di Rende"},"content":{"rendered":"<h4>Il ritrovamento del cadavere del giovane, luned\u00ec scorso nel quartiere di Tor Bella Monaca, in un palazzo in via Arnaldo Brandizzi alla periferia di Roma. Era sparito da Rende e i genitori ne avevano denunciato la scomparsa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; E&#8217; stato il pap\u00e0 a riconoscerlo e ad identificarlo. Il macabro ritrovamento del giovane in un vano scale, in via Arnaldo Brandizzi era avvenuto lo scorso 30 aprile, dai residenti del palazzo che hanno allertato i Carabinieri che indagano per risalire a quanto accaduto.<\/p>\n<p>Il giovane al momento del ritrovamento era vestito e non presentava evidenti segni di violenza, ma della caduta, che potrebbe essere anche accidentale. Ovviamente sar\u00e0 l&#8217;autopsia a stabilire con certezza le cause del decesso. Il giovane \u00e8 stato identificato dai genitori e si tratta di <strong>Andrea Muoio, 21enne domiciliato a Rende<\/strong>. E proprio i genitori ne avevano denunciato la scomparsa nei giorni scorsi dopo che il ragazzo si era allontanato da casa sabato senza fare pi\u00f9 ritorno. I carabinieri non escludono alcuna ipotesi anche quella che il giovane possa essersi tolto la vita, ma si attendono gli esiti dell&#8217;autopsia in quanto sul corpo sarebbero stati trovati &#8216;segni di precipitazione&#8217;.<\/p>\n<p>La salma del ragazzo, che era in cura presso il Centro Salute Mentale locale, \u00e8 stata riconosciuta dal pap\u00e0 nell&#8217;istituto di medicina legale del Policlinico Tor Vergata. Di lui si erano perse le tracce la sera del 28 aprile, quando si allontan\u00f2 dalla propria abitazione. Poi la denuncia di scomparsa da parte dei familiari ai carabinieri della Compagnia di Rende diretti dal capitano Sebastiano Maieli. Sul caso indagano i militari della Stazione Tor Bella Monaca ed i militari del Nucleo Investigativo della Compagnia di Frascati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ritrovamento del cadavere del giovane, luned\u00ec scorso nel quartiere di Tor Bella Monaca, in un palazzo in via Arnaldo Brandizzi alla periferia di Roma. Era sparito da Rende e i genitori ne avevano denunciato la scomparsa<\/p>\n","protected":false},"author":22,"featured_media":92556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,44],"tags":[],"class_list":["post-92555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=92555"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/92555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/92556"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=92555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=92555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=92555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}