{"id":93075,"date":"2018-05-16T04:59:25","date_gmt":"2018-05-16T02:59:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/reperti-archeologici-di-valore-nascosti-in-una-stalla-una-denuncia\/"},"modified":"2023-01-16T18:53:25","modified_gmt":"2023-01-16T17:53:25","slug":"216860-reperti-archeologici-di-valore-nascosti-in-una-stalla-una-denuncia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/216860-reperti-archeologici-di-valore-nascosti-in-una-stalla-una-denuncia\/","title":{"rendered":"Reperti archeologici di valore nascosti in una stalla, una denuncia"},"content":{"rendered":"<h4>I carabinieri hanno scoperto un vero e proprio tesoro archeologico in una stalla mentre erano alla ricerca di armi ed esplosivo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; I carabinieri della Compagnia di Cir\u00f2 Marina stavano compiendo una perquisizione finalizzata alla ricerca di armi e materiali esplodenti ed invece si sono imbattuti in quello che hanno definito un vero e proprio tesoro archeologico. I militari, in un armadio posto in una stalla, hanno rinvenuto numerosi reperti di pregevole fattura tra cui gioielli, monili in bronzo e vasellame decorato. I reperti sono stati sequestrati e il possessore \u00e8 stato denunciato in stato di libert\u00e0 alla Procura della Repubblica di Crotone.<\/p>\n<p>I militari del nucleo operativo radiomobile stavano eseguendo un controllo in un&#8217;azienda agricola di localita&#8217; Punta Alice della quale e&#8217; proprietario un <strong>commerciante del luogo, G.P., di 68 anni,<\/strong> ritenuto legato ad ambienti criminali della cittadina.<\/p>\n<p>In un armadio della stalla, pero&#8217;, invece di armi hanno trovato alcune scatole contenenti una quarantina di reperti archeologici. Si tratta di corredi funerari scavati, probabilmente, in tombe nella zona di Ciro&#8217;: vasellame e bronzi dell&#8217;eta&#8217; del ferro e ceramiche decorate di eta&#8217; ellenistica. Tra i reperti diverse fibule da parata, orecchini, bracciali, ma anche armi e collane per bambine.<\/p>\n<p>Come ha spiegato Maria Grazia Aisa &#8211; funzionaria della Soprintendenza archeologica responsabile dell&#8217;area di Ciro&#8217; Marina &#8211; &#8220;non si tratta di reperti di grande pregio o valore, ma comunque di oggetti che, proprio perche&#8217; spesso oggetto di mercato clandestino, non sono presenti in alcun museo della zona crotonese&#8221;. &#8220;Questo ritrovamento &#8211; ha detto il capitano Epifanio &#8211; fa capire l&#8217;interesse criminale sull&#8217;archeologia, chi li deteneva era raccoglitore di reperti che poi avrebbe messo in vendita. Il materiale archeologico non e&#8217; stato trovato in modo fortuito ma proviene da scavi diversi. Non meraviglia neppure la presenza di eventuali falsi come accade spesso nel mercato clandestino dell&#8217;arte&#8221;. Il proprietario dell&#8217;azienda agricola e&#8217; stato denunciato per riciclaggio ed appropriazione di beni dello Stato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri hanno scoperto un vero e proprio tesoro archeologico in una stalla mentre erano alla ricerca di armi ed esplosivo.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-93075","post","type-post","status-publish","format-standard","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93075"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93075\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}