{"id":93082,"date":"2018-05-16T04:50:16","date_gmt":"2018-05-16T02:50:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/216879\/"},"modified":"2023-01-16T18:53:26","modified_gmt":"2023-01-16T17:53:26","slug":"216879-216879","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/216879-216879\/","title":{"rendered":"Imprenditore condannato per omesso versamento dell&#8217;IVA, confisca da 360mila euro"},"content":{"rendered":"<h4>Il provvedimento di confisca \u00e8 stato eseguito dalla Guardia di Finanza. I beni per un valore di 360 mila euro sono stati confiscati ad un imprenditore condannato per omesso versamento dell&#8217;IVA<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; I Finanzieri del Comando Provinciale di Reggio Calabria hanno dato esecuzione ad un provvedimento di confisca per equivalente per un valore di oltre <strong>360 mila euro,<\/strong> emesso dalla Corte d\u2019Appello di Reggio Calabria nei confronti di un imprenditore condannato per il reato di omesso versamento di IVA. In esecuzione del decreto di confisca, le Fiamme Gialle hanno cautelato diversi conti correnti e beni mobili registrati nella disponibilit\u00e0 dell\u2019imprenditore condannato.<\/p>\n<p>Il provvedimento, eseguito dalla Compagnia di Palmi sotto il coordinamento della locale Procura della Repubblica, scaturisce da un\u2019attivit\u00e0 d\u2019indagine eseguita nei confronti di un\u2019impresa individuale operante nel settore del trasporto merci su strada, il cui titolare ha omesso di versare l\u2019Imposta sul Valore aggiunto, dovuta in base alla dichiarazione annuale relativa all\u2019anno d\u2019imposta<strong> 2010, per un importo di euro 361.579,00.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il provvedimento di confisca \u00e8 stato eseguito dalla Guardia di Finanza. I beni per un valore di 360 mila euro sono stati confiscati ad un imprenditore condannato per omesso versamento dell&#8217;IVA<\/p>\n","protected":false},"author":22,"featured_media":93083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-93082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93082"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93083"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}