{"id":93188,"date":"2018-05-19T06:10:09","date_gmt":"2018-05-19T04:10:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/meteo-cosenza-weekend-ancora-variabile-ma-prevale-il-sole-piu-caldo-da-lunedi\/"},"modified":"2023-01-16T18:53:32","modified_gmt":"2023-01-16T17:53:32","slug":"217314-meteo-cosenza-weekend-ancora-variabile-ma-prevale-il-sole-piu-caldo-da-lunedi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/217314-meteo-cosenza-weekend-ancora-variabile-ma-prevale-il-sole-piu-caldo-da-lunedi\/","title":{"rendered":"Meteo Cosenza, weekend ancora variabile ma prevale il sole. Pi\u00f9 caldo da luned\u00ec"},"content":{"rendered":"<h4><span style=\"color: #000000;\">Su tutto il Mediterraneo centrale persiste il clima di instabilit\u00e0 dovuto all&#8217;assenza dell&#8217;anticiclone delle Azzorre. Va decisamente meglio al sud e sulla Calabria, dove a parte un p\u00f2 di variabilit\u00e0 avremo giornate dominate dal sole. E dalla prossima settimana temperature in aumento<\/span>\u00a0<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;<span style=\"color: #000000;\"> La scorsa settimana avevamo parlato di una <strong>primavera abbastanza capricciosa, fresca ma soprattutto\u00a0instabile<\/strong> con frequenti rovesci, acquazzoni e persino grandinate&#8230; da nord a sud. A distanza di 7 giorni le cose sono cambiate di poco. <strong>L&#8217;assenza di un robusto campo d&#8217;alta pressione<\/strong> come l&#8217;<strong>anticiclone delle Azzorre<\/strong> (figura essenziale per garantire una primavera\u00a0stabile,\u00a0temperata e soleggiata per diversi giorni) o quello decisamente pi\u00f9 caldo <strong>subtropicale<\/strong>, fa si che il bacino del Mediterraneo Centrale sia soggetto a<strong> frequenti incursioni di aria fresca atlantica\u00a0in quota\u00a0<\/strong>che non fanno altro che alimentare l&#8217;instabilit\u00e0 preesistente, oppure come avvenuto ieri, la risalita di un <strong>fronte perturbato dal nord Africa<\/strong>\u00a0che ha portato piogge e cieli grigi su\u00a0tutta la Calabria fino a sera. <\/span><\/p>\n<p><span style=\"color: #000000;\">Nel fine settimana le cosa andranno comunque decisamente meglio, con <strong>il sole che prevarr\u00e0 nettamente sulle\u00a0 nuvole<\/strong>\u00a0in un contesto climatico che resta comunque ancora lontano dai connotati tipici della primavera a cui negli ultimi anni eravamo abituati. La buona notizia, \u00e8 che a<strong> partire dall&#8217;inizio della prossima settimana non solo le temperature inizieranno a salire<\/strong> di\u00a0alcuni gradi, in pi\u00f9 la Calabria rester\u00e0 abbastanza ai margini dell&#8217;instabilit\u00e0 che continuer\u00e0 a colpir\u00e0 le aree alpine\u00a0del nord\u00a0 Italia e\u00a0le zone dell&#8217;appennino\u00a0centrale anche se non sono esclusi anche qui da noi rovesci e acquazzoni nelle ore pi\u00f9 calde. Insomma, p<strong>er avere un clima decisamente pi\u00f9 stabile bisogner\u00e0 attendere almeno la fine di maggio<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su tutto il Mediterraneo centrale persiste il clima di instabilit\u00e0 dovuto all&#8217;assenza dell&#8217;anticiclone delle Azzorre. Va decisamente meglio al sud e sulla Calabria, dove a parte un p\u00f2 di variabilit\u00e0 avremo giornate dominate dal sole. E dalla prossima settimana temperature in aumento\u00a0<\/p>\n","protected":false},"author":22,"featured_media":93189,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,221],"tags":[],"class_list":["post-93188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-previsioni-meteo-per-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93188"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93189"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}