{"id":93225,"date":"2018-05-19T03:50:22","date_gmt":"2018-05-19T01:50:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/uccise-cugino-motivi-gelosia-arrestato-19enne\/"},"modified":"2023-01-16T18:53:35","modified_gmt":"2023-01-16T17:53:35","slug":"217461-uccise-cugino-motivi-gelosia-arrestato-19enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/217461-uccise-cugino-motivi-gelosia-arrestato-19enne\/","title":{"rendered":"Uccise il cugino per motivi di gelosia, arrestato 19enne"},"content":{"rendered":"<h4>Il movente dell&#8217;omicidio di Bruno Lazzaro, 27 anni, sarebbe di natura passionale. Il cugino lo avrebbe accoltellato a morte per una ragazza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>VIBO VALENTIA &#8211; L&#8217;omicidio \u00e8 stato compiuto a Sorianello il 4 marzo scorso. La vittima, Bruno Lazzaro di 27 anni venne colpita a morte con un fendente all&#8217;addome. Un omicidio per il quale il pm della Procura di Vibo Valentia, Olimpia Anzalone, ha ottenuto dal gip un&#8217;ordinanza di custodia cautelare in carcere nei confronti di <strong>Gaetano Muller, 19 anni, cugino della vittima.<\/strong><\/p>\n<p>Particolarmente utili alle indagini si sono rivelate le conversazioni estrapolate dal cellulare della vittima, ritrovato sul luogo\u00a0dove \u00e8 stata soccorsa.\u00a0Conversazioni su Whatsapp dalle quale \u00e8 stato appurato come, pochi minuti prima dell&#8217;agguato, Bruno Lazzaro era stato messo in guardia dalla ragazza, ex fidanzata di Muller, che temeva per la sua incolumit\u00e0 in quanto Muller, era venuto a conoscenza della relazione fra i due.<\/p>\n<p>Il 19enne aveva <strong>dato appuntamento in auto al cugino<\/strong> per portarlo in localit\u00e0<strong> Savini di Sorianello<\/strong> dove \u00e8 iniziata una furiosa lite, culminata con l&#8217;accoltellamento. Poi lo stesso Muller ha chiamato i carabinieri dicendo che il cugino si era ferito con un ferro. Nonostante gli immediati soccorsi, il giovane e&#8217; deceduto due ore dopo in ospedale a Vibo Valentia. La gelosia dunque, \u00e8 il movente dell&#8217;omicidio di Bruno Lazzaro, per il quale ieri i carabinieri hanno arrestato il cugino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il movente dell&#8217;omicidio di Bruno Lazzaro, 27 anni, sarebbe di natura passionale. Il cugino lo avrebbe accoltellato a morte per una ragazza<\/p>\n","protected":false},"author":22,"featured_media":93226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-93225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93225"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93226"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}