{"id":93263,"date":"2018-05-20T15:16:08","date_gmt":"2018-05-20T13:16:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sclerosi-multipla-presentato-il-pdta-una-vittoria-per-il-paziente\/"},"modified":"2023-01-16T18:53:38","modified_gmt":"2023-01-16T17:53:38","slug":"217668-sclerosi-multipla-presentato-il-pdta-una-vittoria-per-il-paziente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/217668-sclerosi-multipla-presentato-il-pdta-una-vittoria-per-il-paziente\/","title":{"rendered":"Sclerosi multipla, presentato il Pdta: una vittoria per il paziente"},"content":{"rendered":"<h4>La regione Calabria ha definito il percorso assistenziale per la sclerosi multipla che garantisce la presa in carico totale, dalla diagnosi, e per tutto il percorso, del paziente<\/h4>\n<p><!--more--><br \/>\nCATANZARO &#8211;\u00a0Alla Cittadella della Regione Calabria, un passo importantissimo \u00e8 stato fatto per i pazienti affetti da sclerosi multipla: \u00e8 stato presentato il PDTA (percorso diagnostico terapeutico assistenziale), nella Sclerosi Multipla. Il convegno presentato venerd\u00ec scorso ha avuto come tema\u00a0\u201cil percorso diagnostico-terapeutico assistenziale in Calabria\u201d, presentato e moderato dai dirigenti di settore del Dipartimento regionale tutela della salute e politiche sanitarie Liliana Rizzo e Sergio Petrillo. L&#8217;incontro nasce anche dall\u2019esigenza di prendere in esame e definire un percorso diagnostico terapeutico e assistenziale per le persone con sclerosi multipla che metta concretamente il paziente al centro e che \u00e8 strettamente collegata all\u2019evidente impatto sociale di questa malattia e alle difficolt\u00e0 crescente che l\u2019offerta attuale da parte del Servizio sanitario nazionale definisci in termini di oneri assistenziali a carico delle famiglie nelle quali \u00e8 presente una persona con malattia cronica.<\/p>\n<p>In tal senso, la Regione, con il Decreto del commissario ad acta n. 140 del 19 ottobre 2017, ha definito il percorso assistenziale per la sclerosi multipla che garantisce, secondo un progetto personalizzato integrato, la presa in carico del paziente, assicura la diagnosi tempestiva di malattia, il monitoraggio clinico strumentale e il trattamento.Interverranno all\u2019iniziativa la presidente nazionale dell\u2019Aism Angela Martino e il direttore affari generali Paolo Bandiera, il responsabile del Centro sclerosi multipla dell\u2019Asp di Cosenza Roberto Bruno Bossio, Paola Valentino dell\u2019unit\u00e0 operativa neurologia dell\u2019Azienda ospedaliera universitaria Mater Domini, Brunella Piro del servizio farmaceutico dell\u2019Asp di Cosenza, il coordinatore regionale medico legale dell\u2019Inps Eugenio Cupelli,\u00a0 il direttore dell\u2019unit\u00e0 operativa medicina fisica e riabilitativa dell\u2019Aou Mater Domini Maurizio Iocco, il coordinatore regionale Aism Calabria Salvatore Lico, il dirigente medico legale dell\u2019Inps regionale Francesco Naso.\u00a0#aismcosenza #Smuoviti #50anniAISM #sclerosimultipla #pdtaism<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La regione Calabria ha definito il percorso assistenziale per la sclerosi multipla che garantisce la presa in carico totale, dalla diagnosi, e per tutto il percorso, del paziente<\/p>\n","protected":false},"author":37,"featured_media":93264,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,52],"tags":[],"class_list":["post-93263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93263"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93264"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}