{"id":93710,"date":"2018-05-31T07:30:32","date_gmt":"2018-05-31T05:30:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/minorenne-scappa-da-una-comunita-rintracciata-dalla-polfer\/"},"modified":"2023-01-16T18:54:09","modified_gmt":"2023-01-16T17:54:09","slug":"219726-minorenne-scappa-da-una-comunita-rintracciata-dalla-polfer","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/219726-minorenne-scappa-da-una-comunita-rintracciata-dalla-polfer\/","title":{"rendered":"Minorenne scappa da una comunit\u00e0, rintracciata dalla Polfer"},"content":{"rendered":"<h4>La ragazzina di origine siciliana si era allontanata arbitrariamente da una comunit\u00e0 di Catania. E&#8217; stata rintracciata in Calabria<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Nei giorni scorsi, nell\u2019ambito delle direttive ministeriali, volte all\u2019intensificazione dei servizi di vigilanza e controllo all\u2019interno delle stazioni e sui convogli ferroviari, per garantire la sicurezza dei viaggiatori soprattutto nell\u2019approssimarsi del periodo estivo, personale della Polizia di Stato in servizio presso il locale Compartimento di Polizia Ferroviaria ha rintracciato una<strong> giovane di 15 anni,<\/strong> allontanatasi volontariamente da una comunit\u00e0 di Catania.<\/p>\n<p>La minore, originaria di Lentini (SR), \u00e8 stata notata dal personale della Polfer sul marciapiede del primo binario della stazione ferroviaria di Reggio Calabria, in evidente stato confusionale e condotta negli uffici del Posto di Polizia Ferroviaria per le prime operazioni di assistenza e di controllo. Gli accertamenti svolti hanno consentito di accertare che per la minore, arbitrariamente allontanatasi dalla comunit\u00e0 a cui era stata affidata per raggiungere alcuni conoscenti in questo centro, vi era in atto un piano di ricerche e rintraccio. La ragazzina nel pomeriggio \u00e8 stata affidata alla<strong> madre giunta dalla provincia di Catania. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ragazzina di origine siciliana si era allontanata arbitrariamente da una comunit\u00e0 di Catania. E&#8217; stata rintracciata in Calabria<\/p>\n","protected":false},"author":22,"featured_media":93711,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-93710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93710"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93711"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}