{"id":9375,"date":"2012-12-11T09:48:10","date_gmt":"2012-12-11T08:48:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9375"},"modified":"2023-01-17T13:42:32","modified_gmt":"2023-01-17T12:42:32","slug":"4132-surdo-incidente-stradale-muore-48enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4132-surdo-incidente-stradale-muore-48enne\/","title":{"rendered":"Surdo, sbanda con la moto: muore 48enne"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>RENDE &#8211;<\/strong> Strada killer. Ancora una volta, l&#8217;asfalto si macchia di sangue. E&#8217; quello di Vincenzo Magnelli, classe &#8217;64, nativo e residente a Cosenza, rimasto vittima di un pauroso incidente stradale autonomo a Surdo. I rilievi dell&#8217;incidente sono stati effettuati dagli agenti della polizia municipale.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Il 48enne, era in sella alla sua moto, quando, forse per l&#8217;alta velocit\u00e0 o per una manovra sbagliata, ha perso il controllo della sua due ruote, finendo per schiantarsi. L&#8217;impatto, lo dicono anche i segni di frenata lasciati sull&#8217;asfalto, \u00e8 stato devastante. Leferite riportate dal centauro sono state tante: fratture estese su tutto il corpo, con evidente trauma cranico-facciale e numerose escoriazioni. Immediatamente soccorso dall&#8217;equipe medica, infermieristica e paramedica del 118, \u00e8 stato trasportato all&#8217;ospedale dell&#8217;Annunziata, dov&#8217;\u00e8 deceduto. Le tante, trope ferite e le altrettante fratture interne non gli hanno lasciatgo scampo. Prima di spirare, i medici gli hanno praticato una prolungata attivit\u00e0 di soccorso rianimatorio e cardicircolatorio che, per\u00f2, non ne ha impedito il decesso. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Strada killer. Ancora una volta, l&#8217;asfalto si macchia di sangue. E&#8217; quello di Vincenzo Magnelli, classe &#8217;64, nativo e residente a Cosenza, rimasto vittima di un pauroso incidente stradale autonomo a Surdo. I rilievi dell&#8217;incidente sono stati effettuati dagli agenti della polizia municipale.<\/p>\n","protected":false},"author":22,"featured_media":9376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9375"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9376"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}