{"id":93943,"date":"2018-06-05T08:39:31","date_gmt":"2018-06-05T06:39:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-corteo-per-il-diritto-alla-salute-stop-commissariamento-foto\/"},"modified":"2023-01-16T18:54:25","modified_gmt":"2023-01-16T17:54:25","slug":"220654-cosenza-corteo-per-il-diritto-alla-salute-stop-commissariamento-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/220654-cosenza-corteo-per-il-diritto-alla-salute-stop-commissariamento-foto\/","title":{"rendered":"Cosenza, corteo per il diritto alla Salute: &#8220;stop commissariamento&#8221; &#8211; FOTO"},"content":{"rendered":"<h4>E&#8217; partita da piazza Zumbini questa mattina la mobilitazione provinciale promossa dalla Cgil di Cosenza e dalla sezione Pollino Sibaritide tirreno che arriver\u00e0 a Via Alimena davanti alla sede cosentina dell&#8217;Asp. <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Da un periodo di commissariamento che si trascina da anni ad un diritto, quello alla salute, fondamentale per l&#8217;interesse della collettivit\u00e0 che \u00e8 venuto meno per i cittadini cosentini e calabresi.<strong> Giuseppe Guido, segretario comprensoriale<\/strong> della <strong>Cgil Pollino Sibaritide Tirreno, e Umberto Calabrone,<\/strong> segretario generale della <strong>Cgil Cosenza,<\/strong> conducono il corteo promosso per questa mattina a Cosenza, per alzare la voce sulla situazione del servizio sanitario della nostra Provincia che versa in un momento negativo mai registrato, sia in termini di organizzazione che di qualit\u00e0 dei servizi offerti ai nostri concittadini, ai quali non sono garantiti i bisogni primari di salute, contravvenendo proprio al dettato costituzionale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-220660 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/corteo-cgil-cosenza-sanita-07.jpg\" alt=\"\" width=\"409\" height=\"204\" title=\"\">Il segretario della Cgil di Cosenza, Umberto <strong>Calabrone<\/strong> \u00e8 <strong>categorico<\/strong>:<em> &#8220;Abbiamo un diritto negato della Costituzione nel nostro territorio che \u00e8 quello alla salute. non riteniamo pi\u00f9 opportuno che in Calabria e soprattutto in provincia di Cosenza, si continui con un commissariamento che non ha prodotto gli effetti che si speravano e chiediamo che si torni al pi\u00f9 presto possibile ad una gestione normale e ordinaria della sanit\u00e0 in Calabria che miri alla tutela della salute dei cittadini e non al risparmio economico perch\u00e8 sulla sanit\u00e0 non si risparmia&#8221;.<\/em><\/p>\n<p><em>&#8220;I cittadini stanno pagando sia alivello economico che di efficienza del servizio sanitario che come possiamo sentire quotidianamente vive di problemi. Molti cittadini sono costretti ad andare fuori non solo per le visite specialistiche ma anche per visite ordinarie perch\u00e8 ormai \u00e8 venuta meno la fiducia nel sistema sanitario calabrese e cosentino in particolare. Riteniamo &#8211;<\/em> spiega <strong>Calabrone<\/strong> <em>&#8211; che si debba cambiare passo immediatamente sia per quanto riguarda la politica che per quanto riguarda le istituzioni ad iniziare dall&#8217;ASP&#8221;.<\/em><\/p>\n<p>E&#8217; tempo di trovare soluzioni su problemi che sono di fondamentale importanza sia per i servizi di cura e di assistenza ai cittadini bisognosi, sia per le lavoratrici ed i lavoratori della sanit\u00e0. Basta con le scelte spesso improvvisate, a volte anche clientelari che producono solo ricadute negative sul servizio pubblico che continua ad essere depotenziato. La situazione della sanit\u00e0 in provincia di Cosenza \u00e8 allo sbando con gravi ripercussioni. Si assiste ad una sanit\u00e0 privata, che si sostituisce a quella pubblica che invece arranca, e costringe i cittadini a recarsi fuori regione anche per una visita ordinaria. E la Cgil chiede con forza, stamattina, che il <strong>settore<\/strong> della sanit\u00e0 regionale<strong> &#8220;ritorni alla gestione ordinaria&#8221;.<\/strong> La manifestazione sar\u00e0 conclusa dalla Segretaria Generale della Funzione Pubblica CGIL, Serena Sorrentino.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; partita da piazza Zumbini questa mattina la mobilitazione provinciale promossa dalla Cgil di Cosenza e dalla sezione Pollino Sibaritide tirreno che arriver\u00e0 a Via Alimena davanti alla sede cosentina dell&#8217;Asp.<\/p>\n","protected":false},"author":22,"featured_media":93944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-93943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93943"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93944"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}