{"id":93947,"date":"2018-06-06T19:50:01","date_gmt":"2018-06-06T17:50:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-beffa-atroce-i-rossoblu-dominano-ma-cadono-al-90-ora-serve-il-marulla\/"},"modified":"2023-01-16T18:54:25","modified_gmt":"2023-01-16T17:54:25","slug":"220664-cosenza-beffa-atroce-i-rossoblu-dominano-ma-cadono-al-90-ora-serve-il-marulla","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/220664-cosenza-beffa-atroce-i-rossoblu-dominano-ma-cadono-al-90-ora-serve-il-marulla\/","title":{"rendered":"Cosenza, beffa atroce. I rossoblu dominano ma cadono al 90&#8242;. Ora serve la spinta del Marulla"},"content":{"rendered":"<h4><span style=\"color: #000000;\">Sconfitta amarissima per i rossoblu che perdono 1 a 0 la semifinale di andata contro il\u00a0S\u00fcdtirol dopo aver dominato il match per lunghi tratti e sfiorato il vantaggio sopratutto nella ripresa. Decide un goal di Cia proprio allo scadere del tempo. Ora servir\u00e0 la spinta del Marulla per ribaltare la gara<\/span><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #000000;\">BOLZANO &#8211;<\/span>\u00a0<span style=\"color: #000000;\">Va al\u00a0S\u00fcdtirol la sfida di andata della semifinale playoff disputata allo stadio Druso di Bolzano. Vincono i padroni di casa che si impongono per 1 a 0 ma\u00a0<\/span><span style=\"color: #000000;\">il Cosenza si morde le mani per una <strong>sconfitta amarissima e assolutamente immeritata,<\/strong>\u00a0che per alcune\u00a0analogie ricorda la sfida dello scorso anno contro il Pordenone persa 1 a 0 proprio con una rete beffa subita al 90&#8242;. I rossoblu, alla settima gara in poco meno di 30 giorni, spinti da oltre<b>\u00a0300 fantastici tifosi arrivati da tutta Italia,<\/b>\u00a0giocano un&#8217;ottima gara<strong> dominando per lunghi tratti, sopratutto nel secondo tempo<\/strong> quando sono arrivate anche <strong>le occasioni da rete con Corsi e soprattutto Pascali<\/strong>, sul quale solo un grande intervento di Offredi nega la gioia della rete. <\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Il S\u00fcdtirol invece si limita ad una partita prettamente di contenimento<\/strong>\u00a0almeno fino all&#8217;80&#8217; quando inevitabilmente il Cosenza cala fisicamente e\u00a0deve arrendersi al <strong>guizzo di Cia, che sfrutta un rimpallo in area per beffare Saracco proprio al 90&#8242; con un piattone sotto porta<\/strong>. Ora ai rossoblu servir\u00e0 la spinta dei 20.000 Marulla per ribaltare la gara che si giocher\u00e0 senza Dermaku squalificato e con Camigliano uscito dopo 1&#8242; minuto per un guaio fisico. Ma guai ad abbattersi, tutto \u00e8 ancora possibile.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-221203\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/Sudtirol-Cosenza-tifosi.jpg\" alt=\"\" width=\"584\" height=\"389\" title=\"\"><\/p>\n<h4>L&#8217;amarezza di mister Braglia &#8220;preso un goal ingenuo ma nulla \u00e8 compromesso. Domenica giocheremo alla morte&#8221;<\/h4>\n<p>Il tecnico del Cosenza si presenta in sala stampa con il volto scuro per una sconfitta che fa male per come maturata &#8220;<em>Abbiamo preso un goal al 90&#8242; ma sull&#8217;azione siamo stati ingenui a concedere loro quella particolare situazione: Il calcio per\u00f2 \u00e8 questo&#8221;<\/em>. Per lunghi tratti si \u00e8 visto un ottimo Cosenza che avrebbe meritato il goal ed invece \u00e8 arrivata una sconfitta. &#8220;<em>E&#8217; difficile commentare questa partita perch\u00e9 loro ci hanno aspettato giocando una gara di contenimento, cosa che faranno anche a Cosenza a maggior ragione avendo anche il gol di vantaggio. Per\u00f2 nulla \u00e8 compromesso, non dobbiamo demoralizzarci ma rimboccarci le maniche. Con Dermaku squalificato domenica potrebbe non esserci Camigliano perch\u00e9 ho paura che si sia fatto male<\/em>. Domenica ci sar\u00e0 un Marulla gremito fino all&#8217;inverosimile &#8220;<em>daremo tutto per ribaltare il risultato giocando fino alla morte<\/em>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/507\" rel=\"attachment wp-att-49952\"><br \/>\n<\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-220683 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/Logo_Fussball_Club_S\u00fcdtirol.png\" alt=\"\" width=\"167\" height=\"168\" title=\"\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/quicosenza.it\/news\/859\" rel=\"attachment wp-att-49958\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38351 alignnone\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/logo-Cosenza Calcio.png\" alt=\"logo-Cosenza Calcio\" width=\"130\" height=\"169\" title=\"\"><\/a><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 18pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 S\u00fcdtirol\u00a0 \u00a0 &#8211;\u00a0 \u00a0<\/span><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0Cosenza<\/span><\/span><\/span><\/strong><\/span><\/p>\n<div id=\"blink\" style=\"text-align: center;\"><span style=\"color: #ff0000; font-size: 20pt;\"><a target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">1\u00a0&#8211;\u00a00<\/span><\/a><\/span><\/div>\n<p><span style=\"color: #000000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Marcatori<\/strong>: 91&#8242; Cia<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.badando\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\">SECONDO TEMPO<\/span><\/strong><\/span><\/p>\n<p><b><strong>94&#8242; &#8211; FINALE DI GARA<\/strong><\/b><\/p>\n<p><b><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49956\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Goal2.gif\" alt=\"Goal2\" width=\"122\" height=\"61\" title=\"\">90\u2032\u00a0\u2013\u00a0GOAL S\u00dcDTIROL CON CIA. <\/strong><\/b>Mischia paurosa in area del Cosenza, la sfera finisce sui piedi di Cia che da due passi batte Saracco<b><br \/>\n90&#8242; &#8211; Concessi 3&#8242; muniti\u00a0di recupero<\/b><br \/>\n<b><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">86\u2032-<\/b> Sostituzione nel S\u00fcdtirol. Fuori\u00a0 Frascatore e dentro Zanchi<strong><b><br \/>\n83&#8242; &#8211; <\/b><\/strong>Proteste dei padroni di casa per un presunto atterramento in area di Costantino ad opera di Pascali. Il signor\u00a0 Dionisi di L&#8217;Aquila non fa una piega<strong><b><br \/>\n80&#8242; &#8211; <\/b><\/strong>Ultimi 10 minuti di gara con il Cosenza che inizia ad accusare un pizzico di fatica<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">74\u2032- <\/b><\/strong>Doppio cambio nei padroni di casa. Fuori Smith e Candellone. Dentro Bertoni e Flores<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a073\u2032 &#8211;\u00a0<\/b><\/strong>Cartellino giallo pesante per Dermaku. Il difensore era in diffida e salter\u00e0 la semifinale di ritorno<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">72\u2032-\u00a0<\/b><\/strong>Doppio cambio nel Cosenza, Fuori Tutino e Mungo, dentro Perez e Calamai<strong><b><br \/>\n71&#8242; &#8211; <\/b><\/strong>Occasionissima per i rossoblu. Corner dalla sinistra, incornata di Pascali e miracolo di Offredi\u00a0<strong><b><br \/>\n70&#8242; &#8211; <\/b><\/strong>Gran tiro di Corsi dalla distanza, Offredi si allunga e devia in angolo<strong><b><br \/>\n68&#8242; &#8211; <\/b><\/strong>Copione tattico della gara che non sembra essere cambiato nemmeno nella ripresa. Cosenza a fare la gara,\u00a0S\u00fcdtirol tutta raccolta pronta a giocare di rimessa\u00a0<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">62\u2032-<\/b><\/strong>\u00a0Prima sostituzione nel S\u00fcdtirol. Fuori Fink e dentro Cia<br \/>\n<strong><b>60&#8242; &#8211; <\/b><\/strong>Occasione goal per il Cosenza. Da un corner battuto dalla destra, il pallone rimane in area e viene colpito con un gran collo piede da Palmiero. Sfera che esce di un nulla<strong><b><br \/>\n55&#8242; &#8211; <\/b><\/strong>Grande accelerazione di\u00a0Broh sulla sinistra, pallone al centro per Costatino che controlla e calcia in diagonale. Saracco si distende e blocca la sfera<strong><b><br \/>\n52&#8242; &#8211;\u00a0<\/b><\/strong>Sulla susseguente punizione pallone in area di Palmiero per l&#8217;inserimento di Mungo che va in &#8220;estirata&#8221; ma non riesce a colpire la sfera che si perde sul fondo<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a051\u2032 &#8211;\u00a0<\/b><\/strong>Cartellino giallo per Sgarbi entrato duro su Tutino<strong><b><br \/>\n45&#8242; &#8211;\u00a0<\/b><\/strong>Riparte la contesa allo stadio Druso illuminato ora dalle luci artificiali. Non ci sono state cambi nell&#8217;intervallo<\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\">PRIMO TEMPO<\/span><\/strong><\/span><\/p>\n<p><strong><b>48&#8242; &#8211;\u00a0FINALE DI PRIMO TEMPO<br \/>\n45&#8242; &#8211;\u00a0<\/b><\/strong>Concessi 3&#8242; minuti di recupero<strong><b><br \/>\n45&#8242; &#8211;\u00a0<\/b><\/strong>Cross di Vinetot per la testa di Candellone. Pallone largo alla sinistra di Perina<strong><b><br \/>\n37&#8242; &#8211;\u00a0<\/b><\/strong>Occasione per Pascali che impatta di testa su corner battuto dalla sinistra, ma il pallone viene smorzato da un difensore e termine alto<strong><b><br \/>\n35&#8242; &#8211;\u00a0<\/b><\/strong>Il\u00a0S\u00fcdtirol per ora si limita a controllare, rimanendo ben coperto in difesa ma soffre molto le incursioni di Corsi a destra ben supportato da Bruccini<br \/>\n<strong><b>28&#8242; &#8211;\u00a0<\/b><\/strong>Bene il Cosenza che pian piano ha preso possesso del centrocampo ma non deve assolutamente distrarsi perch\u00e9 i padroni di casa cono pericolosissimi nelle ripartenze<strong><b><br \/>\n19&#8242; &#8211;\u00a0<\/b><\/strong>Gran pallone di Mungo in area per l&#8217;inserimento di Bruccini che per un soffio non arriva a colpire la sfera<strong><b><br \/>\n18&#8242; &#8211;\u00a0<\/b><\/strong>Accelerazione di D&#8217;Orazio che parte da centrocampo e arriva fino la limite dell&#8217;area. Il suo diagonale per\u00f2 \u00e8 largo e il pallone finisce fuori<strong><b><br \/>\n17&#8242; &#8211;\u00a0<\/b><\/strong>Replicano gli altoatesini con una conclusione da fuori area di Costantino. Tiro ciabattato che si perde sul fondo<strong><b><br \/>\n15&#8242; &#8211;\u00a0<\/b><\/strong>Corsi ci prova con un gran destro dalla distanza, pallone deviato che finisce tra le braccia del portiere Offredi<strong><b><br \/>\n13&#8242; &#8211;<\/b><\/strong>\u00a0Punizione velenosa di\u00a0Fink in area per l&#8217;accorrente Costantino che appostato sul secondo palo non arriva sulla sfera che si perde sul fondo<strong><b><br \/>\n7&#8242; &#8211;\u00a0<\/b><\/strong>Manovra il Cosenza in attacco. Corsi chiude l&#8217;azione con un pallone appoggiato per l&#8217;accorrente Bruccini che calcia dalla distanza. Pallone altissimo<strong><b><br \/>\n5&#8242; &#8211;\u00a0<\/b><\/strong>Cross di D&#8217;Orazio per la testa di Tutino che va in elevazione ma non riesce a impattare il pallone da ottima posizione<strong><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">3\u2032-\u00a0<\/b><\/strong>Camigliano di accascia al suolo dopo un contrasto di gioco. Il difensore del Cosenza non riesce a proseguire e deve abbandonare il terreno di gioco. Al suo posto Pascali<strong><br \/>\n1&#8242; &#8211;\u00a0<\/strong>I padroni di casa battono il calcio d&#8217;avvio. E&#8217; iniziata la semifinale di andata Tra\u00a0S\u00fcdtirol\u00a0 e Cosenza. I rossoblu attaccheranno da destra verso sinistra<strong><br \/>\n<\/strong>Ecco S\u00fcdtirol e Cosenza fare il loro ingresso sul terreno del Drusi davanti a poco pi\u00f9 di 3.000 spettatori. I ragazzi di Braglia in campo con la classica divisa rossoblu. Padroni di casa in completo bianco<\/p>\n<p>Terreno di gioco del Druso abbondantemente annaffiato prima della gara. Fantastici i tifosi del Cosenza arrivati con ogni mezzo dopo un viaggio infinito di 1.200 km.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>FC S\u00dcDTIROL (3-5-2)<\/strong>:\u00a0 Offredi; Erlic, Sgarbi, Vinetot; Tait, Smith (74&#8242; Bertoni), Broh, Fink (62&#8242; Cia), Frascatore (86&#8242; Zanchi); Costantino, Candellone (74&#8242; Flores)<br \/>\n<strong>Panchina:<\/strong> D&#8217;Egidio, Weiss, Bertoni, Cia, Zanchi, Baldan, Boccalari, Oneto, Gatto, Heatley Flores, Berardi, Roma<br \/>\n<strong>Allenatore:\u00a0<\/strong>Paolo Zanetti<\/p>\n<p><strong>COSENZA CALCIO (3-5-2):<\/strong>\u00a0Saracco, Corsi, Idda, Palmiero, Mungo (72&#8242; Calamai), Okereke, Bruccini, Tutino (72&#8242; Perez), D\u2019Orazio, Dermaku, Camigliano (3&#8242; Pascali)<br \/>\n<strong>Panchina:<\/strong>\u00a0Zommers, Ramos, Perez, Pasqualoni, Boniotti, Trovato, Calamai, Loviso, Pascali, Braglia<br \/>\n<strong>Allenatore:\u00a0<\/strong>Piero Braglia<\/p>\n<p><strong>Arbitro:<\/strong>\u00a0Signor Federico Dionisi di L&#8217;Aquila<\/p>\n<p><strong>Assistenti:\u00a0<\/strong>Signor\u00a0Lorenzo Abagnara di Nocera Inferiore e signor\u00a0Pierluigi Della Vecchia di Avellino<\/p>\n<p><strong>Angoli: <\/strong>1-8<\/p>\n<p><strong>Ammoniti: <\/strong>Sgarbi (S), Dermaku (C)<\/p>\n<p><strong>Espulsi:<\/strong><\/p>\n<p><strong>Recupero: <\/strong>3&#8242; &#8211; 3&#8242;<\/p>\n<p><strong>Note: <\/strong>Serata estiva a Bolzano con temperatura sui 26 gradi. Stadio Druso praticamente esaurito. Presenti poco pi\u00f9 di 3.000 spettatori, 300 dei quali arrivati da Cosenza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sconfitta amarissima per i rossoblu che perdono 1 a 0 la semifinale di andata contro il\u00a0S\u00fcdtirol dopo aver dominato il match per lunghi tratti e sfiorato il vantaggio sopratutto nella ripresa. Decide un goal di Cia proprio allo scadere del tempo. Ora servir\u00e0 la spinta del Marulla per ribaltare la gara<\/p>\n","protected":false},"author":23,"featured_media":93948,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-93947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=93947"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/93947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/93948"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=93947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=93947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=93947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}