{"id":94279,"date":"2018-06-12T11:37:00","date_gmt":"2018-06-12T09:37:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/micronarrativa-fotografia-e-teatro-nel-cuore-della-sicilia\/"},"modified":"2023-01-16T18:54:47","modified_gmt":"2023-01-16T17:54:47","slug":"222192-micronarrativa-fotografia-e-teatro-nel-cuore-della-sicilia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/222192-micronarrativa-fotografia-e-teatro-nel-cuore-della-sicilia\/","title":{"rendered":"Micronarrativa, fotografia e teatro nel cuore della Sicilia"},"content":{"rendered":"<h4>Il concorso nazionale \u00e8 aperto a tutti e intende portare alla ribalta il nuovo modo di scrivere e comunicare creato dall&#8217;influenza dei social network<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LEONFORTE (EN) &#8211; In una fase di estrema crisi dei concorsi letterari, c&#8217;\u00e8 chi ancora resiste. Rivisitando i classici con lo sguardo alle nuove forme di comunicazione. Il Comune di Leonforte, Assessorato alla Cultura, Sport, Spettacolo e Turismo indice la trentasettesima edizione del \u201cPremio Citt\u00e0 di Leonforte\u201d. Il concorso \u00e8 rivolto a tutti, a partire dal sedicesimo anno di et\u00e0. Le novit\u00e0 introdotte pongono il premio a met\u00e0 strada tra tradizione e innovazione, guardando alla specificit\u00e0<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-222193 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/Asset-5-250x280.png\" alt=\"\" width=\"250\" height=\"280\" title=\"\"> di un genere letterario come quello della micronarrativa, che si sviluppa lungo il percorso del testo scritto o della fotografia. Proprio questa scelta specifica fa s\u00ec che il Premio Citt\u00e0 di Leonforte sia <strong>l&#8217;unico concorso letterario, su tutto il territorio regionale, dedicato a questo particolare genere<\/strong>. La diffusione massiccia dei social network, Twitter in particolare, ha rivoluzionato il modo di scrivere e comunicare. Da qui prende spunto l&#8217;essenza stessa del concorso: nella brevit\u00e0 di pochi caratteri, infiniti modi di raccontare.<\/p>\n<p>&nbsp;<\/p>\n<p>Due le sezioni previste dal bando: micronarrativa e teatro. Per la micronarrativa si possono presentare elaborati da 1400 caratteri, sviluppando racconti a partire da uno dei tre incipit presenti nel bando. Si pu\u00f2, in alternativa, presentare una foto ispirata al tema &#8220;attimi di paese&#8221;, corredata da un pensiero coerente con la foto e di massimo 140 caratteri. Per il teatro, le compagnie possono inviare le proprie opere agli indirizzi presenti nel bando. <strong>I termini di scadenza per presentare gli elaborati sono fissati al 20 Giugno 2018 per il teatro, mentre per la micronarrativa c\u2019\u00e8 tempo fino al 06 Luglio.<\/strong> Dopodich\u00e9 due commissioni formate da esperti nel campo giornalistico, letterario, fotografico e teatrale valuteranno le opere pervenute entro trenta giorni. La cerimonia di premiazione avr\u00e0 luogo all\u2019inizio di agosto 2018, all&#8217;interno di un Festival culturale che animer\u00e0 il cuore barocco della citt\u00e0. I vincitori si aggiudicheranno premi in denaro, nonch\u00e9 la possibilit\u00e0 di essere inseriti (per il teatro) all\u2019interno della stagione teatrale del Teatro Regina Margherita di Caltanissetta.<\/p>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\">CLICCA IN BASSO PER<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5235\" target=\"_blank\" rel=\"noopener\">PREMIO LEONFORTE<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/5236\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">BANDO TEATRO<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/5237\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">BANDO MICRONARRATIVA\/FOTOGRAFIA<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Il concorso nazionale \u00e8 aperto a tutti e intende portare alla ribalta il nuovo modo di scrivere e comunicare creato dall&#8217;influenza dei social network<\/p>\n","protected":false},"author":22,"featured_media":94280,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42,40,16,7],"tags":[],"class_list":["post-94279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza","category-cultura-spettacolo","category-italia","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=94279"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/94280"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=94279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=94279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=94279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}