{"id":94504,"date":"2018-06-16T15:01:52","date_gmt":"2018-06-16T13:01:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sconti-per-gli-studenti-delluniversita-della-calabria-su-comunical\/"},"modified":"2023-01-16T18:55:03","modified_gmt":"2023-01-16T17:55:03","slug":"223245-sconti-per-gli-studenti-delluniversita-della-calabria-su-comunical","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/223245-sconti-per-gli-studenti-delluniversita-della-calabria-su-comunical\/","title":{"rendered":"Sconti per gli studenti dell&#8217;Universit\u00e0 della Calabria su Comunical"},"content":{"rendered":"<h4>Cartolibreria, birreria, parrucchiere, estetista diverse le strutture commerciali che offrono sconti agli studenti dell&#8217;Unical<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Una vetrina virtuale in cui domanda e offerta si incontrano, uno spazio dedicato alle eccellenze del territorio: nasce Comunical. Il progetto porta la firma del Comune di Rende e dell\u2019Universit\u00e0 degli Studi della Calabria e mira a valorizzare le attivit\u00e0 cittadine del settore terziario e a favorire un contatto diretto con gli studenti del campus, attraverso la creazione di<strong> una rete di supporto agli esercenti, che decideranno di inserire delle promozioni per gli studenti Unical<\/strong>. Nel corso della conferenza stampa di presentazione del protocollo d\u2019intesa sono stati illustrati i dettagli dell\u2019iniziativa alla presenza dell\u2019assessore alle Attivit\u00e0 Produttive Domenico Ziccarelli e del Prorettore Centro Residenziale Unical Luigino Filice.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul portale <a href=\"https:\/\/quicosenza.it\/news\/5262\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em><strong>www.comunical.org<\/strong> <\/em><\/span><\/a>sar\u00e0 possibile consultare la mappa delle attivit\u00e0 aderenti all\u2019iniziativa, trovare informazioni utili. Al contempo <strong>gli esercenti potranno avere a loro disposizione una vetrina in cui inserire promozioni ed eventi in corso<\/strong>, che saranno veicolati anche attraverso i canali dei social media dedicati. \u201c Il campus ospita migliaia di ragazzi fuori sede che poco o nulla sanno della citt\u00e0. Abbiamo voluto creare uno spazio virtuale in cui gli studenti potessero orientarsi facilmente ed avere un contatto diretto con il territorio, ha spiegato l\u2019assessore alle attivit\u00e0 Produttive Domenico Ziccarelli. Il compito primario per una amministrazione deve essere quello di creare sinergie all\u2019interno delle diverse anime della citt\u00e0. Abbiamo puntato non a caso sul commercio, che \u00e8 il motore dell\u2019economia del territorio\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cAbbiamo accolto con molto favore questa iniziativa- ha aggiunto il Prorettore Filice in conferenza stampa- perch\u00e9 offre un servizio concreto agli studenti e contribuisce alla formazione della comunit\u00e0 in una citt\u00e0 a connotazione universitaria\u201d. \u201cComunical \u00e8 soltanto un tassello \u2013 ha aggiunto l\u2019Assessore Ziccarelli- delle tante iniziative che l\u2019amministrazione Manna sta portando avanti in direzione di una sinergia sempre pi\u00f9 stretta tra Campus e citt\u00e0 di Rende. <strong>Abbiamo gi\u00e0 avviato l\u2019iter per l\u2019istituzione di una delegazione del Municipio all\u2019interno dell\u2019Universit\u00e0.<\/strong> Lo sportello crer\u00e0 un canale diretto di confronto tra gli studenti e il Comune, in cantiere poi i sono i progetti inseriti all\u2019interno della strategia urbana, che ridisegner\u00e0 la citt\u00e0 di Rende nei prossimi vent\u2019anni e l\u2019Unical avr\u00e0 un ruolo sempre pi\u00f9 centrale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">CLICCA IN BASSO PER<\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/5262\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">ACCEDERE A COMUNICAL<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cartolibreria, birreria, parrucchiere, estetista diverse le strutture commerciali che offrono sconti agli studenti dell&#8217;Unical<\/p>\n","protected":false},"author":21,"featured_media":94505,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-94504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=94504"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/94505"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=94504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=94504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=94504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}