{"id":94621,"date":"2018-06-20T09:06:30","date_gmt":"2018-06-20T07:06:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/petizione-su-ospedale-bruno-bossio-pd-occhiuto-si-e-impuntato-atteggiamento-infantile\/"},"modified":"2023-01-16T18:55:09","modified_gmt":"2023-01-16T17:55:09","slug":"223869-petizione-su-ospedale-bruno-bossio-pd-occhiuto-si-e-impuntato-atteggiamento-infantile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/223869-petizione-su-ospedale-bruno-bossio-pd-occhiuto-si-e-impuntato-atteggiamento-infantile\/","title":{"rendered":"Petizione su ospedale, Bruno Bossio (PD): &#8220;Occhiuto si \u00e8 impuntato, atteggiamento infantile&#8221;"},"content":{"rendered":"<h4>Il dibattito intorno al nuovo ospedale non sembra trovare uno sbocco. Da un lato c&#8217;\u00e8 lo studio di fattibilit\u00e0 per Vaglio Lise, dall&#8217;altro l&#8217;opposizione di Occhiuto. Una discussione che si trascina da tempo e a soffrire le carenze sono i cittadini del territorio cosentino.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;Mario Occhiuto <strong>si \u00e8 impuntato cos\u00ec come aveva fatto per la Metro<\/strong>, che adesso\u00a0presenta come una sua creatura, vorr\u00e0 dire che forse si convincer\u00e0&#8221;. A dirlo \u00e8 la deputata del Pd Enza Bruno Bossio che annuncia l&#8217;avvio di una\u00a0petizione attraverso cui raccogliere le firme per far decidere ai cittadini &#8220;affinch\u00e8 queste scelte si facciano nella maniera migliore&#8221;. Quello che \u00e8 chiaro, \u00e8 che &#8220;l&#8217;ospedale che si deve realizzare \u00e8 l&#8217;ospedale hub della provincia e tutti sappiamo che ci sono tanti problemi soprattutto al Pronto soccorso. La struttura attuale non \u00e8 adeguata ad essere un ospedale Hub non solo dal punto di vista delle risorse professionali (anche se su questo, grazie alle ultime scelte del direttore generale, si sono avuti i nuovi ingressi di medici e di infermieri), ma perch\u00e8 la struttura ha una richiesta enorme quindi un nuovo ospedale, provinciale, a Cosenza serve&#8221;.<\/p>\n<h3>&#8220;L&#8217;atteggiamento di Occhiuto \u00e8 un p\u00f2 infantile&#8221;<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-122202 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/11\/Ospedale700x400.jpg\" alt=\"\" width=\"333\" height=\"211\" title=\"\">&#8220;E&#8217; ovvio che il presidente Oliverio e la Regione, hanno pensato che il luogo pi\u00f9 giusto fosse nel territorio di Cosenza che \u00e8 il capoluogo di provincia. Se il s<strong>indaco di Cosenza<\/strong> questo non vuole farlo &#8211;\u00a0 prosegue la Bruno Bossio &#8211; perch\u00e8 <strong>dice &#8220;Cosenza \u00e8 mia e la gestitsco io&#8221;<\/strong> francamente mi sembra un <strong>atteggiamento un p\u00f2 infantile<\/strong>. Fermo restando le prerogative istituzionali di ognuno, penso che questo sia un servizio importante per il &#8216;cittadino&#8217;; oltretutto non c&#8217;\u00e8 <strong>nessuna contrapposizione tra gli investimenti<\/strong> per migliorare la struttura attuale e il nuovo investimento. Tant&#8217;\u00e8 che nei giorni scorsi, il presidente Oliverio ha inaugurato le nuove sale operatorie; un complesso che consente una risposta anche a livello di chirurgia che \u00e8 all&#8217;altezza di un ospedale provinciale. Le scelte che sta facendo il presidente di Regione, vanno nella direzione del bene dei cittadini della provincia e della citt\u00e0&#8221;.<\/p>\n<p>La deputata del <strong>Partito Democratico, Enza Bruno Bossio<\/strong>, \u00e8 intervenuta sull&#8217;argomento su <strong>Rlb<\/strong> ai microfoni della trasmissione <strong>Informattiva<\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/h4>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/ENZA-BRUNO-BOSSIO-sanita.mp3&#8243;]<\/p>\n<h4>Il consiglio comunale? Scelta miope non invitare il governatore Oliverio<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-147251 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/ConsiglioComunale.jpg\" alt=\"\" width=\"318\" height=\"282\" title=\"\">&#8220;Siamo in un momento in cui la democrazia pare si stia appannando &#8211; dichiara la deputata del Partito Democratico &#8211; ma per fortuna in Italia esiste l&#8217;esecutivo e il legislativo, esiste il livello del governo e il livello dell&#8217;istituzione parlamentare e in questo caso, il Parlamento dei cittadini di Cosenza, \u00e8 il Consiglio comunale. Tra l&#8217;altro<strong> non invitare il presidente della Regione alla discussione<\/strong> sul nuovo ospedale \u00e8 <strong>una scelta <\/strong>veramente <strong>miope e senza senso&#8221;<\/strong>.<\/p>\n<p>&#8220;Parliamoci chiaro &#8211; ribadisce Enza Bruno Bossio &#8211; tutti gli <strong>investimenti<\/strong> che si fanno per la citt\u00e0 di Cosenza, <strong>non sono fondi del Comune<\/strong>, sono tutte iniziative e finanziamenti regionali.<strong> Non c&#8217;\u00e8 un salvadanaio di Occhiuto<\/strong> che decide se fare questo o quell&#8217;altro. Sono finanziamenti europei, nazionali, regionali. Il Comune certamente ha voce in capitolo ma non \u00e8 determinante&#8221;.<\/p>\n<h3>Vaglio Lise e la Cittadella della Salute<\/h3>\n<p>&#8220;Vaglio Lise \u00e8 una scelta che non ha fatto Oliverio ma \u00e8 stato fatto uno <strong>studio di fattibilit\u00e0,<\/strong> molto trasparente, e <strong>ogni cittadino pu\u00f2 andare a leggere le diverse opzioni<\/strong>\u00a0tra cui, quella del sito attuale. Sicuramente <strong>non si creer\u00e0 nessuna periferia<\/strong> perch\u00e8 nella vecchia struttura <strong>si intende realizzare una Cittadella della Salute<\/strong> nella quale trasferire tutti gli uffici dell&#8217;Asp e anche le strutture ambulatoriali&#8221;.<\/p>\n<p>&#8220;Mi sembra che il vero problema della citt\u00e0 di Cosenza \u00e8 quello di integrare le periferie. Le opere di questo tipo, come il Ponte di Calatrava, hanno un senso per creare una maggiore integrazione di una citt\u00e0 che non \u00e8 enorme. E poi la vicinanza della stazione ferroviaria di Vaglio Lise potrebbe dare anche un nuovo impulso. Mario Occhiuto essendo anche un architetto &#8211; sottolinea &#8211; non pu\u00f2 che pensare che Vaglio Lise in questo modo si integra e l&#8217;attuale sede, nel momento in cui diventa una Cittadella della Salute, diventa un ulteriore servizio che si da al cittadino&#8221;.<\/p>\n<h3>Scura? Si torni presto alla gestione ordinaria della Sanit\u00e0<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-50535 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/scura.jpg\" alt=\"\" width=\"259\" height=\"171\" title=\"\">&#8220;Il problema di un commissario al piano di rientro ha come finalit\u00e0 quello di rientrare dai costi. Da quando c&#8217;\u00e8 Massimo Scura (che \u00e8 in piena eredit\u00e0 con il commissario precedente che era Scopelliti), <strong>i costi non sono diminuiti ma aumentati<\/strong> e contemporaneamente sono<strong> diminuti i livelli essenziali dei servizi<\/strong>. Questo problema lo dobbiamo affrontare e non l&#8217;abbiamo posto noi dal punto di vista politico; l&#8217;ha posto il<strong> Tavolo Tecnico Interministeriale che ha valutato negativamente l&#8217;operato di Scura<\/strong>. C&#8217;\u00e8 una legge nazionale e dice che il commissario, cos\u00ec come fatto in Campania, dovrebbe essere il presidente della Regione. Meglio ancora se si ripristina una normale articolazione che \u00e8 quella dell&#8217;assessore alla sanit\u00e0 e dunque della gestione ordinaria del settore&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il dibattito intorno al nuovo ospedale non sembra trovare uno sbocco. Da un lato c&#8217;\u00e8 lo studio di fattibilit\u00e0 per Vaglio Lise, dall&#8217;altro l&#8217;opposizione di Occhiuto. Una discussione che si trascina da tempo e a soffrire le carenze sono i cittadini del territorio cosentino.<\/p>\n","protected":false},"author":22,"featured_media":94622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-94621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=94621"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/94622"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=94621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=94621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=94621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}