{"id":9493,"date":"2012-12-12T12:26:25","date_gmt":"2012-12-12T11:26:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9493"},"modified":"2023-01-17T13:42:39","modified_gmt":"2023-01-17T12:42:39","slug":"4197-beni-culturali-incontro-a-lamezia-terme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4197-beni-culturali-incontro-a-lamezia-terme\/","title":{"rendered":"Beni Culturali: incontro a Lamezia Terme"},"content":{"rendered":"<p><strong>LAMEZIA TERME<\/strong> &#8211; L&#8217;assessorato regionale alla Cultura, Mario Caligiuri &#8211; informa una nota dell&#8217;ufficio stampa<\/p>\n<p>  <!--more-->  <\/p>\n<p>della Giunta &#8211; ha promosso un incontro operativo che si terra&#8217; domani, giovedi&#8217; 13 dicembre, alle ore 15, nella sede della Fondazione Terina al Centro agroalimentare di Lamezia Terme. L&#8217;iniziativa, organizzata in collaborazione con la Soprintendenza ai beni culturali della Calabria e il Dipartimento di archeologia dell&#8217;Universita&#8217; della Calabria con il supporto delle Fondazioni &#8220;Field&#8221; e &#8220;Brettion&#8221;, sara&#8217; l&#8217;occasione per presentare una prima ricognizione dei beni culturali calabresi finanziati nel corso degli anni e non completamente valorizzati. Durante l&#8217;incontro, inoltre, saro&#8217; illustrato un progetto pilota per sperimentare l&#8217;essenziale collaborazione tra pubblico, privato, terzo settore e volontariato per la valorizzazione dei beni culturali. I lavori saranno introdotti dall&#8217;assessore regionale alla Cultura Mario Caligiuri. Interverranno, tra gli altri, il direttore della Fondazione Brettion Paolo Gallo, la direttrice di Lubec (Lucca Beni Culturali), e coordinatore del progetto &#8220;La Magna Charta del Volontariato per i beni culturali&#8221;, Francesca Velani, la presidente regionale del Fondo per l&#8217;Ambiente Italiano (Fai) Annalia Paravati, dla sovrintendente dei Beni Archeologici della Calabria Simonetta Bonomi e il direttore del Dipartimento di archeologia dell&#8217;Universita&#8217; della Calabria Giuseppe Roma. Parteciperanno inoltre i delegati regionali di &#8220;Italia Nostra&#8221;, &#8220;Gruppi Archeologici d&#8217;Italia&#8221; e &#8220;Archeoclub&#8221;, oltre a rappresentanti dell&#8217;associazione &#8220;San Fantino&#8221; di Palmi e della cooperativa &#8220;Aristippo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME &#8211; L&#8217;assessorato regionale alla Cultura, Mario Caligiuri &#8211; informa una nota dell&#8217;ufficio stampa<\/p>\n","protected":false},"author":22,"featured_media":9494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-9493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9493"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9494"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}