{"id":94963,"date":"2018-06-29T09:30:10","date_gmt":"2018-06-29T07:30:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/jacqueline-scricciola-timida-che-ama-le-coccole-posture-sono-rilassato-ti-rispetto\/"},"modified":"2023-01-16T18:55:32","modified_gmt":"2023-01-16T17:55:32","slug":"225066-jacqueline-scricciola-timida-che-ama-le-coccole-posture-sono-rilassato-ti-rispetto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225066-jacqueline-scricciola-timida-che-ama-le-coccole-posture-sono-rilassato-ti-rispetto\/","title":{"rendered":"Jacqueline, scricciola timida che ama le coccole. Posture: &#8220;sono rilassato, ti rispetto&#8221; (AUDIO)"},"content":{"rendered":"<h4>Gli occhi di Jacqueline sono quelli della fiducia che ha dovuto riacquistare nonostante la sua giovanissima et\u00e0. Oggi adora stare accanto ai suoi amici &#8220;due zampe&#8221; e si fida dell&#8217;uomo.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<h3>Jacqueline<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-225068 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/jacqueline-022-159x280.jpg\" alt=\"\" width=\"85\" height=\"150\" title=\"\">E&#8217; una piccoletta di 7 mesi, futura taglia medio piccola, tutta bianca e con due occhi speciali. Dopo un p\u00f2 di diffidenza dettata probabilmente dalla paura, oggi la piccola Jacqueline va al guinzaglio, si fa coccolare ed \u00e8 pronta per trovare un umano che le voglia bene. Non importa come \u00e8 finita in canile e da dove \u00e8 arrivata, quello che conta \u00e8 che qualcuno metta fine alla sua solitudine dietro quel box in canile e non permetta il suo trasferimento nell&#8217;affollato canile rifugio. Lei \u00e8 solo una cucciola&#8230; merita di crescere in un altro modo. Jacqueline ricerca molto il contatto umano, soffre la solitudine e si affida vaccinata, sterilizzata, chippata.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA la rubrica di questa settimana<\/span><br \/>\n[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/Quilazampa-19-giugno.mp3&#8243;]<\/h4>\n<h4 style=\"text-align: center;\">Posture per capire lo stato d&#8217;animo del cane<\/h4>\n<p>Questa settimana ecco altre posture dei nostri amici pelosi che comunicano attraverso le loro azioni, cosa provano e se sono stressati, arrabbiati, calmi o infastiditi.<\/p>\n<p><strong>Sono completamente rilassato<\/strong>: il cane porta le orecchie indietro e inizia a socchiudere gli occhi e a sbattere le palpebre. Facciamoci caso, se lo facciamo noi, anche il nostro amico peloso sbatte le palpebre dopo pochi secondi. Se noi socchiudiamo gli occhi e sbadigliamo gli comunichiamo di essere anche noi rilassati.<\/p>\n<p><strong>La posizione a pallina<\/strong>: quando il cane \u00e8 in piedi e la testa quasi raggiunge il sederino e lui inizia a girare su se stesso ci sta comunicando &#8220;sono educato, sono felice di vederti, mi so comportare, non ti mordo, sono buono e gradisco due coccole&#8221;. Gradisce il contatto umano<\/p>\n<p><strong>Quando \u00e8 seduto e ci d\u00e0 le spalle<\/strong>: \u00e8\u00a0un segno di rispetto. Il cane ci comunica &#8220;non voglio scontri, non voglio sfide&#8230; magari non mi fido al 100% ma ti rispetto come essere umano&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-222949 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/posture-cani-qui-la-zampa.jpg\" alt=\"\" width=\"569\" height=\"610\" title=\"\"><\/p>\n<p>Se vuoi scriverci e chiederci un consiglio sull\u2019educazione del tuo cane: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3>Numeri utili per informazioni e\/o adozioni<\/h3>\n<p>Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Gli occhi di Jacqueline sono quelli della fiducia che ha dovuto riacquistare nonostante la sua giovanissima et\u00e0. Oggi adora stare accanto ai suoi amici &#8220;due zampe&#8221; e si fida dell&#8217;uomo.<\/p>\n","protected":false},"author":22,"featured_media":94964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,47],"tags":[],"class_list":["post-94963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=94963"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/94964"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=94963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=94963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=94963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}