{"id":94980,"date":"2018-06-29T12:00:01","date_gmt":"2018-06-29T10:00:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/due-giornate-nel-cuore-della-sila-per-ricordare-piero-romeo\/"},"modified":"2023-01-16T18:55:33","modified_gmt":"2023-01-16T17:55:33","slug":"225106-due-giornate-nel-cuore-della-sila-per-ricordare-piero-romeo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225106-due-giornate-nel-cuore-della-sila-per-ricordare-piero-romeo\/","title":{"rendered":"Due giornate nel cuore della Sila per ricordare Piero Romeo"},"content":{"rendered":"<h4>Nel ricordo di Piero anche quest\u2019anno non si rinuncia a ricordare la figura di Piero Romeo<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Domani, 30 giugno e domenica 1\u00b0 luglio torna l&#8217;iniziativa dedicata a Piero Romeo, un cosentino speciale che ha contribuito in maniera fondamentale al movimento ultr\u00e0 cosentino e ritenuto figura di riferimento dell&#8217;intero popolo rossoblu&#8217;. Una persona di cui Cosenza va orgogliosa. Anche Piero Romeo dunque\u00a0festegger\u00e0 la ritrovata Serie B, festegger\u00e0 un\u2019annata dolce e amara conclusasi con un turbinio di emozioni, difficilmente paragonabili ad altre finora vissute.<\/p>\n<p>La due giorni inizier\u00e0 con il pranzo di sabato, per poi assistere tutti assieme al torneo di calcetto, alla fine del quale si terr\u00e0 un dibattito che verter\u00e0 sul significato dell\u2019essere ultr\u00e0, tra ieri ed oggi. La serata si concluder\u00e0 con cena e dj set.<\/p>\n<p>La domenica colazione, pranzo e saluti finali a tutti i partecipanti. Un modo per ritrovarsi tutti insieme nello splendido scenario della Sila, tifosi ed ultr\u00e0, con i fratelli gemellati e tutti coloro i quali vorranno onorare la figura di Piero Romeo, che, pur essendo scomparso cos\u00ec prematuramente, in realt\u00e0 \u00e8 vivo e presente nel cuore di chi lo ha conosciuto, da uomo, da cosentino e da ultr\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-225111 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/36334517_803398683188522_2495049615821242368_n.jpg\" alt=\"\" width=\"497\" height=\"304\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel ricordo di Piero anche quest\u2019anno non si rinuncia a ricordare la figura di Piero Romeo<\/p>\n","protected":false},"author":24,"featured_media":94981,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-94980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=94980"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/94980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/94981"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=94980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=94980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=94980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}