{"id":95004,"date":"2018-06-29T15:33:55","date_gmt":"2018-06-29T13:33:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/zonadem-nuovo-ospedale-curarsi-nella-propria-terra-e-non-migrare\/"},"modified":"2023-01-16T18:55:35","modified_gmt":"2023-01-16T17:55:35","slug":"225179-zonadem-nuovo-ospedale-curarsi-nella-propria-terra-e-non-migrare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225179-zonadem-nuovo-ospedale-curarsi-nella-propria-terra-e-non-migrare\/","title":{"rendered":"ZonaDem, nuovo ospedale: \u00abCurarsi nella propria terra e non migrare\u00bb"},"content":{"rendered":"<h4>Per Grandinetti questo progetto \u00e8 l&#8217;inizio di uno\u00a0sviluppo in grado di diventare negli anni il fiore all\u2019occhiello per l\u2019intero mezzogiorno d\u2019Italia<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-225181 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/20180530_173332-373x280.jpg\" alt=\"\" width=\"273\" height=\"205\" title=\"\">COSENZA &#8211; In una nota, il coordinatore e portavoce del Circolo ZonaDem di Cosenza, Alessandro Grandinetti, analizza la situazione di stallo in cui regna la scelta del sito per la realizzazione del nuovo Ospedale dell\u2019area urbana bruzia. Occorre programmare il futuro non fermandosi alle scaramucce politiche e alle gelosie del momento tra i vari rappresentanti delle Istituzioni interessate. Per il bene dei cittadini e per la tutela del diritto costituzionale, ossia di garantire una buona sanit\u00e0 a tutti, serve uno slancio di orgoglio sia da parte del Sindaco di Cosenza, Occhiuto, che da parte del Presidente della Regione Calabria, Oliverio. Quanto accaduto giorni fa, in seno all\u2019assise comunale, non deve preoccuparci perch\u00e9 fa parte della normale dialettica interna, piuttosto dobbiamo (includendo tutti i soggetti coinvolti e anche noi cittadini, spesso lasciati inermi dinanzi alle scelte strategiche) impegnarci affinch\u00e9 questo nuovo Ospedale si realizzi, con tempi certi, in un luogo sicuro e ottimo logisticamente ma soprattutto che i finanziamenti siano mirati e spesi bene e, cosa di non minore conto, che anche l\u2019area a sud, ove insiste, ad oggi, l\u2019Ospedale dell\u2019Annunziata, venga recuperata e rilanciata, magari per una medicina generale e poliambulatoriale.<\/p>\n<p>Non occorrono autoproclami su eventuali primogeniture o intervenire continuamente per apportare modifiche alle linee programmatiche gi\u00e0 prese, con il solo scopo di dilungare i tempi e fare melina, serve, invece, che finalmente si doti l\u2019intera area dell\u2019hinterland di Cosenza con servizi veloci, efficienti e uguali per tutti. Nessun campanilismo, dunque, secondo Grandinetti, ma solo voglia di realizzare una cosa mai fatta prima, di far dono con una sana politica a quello che da anni si reclama, ad essere curati nella propria terra e a non vedersi costretti alla migrazione sanitaria, arricchendo di fatto le regioni del nord. La politica ha il compito e il dovere di dare risposte ma anche di creare le basi per garantire un futuro migliore ai cittadini. Auspico, pertanto, che in queste settimane si ponga inizio ad una nuova fase, responsabile e soprattutto capace di farci sentire per una volta finalmente fieri dei nostri politici. Comune e Regione insieme possono fare con questo progetto in questa nostra terra, spesso derisa e depauperata di tutto, un volano di sviluppo in grado di diventare negli anni il fiore all\u2019occhiello per l\u2019intero mezzogiorno d\u2019Italia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per Grandinetti questo progetto \u00e8 l&#8217;inizio di uno\u00a0sviluppo in grado di diventare negli anni il fiore all\u2019occhiello per l\u2019intero mezzogiorno d\u2019Italia<\/p>\n","protected":false},"author":37,"featured_media":95005,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-95004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95004"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95005"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}