{"id":95040,"date":"2018-06-30T06:56:20","date_gmt":"2018-06-30T04:56:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/longobucco-coltivava-la-marijuana-a-casa-arrestato-28enne\/"},"modified":"2023-01-16T18:55:38","modified_gmt":"2023-01-16T17:55:38","slug":"225283-longobucco-coltivava-la-marijuana-a-casa-arrestato-28enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225283-longobucco-coltivava-la-marijuana-a-casa-arrestato-28enne\/","title":{"rendered":"Longobucco, coltivava la marijuana a casa. Arrestato 28enne"},"content":{"rendered":"<h4>I carabinieri di Longobucco, nel corso di un servizio finalizzato alla prevenzione ed alla repressione di reati in materia di spaccio di stupefacenti, lo hanno arrestato in flagranza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LONGOBUCCO (CS) &#8211; E&#8217; stato arrestato nel pomeriggio di gioved\u00ec <strong>F. D., di 28 anni<\/strong>, poich\u00e9 indagato per il reato di <strong>coltivazione di sostanza stupefacente<\/strong>. I carabinieri infatti, nell\u2019ambito delle attivit\u00e0 istituzionali hanno proceduto al controllo dell\u2019abitazione dell\u2019uomo trovandosi di fronte, ad una attivit\u00e0 di coltivazione della marijuana: l\u2019uomo aveva ricavato uno spazio all\u2019interno del quale deteneva i <strong>vasi con all\u2019interno le piante da cui ricavare lo stupefacente.<\/strong><\/p>\n<p>Nel complesso i militari dell\u2019Arma hanno rinvenuto e sottoposto a sequestro otto piante di marijuana di altezza media di circa settanta centimetri e materiale per la coltivazione. L\u2019arrestato, al termine delle formalit\u00e0 di rito, \u00e8 stato rimesso in libert\u00e0 su disposizione del Sostituto Procuratore della Repubblica di Castrovillari, non ritenendo sussistenti allo stato esigenze di natura cautelare, per cui si proceder\u00e0 alla convalida dell\u2019arresto. Il risultato operativo si inserisce in una serie di controlli voluti dal Comando Provinciale Carabinieri di Cosenza diretti a contrastare il fenomeno dello spaccio di sostanze stupefacenti, soprattutto tra i pi\u00f9 giovani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri di Longobucco, nel corso di un servizio finalizzato alla prevenzione ed alla repressione di reati in materia di spaccio di stupefacenti, lo hanno arrestato in flagranza<\/p>\n","protected":false},"author":22,"featured_media":95041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-95040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95040"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95041"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}