{"id":95070,"date":"2018-07-01T10:45:36","date_gmt":"2018-07-01T08:45:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sgomberi-in-citta-case-popolari-di-proprieta-di-dipendenti-pubblici\/"},"modified":"2023-01-16T18:55:39","modified_gmt":"2023-01-16T17:55:39","slug":"225350-sgomberi-in-citta-case-popolari-di-proprieta-di-dipendenti-pubblici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225350-sgomberi-in-citta-case-popolari-di-proprieta-di-dipendenti-pubblici\/","title":{"rendered":"Sgomberi in citt\u00e0: case popolari di propriet\u00e0 di dipendenti &#8220;pubblici&#8221;?"},"content":{"rendered":"<h4>Sembra una partita di ping &#8211; pong, con un andirivieni &#8220;dell&#8217;ultima parola ce l&#8217;ho solo io&#8221; che mette i brividi, a colpi di legge dello Stato. Rimane tanta solidariet\u00e0&#8230;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-225335 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/06\/tomao-e-oliverio-440x241.jpg\" alt=\"\" width=\"279\" height=\"153\" title=\"\">COSENZA &#8211; Se il Governatore Oliverio ha detto &#8220;stop allo sgombero&#8221;, almeno per il momento i cento occupanti gli stabili di via Savoia e l&#8217;hotel Centrale possono respirare. Di certo, come ha pi\u00f9 volte espresso il comitato Prendocasa, non bisogna abbassare la guardia; ma il vero messaggio che dovrebbe veicolare la politica locale, regionale e nazionale, non \u00e8 certo quello della tensione che in queste ore ha aleggiato sulla citt\u00e0 bruzia, leggendo i vari &#8220;botta e risposta&#8221; tra le correnti politiche, che non fanno bene non solo agli occupanti degli stabili di via Savoia e dell&#8217;hotel Centrale, ma anche e soprattutto ai cittadini che si rendono conto di una non collaborazione tra le parti verso il bene comune. E il vicesindaco Santelli, dopo aver snocciolato numeri di assistenza messi in campo dal comune bruzio per l&#8217;emergenza abitativa, avverte: &#8220;Le politiche dell\u2019abitare e l\u2019emergenza abitativa sono argomenti troppo seri per essere discussi <strong>da soggetti istituzionali incapaci e da improvvisati della politica<\/strong>\u201d.<\/p>\n<p>Sicuramente il comune di Cosenza avr\u00e0 messo in atto tutte le politiche utili e necessarie per far fronte all&#8217;emergenza abitativa; ma continuando ad applicare la legge, per come all&#8217;epoca ritenne di fare con il caso cooperative B, riuscendo nell&#8217;intento, forse oggi potrebbe rimettere in ordine anche la questione alloggi popolari &#8220;scoperchiando il vaso di Pandora&#8221; per tutte quelle abitazioni (cos\u00ec narra la leggenda) che, per oscuri meccanismi, da casa popolare sarebbero state &#8220;riscosse&#8221; da dipendenti pubblici che abitano in ville nell&#8217;hinterland cosentino e mantengono, tra l&#8217;altro disabitata, una casa che dovrebbe essere annoverata nella casella &#8220;popolare&#8221;, ma di fatto rientrerebbe nelle case riscattate &#8230;cos\u00ec per la fortuna di trovarsi proprietari di un immobile che oggi potrebbe servire per dare un tetto a chi ne ha veramente bisogno. Forse una task force, come all&#8217;epoca il sindaco Occhiuto costitu\u00ec per le cooperative B, potrebbe procedere ad una nuova mappatura, andando a ritroso, per ripescare eventuali abitazioni che non spettano a chi oggi vive con un dignitoso stipendio statale, comunale, ecc ecc. E magari il Governatore Oliverio potrebbe tenerne conto nel disegno di legge del recupero di immobili popolari, di tutti quegli alloggi in mano a chi vive in altre abitazioni ed \u00e8 &#8220;proprietario&#8221; di case popolari.<\/p>\n<p>Non dimentichiamo gli anni in cui, a Cosenza, c&#8217;era la guerra tra i poveri all&#8217;occupazione degli alloggi popolari. La leggenda (che poi conoscono tutti) narra di occupazioni fatte su commissione: si narra che si pagava un tot di soldi a chi doveva occupare un alloggio chiuso perch\u00e8 l&#8217;avente diritto era defunto (a volte i figli del defunto correvano a chiedere la restituzione della casa per &#8220;diritto&#8221;) oppure momentaneamente vuoto perch\u00e8 l&#8217;occupante si trovava in vacanza, con la casa al mare. Gli abusivi, facendosi scudo di donne e bambini, non uscivano dall&#8217;immobile preso di mira fino a quando le forze dell&#8217;ordine non mollavano la presa. Addirittura, &#8220;i malandrini&#8221; arrivavano sul posto gi\u00e0 con pala, picozza, cemento e porte blindate nuove da montare. A tentare di salvare la situazione il vicino di casa che rimaneva in citt\u00e0, immolandosi a vedetta del quartiere. Conclusioni: una bella denuncia agli abusivi, ma una nuova casa che, successivamente, sarebbe stata ceduta a chi l&#8217;aveva commissionata. Negli anni poi, sempre la &#8220;leggenda&#8221; narra che gli stessi alloggi sarebbero stati rivenduti a gente comune dietro pagamento di 10 &#8211; 15 mila euro, a volte anche 20. Poi il nuovo acquirente, con calma, disbrigava le pratiche per regolarizzare il tutto. Ma su questo vigeva l&#8217;omert\u00e0 pi\u00f9 assoluta e il mercato &#8220;nero&#8221; della compravendita andava avanti.<\/p>\n<p>Con queste leggende sembra, dunque, che alloggi popolari ce ne sarebbero diversi in mano a chi ha una seconda casa, una villa, ecc. ecc. Questi fatti sarebbero accaduti negli anni, passando di mano in mano a tante amministrazioni (precedenti all&#8217;amministrazione Occhiuto, ndc), che all&#8217;epoca non sarebbero state in grado di vedere il mercato che si celava dietro ogni tentativo di occupazione abusiva, perch\u00e8 meccanismi che solo chi vive la strada e i bene informati conoscevano. Magari oggi una Task Force, istituita dal sindaco, potrebbe far luce su una buona percentuale di alloggi e restituirne qualcuno ai cittadini bisognosi.\u00a0 Naturalmente noi narriamo &#8220;leggende&#8221; che potrebbero rispondere a verit\u00e0. Non intendiamo puntare il dito contro nessuno, ma una verifica ogni tanto andrebbe fatta, in ragione dell&#8217;emergenza abitativa<\/p>\n<p>&nbsp;<\/p>\n<h3>I fatti delle ultime ore<\/h3>\n<p>Mentre <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5321\" target=\"_blank\" rel=\"noopener\">i penstastellati calabresi<\/a><\/strong><\/span> scrivono che seguiranno il caso da vicino e <strong><a href=\"https:\/\/quicosenza.it\/news\/5322\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Occhiuto e la Santelli<\/span><\/a><\/strong> rispondono che il Comune applica la legge, prende la parola<span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5323\" target=\"_blank\" rel=\"noopener\"> il governatore calabrese Oliverio\u00a0\u00a0<\/a><\/strong><\/span>e raffredda gli animi con lo &#8220;stop agli sgomberi&#8221;. La Giunta regionale\u00a0 &#8211; si legge in una nota -ha predisposto un\u00a0<strong>disegno di legge<\/strong>\u00a0che introduce e regola\u00a0<strong>l\u2019autorecupero<\/strong>\u00a0<strong>degli edifici pubblici<\/strong>. La\u00a0<strong>proposta di legge,<\/strong>\u00a0attualmente al vaglio dell\u2019Ufficio legislativo della Giunta regionale e per la quale sar\u00e0 richiesta corsia preferenziale per l\u2019approvazione in Consiglio,\u00a0<strong>far\u00e0 s\u00ec che edifici pubblici\u00a0<\/strong><strong>inutilizzati<\/strong>\u00a0possano essere\u00a0<strong>recuperati<\/strong>\u00a0dagli enti proprietari in collaborazione con aspiranti inquilini riuniti in cooperative di autorecupero o autocostruzione\u201d.<\/p>\n<h2>Santelli controbatte a Oliverio e pentastellati<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-205461 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/03\/iole-santelli--440x241.jpg\" alt=\"\" width=\"440\" height=\"241\" title=\"\">Buone notizie, dunque, ma le polemiche non si placano. Intanto il vicesindaco Santelli risponde al governatore Oliverio e ai pentastellati &#8220;punto su punto in merito alla questione dell\u2019emergenza abitativa nel capoluogo bruzio&#8221;. \u201cIl presidente della Giunta regionale che prima chiede, attraverso l\u2019Aterp, lo sgombero di un immobile e solo oggi si accorge delle persone fragili e vulnerabili che lo occupavano evidenzia uno stato di preoccupante confusione \u2013 afferma il vice sindaco di Cosenza &#8211; Dopo aver azzerato il contributo fitto casa a migliaia di famiglie calabresi senza avere investito in euro in nuovi insediamenti abitativi, oggi Oliverio scopre che in Calabria esiste un\u2019emergenza casa. La grave crisi in cui versano le politiche sociali nella nostra regione \u2013 aggiunge Santelli &#8211; \u00e8 purtroppo sotto gli occhi di tutti. Solo grazie ai Comuni si \u00e8 riusciti a far fronte ad un fabbisogno che cresce quotidianamente a causa della grave crisi economica in cui versano i nostri territori.<\/p>\n<p>In particolare, il Comune di Cosenza assiste, attraverso vari interventi, circa 600 nuclei familiari, assicurando a oltre un terzo di queste famiglie il pagamento dell\u2019intero canone annuale di locazione. Per i restanti due terzi \u2013 spiega \u2013 il Comune si \u00e8 sostituito con i propri fondi alla Regione Calabria attraverso la concessione di un contributo. Tutte le famiglie cosentine in situazione di disagio sono oggetto di una rete di interventi che hanno l\u2019obiettivo di contrastare uno stato di emergenza che cresce quotidianamente. Inoltre, abbiamo dato avvio al primo progetto di auto-recupero. Quando saranno concluse le procedure di affidamento dei lavori strutturali, saranno individuati nove nuclei familiari che parteciperanno attivamente alla ristrutturazione di uno stabile comunale.<\/p>\n<p>E a differenza di quanto affermano<strong> i rappresentanti dei 5 Stelle,<\/strong> tutti gli immobili comunali sono stati oggetto di una attivit\u00e0 di verifica e monitoraggio che ha permesso di individuare tutte le occupazioni abusive.\u00a0 Gli alloggi comunali sono inoltre oggetto di un intervento di manutenzione straordinaria per un investimento di 1,5 milioni di euro. Rispetto alla questione degli sgomberi \u2013 prosegue Jole Santelli &#8211; come accaduto in passato, senza inutili enunciazioni, abbiamo messo in campo tutte le misure necessarie per far fronte alle eventuali emergenze. Le politiche dell\u2019abitare e l\u2019emergenza abitativa \u2013 conclude &#8211; sono argomenti troppo seri per essere discussi da soggetti istituzionali incapaci e da improvvisati della politica\u201d.<\/p>\n<h2>E arriva la replica anche per Guccione<\/h2>\n<p>\u201cIl Sindaco di Cosenza non \u00e8 tenuto ad aprire alcun tavolo istituzionale, il tavolo \u00e8 gi\u00e0 in corso in Prefettura\u201d. Il vice sindaco di Cosenza, Santelli, replica &#8211; sulla questione dell\u2019emergenza abitativa &#8211; alla richiesta avanzata dal capogruppo consiliare a palazzo dei Bruzi della \u201cGrande Cosenza\u201d nonch\u00e9 consigliere regionale del Pd, Carlo Guccione.\u00a0 \u201cLa Regione \u2013 continua Santelli \u2013 che per giunta \u00e8 proprietaria dell\u2019immobile in questione, ha fatto solo una fugace comparsa. Chieda dunque l\u2019onorevole Guccione proprio alla Regione Calabria di assumersi le proprie responsabilit\u00e0 ad iniziare dal ripristinare il fondo per la locazione immobili che \u00e8 stato cancellato e a cui il Comune di Cosenza provvede da solo, oltre al fatto di assumere iniziative sull\u2019immobile di via Savoia che \u00e8 appunto di propriet\u00e0 regionale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">Ma i pentastellati tengono alto il profilo e rispondono a Comune e Regione:\u00a0<strong>&#8220;Occhiuto e Santelli sfuggono dalle proprie responsabilit\u00e0&#8221;.\u00a0<\/strong><strong>Vigileremo su quanto promesso da Oliverio<!--nextpage--><\/strong><\/h3>\n<p style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-170324 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/08\/Prendocasa-440x275.jpg\" alt=\"\" width=\"440\" height=\"275\" title=\"\">\u00abNon si sono fatti attendere i voli pindarici del sindaco Mario Occhiuto e del vice sindaco Jole Santelli per sfuggire alle proprie responsabilit\u00e0 di fronte l&#8217;emergenza abitativa che da anni attanaglia Cosenza\u00bb. Cos\u00ec i portavoce del Movimento 5 Stelle, Laura Ferrara, Anna Laura Orrico, Nicola Morra e Alessandro Melicchio in risposta alle dichiarazioni arrivate ieri da Palazzo dei Bruzi. \u00abNel pieno rispetto delle istituzioni e della legalit\u00e0 abbiamo inteso incontrare il Prefetto Gianfranco Tomao per aver pi\u00f9 chiara la grave situazione degli stabili di Via Savoia e dell&#8217;ex Hotel Centrale, fino ad oggi occupati abusivamente da diverse famiglie. Il nostro obiettivo \u00e8 quello di cercare una soluzione che sia definitiva, per tutti coloro che ne hanno il diritto superando una volta per tutte le logiche clientelari e ad uso e consumo dei soliti noti.<\/p>\n<p style=\"font-weight: 400;\">Il Comune di Cosenza, al contrario di quanto si vuol far credere, non ha fatto assolutamente nulla, nonostante le competenze in materia, per affrontare concretamente l&#8217;emergenza abitativa, se non elargire contributi economici esigui e non risolutivi del problema. Un&#8217;emergenza che non riguarda solo le famiglie che hanno occupato abusivamente gli edifici succitati, ma tantissimi cittadini. Le nostre proposte, attuabili a medio e lungo termine, vanno nella direzione di garantire a chiunque ne abbia il diritto una casa. Al contrario l&#8217;azione fin qui registrata dall&#8217;amministrazione Occhiuto non ha cambiato di una virgola lo stato di assoluta opacit\u00e0 nella gestione dell&#8217;affidamento delle abitazioni sociali. Il Comune potrebbe intanto avviare un controllo serio nelle case popolari al fine di individuare se gli occupanti siano realmente assegnatari.<\/p>\n<p style=\"font-weight: 400;\">Si chiarisca la destinazione d&#8217;uso degli immobili di propriet\u00e0 del Comune. Non ci interessa la sterile polemica vorremmo i fatti. Con lo sgombero diverse persone, fra queste oltre sessanta minori, si troveranno senza un tetto sicuro. Come Movimento 5 stelle continueremo a tenere alta l&#8217;attenzione sulla tematica del diritto alla casa, non legittimiamo quindi le occupazioni abusive e anzi chiediamo a chi di dovere di riportare la legalit\u00e0, anche e soprattutto nella gestione degli immobili di propriet\u00e0 pubblica destinati ad abitazioni sociali\u00bb. \u00abApprendiamo che <strong>la Regione Calabria \u00e8 finalmente uscita dal letargo<\/strong>. Ha apprezzato la nostra proposta sull&#8217;autorecupero degli immobili pubblici abbandonati e ha intenzione di promuovere una legge regionale sulla scia del DDL del Movimento 5 Stelle. Accogliamo con favore le dichiarazioni del presidente Oliverio e saremo vigili affinch\u00e9 queste parole si traducano in atti concreti\u00a0\u00bb\u00a0.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">Dalla Kasbah solidariet\u00e0 al comitato Prendocasa: &#8220;La dignit\u00e0 non si sgombera&#8221;<!--nextpage--><\/h3>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-195441 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/01\/prendocasa_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\">La notizia diffusa qualche giorno fa dal Comitato Prendocasa a seguito dell&#8217;incontro in Prefettura in cui \u00e8 stata loro comunicata la volont\u00e0 di sgomberare gli stabili di Via Savoia e dell&#8217;Hotel Centrale, ci lascia assai perplessi!<\/div>\n<div>Questi due luoghi sono abitati da singoli e famiglie che nella nostra citt\u00e0 non hanno la possibilit\u00e0 di accedere ad una casa pur avendone tutto il diritto. L&#8217;assoluta mancanza di una politica abitativa strutturale e non emergenziale \u00e8 il frutto di decenni di speculazione da parte della classe politica a danno di quanti vivono la precariet\u00e0 ed il mancato accesso a politiche di welfare.<\/div>\n<div>Per troppo tempo, a Cosenza, l&#8217;accesso alla tanta agognata casa popolare da parte degli ultimi \u00e8 stato ostacolato da un sistema clientelare creato ad arte dalla politica. Il risultato \u00e8 sotto gli occhi di tutti: stabili abitati da non aventi diritto e spesso gestiti dalla malavita locale con il beneplacito di chi, invece, ne dovrebbe controllare la gestione; liste bloccate da anni e innumerevoli stabili di propriet\u00e0 pubblica abbandonati a se stessi e che invece potrebbero soddisfare il bisogno di molti.<\/div>\n<div>La retorica del vecchio governo, oggi, \u00e8 confermata dal quello appena formatosi targato Lega e M5S, che con il pretesto del ripristino della legalit\u00e0 toglie quel briciolo di speranza a quanti per avere un tetto sulla testa sono stati giustamente costretti ad occupare abusivamente gli stabili vuoti presenti in citt\u00e0.<\/div>\n<div><\/div>\n<div>Allora una domanda da porre alle Istituzioni \u00e8 d&#8217;obbligo: come mai il ripristino della legalit\u00e0 parte sempre dai pi\u00f9 deboli? Perch\u00e9 gli organi preposti, in cinquant&#8217;anni di gestione del patrimonio abitativo pubblico, non hanno mai fatto luce sulla compravendita abusiva delle case popolari? Perch\u00e9 i cosidetti Fondi Gescal sono stati utilizzati per costruire un&#8217;opera pubblica dalla dubbia utilit\u00e0 quando invece, se fossero stati utilizzati per il loro vero scopo, avrebbero quantomeno soddisfatto l&#8217;emergenza abitativa di centinaia di persone?<\/div>\n<div>Esprimiamo solidariet\u00e0 al Comitato Prendocasa e ci auguriamo che il Sindaco Mario Occhiuto si faccia carico delle speranze di uomini, donne e bambini che abitano all&#8217;interno degli stabili, avviando un tavolo interistituzionale che si ponga come obiettivo la risoluzione del problema senza l&#8217;utilizzo della forza, perch\u00e9 lo sgombero delle occupazioni aprirebbe una crisi sociale senza precedenti in una citt\u00e0 che conserva ancora intatti i valori della solidariet\u00e0 e dell&#8217;accoglienza.<\/div>\n<div>Le occupazioni non si toccano! #cosenzaresiste<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<h3>I circoli cittadini del Pd puntano il dito contro l&#8217;Amministrazione comunale<\/h3>\n<p style=\"font-weight: 400;\">\u00abLa linea che porta avanti questa amministrazione comunale \u00e8 quella della Lega Nord. Un partito ormai entrato in maggioranza. La conferma arriva dal vice sindaco Jole Santelli, &#8220;portavoce&#8221; di Mario Occhiuto, che usa parole burocratiche e lontane da una seria analisi rispetto a un problema cos\u00ec complesso, come quello dell&#8217;emergenza abitativa. Troppo spesso ignorato\u00bb. A dichiararlo\u00a0Mario Petrozza\u00a0Tommaso Guzzi, segretari dei circoli cittadini Pd. \u00abTutti rispettiamo la legge e la difendiamo, ma c&#8217;\u00e8 una parola che questa amministrazione \u00e8 incapace di pronunciare: umanit\u00e0. Il problema dell&#8217;emergenza abitativa viene completamente ignorato dalla maggioranza consiliare, cos\u00ec come quello della povert\u00e0 dilagante. In compenso per\u00f2 \u00e8 gi\u00e0 pronto il bando per le luminarie e continuiamo ad assistere al solito balletto dei regali agli amici del sindaco.<\/p>\n<p style=\"font-weight: 400;\">Abbiamo letto con attenzione gli ultimi due numeri dell&#8217;Espresso: il direttore Marco Damilano, giustamente, richiamava tutti a un impegno per contrastare una dilagante deriva razzista in Italia. Ci piacerebbe sapere cosa pensa questa amministrazione comunale targata Forza Italia delle idee e delle azioni messe in campo dal ministro Salvini, leader di un partito tra l&#8217;altro presente da poco all&#8217;interno del consiglio comunale. Quei bambini senza casa non hanno alcuna colpa. Noi abbiamo scelto di non girarci dall&#8217;altra parte. Registriamo con amarezza la posizione fintamente attendista di questa amministrazione comunale che in realt\u00e0 ha sempre avuto posizioni reazionarie, come in occasione ad esempio del Gay pride. La battaglia per i diritti fa parte del nostro Dna. Su questi temi non siamo disposti a fare un passo indietro. E tutti devo scendere in campo e assumersi le proprie responsabilit\u00e0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<h3 style=\"text-align: center;\">Il Movimento NOI \u00e8 per la vita e scrive al Papa. Venga nella Citt\u00e0 pi\u00f9 povera della Calabria<\/h3>\n<p style=\"font-weight: 400;\"><!--nextpage--><\/p>\n<p style=\"font-weight: 400;\">La Giustizia deve fare il suo corso, come giusto che sia. Ma se nessuno interverr\u00e0, questi bambini, queste donne, questi uomini, tra i quali anche imprenditori, mamme e padri di figli vittime di un sistema imperfetto e ancora impreparato, finiranno per strada. E\u2019 compito della politica affrontare e risolvere i problemi. La Comunit\u00e0 politica del\u00a0<strong>Movimento NOI<\/strong>\u00a0chiede il massimo impegno in tal senso all\u2019Amministrazione Comunale di Cosenza e, intanto, scrive al\u00a0<strong>Santo Padre<\/strong>\u00a0perch\u00e9 programmi la sua presenza nella\u00a0<strong>Citt\u00e0 di Cosenza<\/strong>, la pi\u00f9 povera della Calabria. La lettera con all\u2019oggetto \u201cRichiesta intervento a tutela dell\u2019Infanzia e degli ultimi\u201d, \u00e8 stata gi\u00e0 inviata alla Santa Sede. Il Movimento NOI, chiede anche all\u2019Arcivescovo di Cosenza Bisignano\u00a0<strong>Sua Eccellenza Mons. Nol\u00e8<\/strong>\u00a0massima attenzione, perch\u00e9 la sua parola possa orientare la politica cosentina verso il buon senso per una ottimale soluzione di una situazione che deve essere avviata verso un percorso attivabile legalmente in questi casi. L\u2019occupazione abusiva di propriet\u00e0 non \u00e8 mai ammissibile. Ma allo stesso tempo, non possiamo ammettere che la gente muoia di solitudine e disperazione abbandonata sotto i ponti, sempre pi\u00f9 grandi. Invitando i &#8220;<strong>Prendocasa<\/strong>&#8221; a maturare un nuovo progetto per il futuro, coerente con i tempi e le leggi, eventualmente da riformare perch\u00e9 si abbraccino le sempre nuove emergenze, il Movimento NOI disponibile a fornire la propria collaborazione a che ci\u00f2 avvenga in tempi celeri, sostiene la vita umana e chi la protegge.<\/p>\n<h3>LA LETTERA INVIATA AL SANTO PADRE<\/h3>\n<p style=\"font-weight: 400;\">Santit\u00e0,<\/p>\n<p style=\"font-weight: 400;\">le scrivo nella qualit\u00e0 di portavoce nazionale della Comunit\u00e0 politica del Movimento cattolico NOI che avverte forte la responsabilit\u00e0 di quanto sta accadendo, a proposito dello sgombero di tanta povera gente che occupa una struttura alberghiera da anni inutilizzata e sottoposta a sequestro giudiziario, nella Citt\u00e0 di Cosenza. Nulla, ovviamente, da obiettare a chi applica le Leggi e deve farle rispettare. Ma, qualcuno deve pur rimediare agli squilibri e quelli siamo NOI, responsabilizzati dalla Parola del Vangelo. Quando Lei, Padre Santo, il 30 Aprile 2017 in Piazza San Pietro, ci esort\u00f2 a entrare in politica \u201cma nella grande politica, in quella con la P maiuscola\u201d, nell\u2019accogliere la sua esortazione, ci siamo fatti carico di attuare l\u2019unica politica con la \u201cP\u201d maiuscola: quella che si fa servizio alla Carit\u00e0; quella nata \u2013 come disse Don Luigi Sturzo \u2013 \u201cper servire e non per servirsi\u201d.<\/p>\n<p style=\"font-weight: 400;\">Nulla di pi\u00f9 difficile, in una societ\u00e0 sempre pi\u00f9 povera di valori, di lavoro e sempre pi\u00f9 radicata nell\u2019IO, a volte frutto dell\u2019egoismo senza fondo, a volte della paura del domani. La Citt\u00e0 di Cosenza, in modo particolare, risulta essere tra le pi\u00f9 povere della Calabria. In una realt\u00e0 su cui pesano questi dati provenienti dalle statistiche, farsi carico del prossimo \u00e8 ancora pi\u00f9 difficile. Ma se all\u2019IO uniamo DIO, ecco sorgere il NOI, il dialogo, l\u2019abbraccio fraterno, la Pace. Questa, \u00e8 la nostra fede. E\u2019 proprio di una vicenda che si sta vivendo a Cosenza che desidero portarLa a conoscenza, perch\u00e9 possa ottenere una Sua nuova preghiera di conciliazione. Saranno sgomberati a breve, su mandato della competente Autorit\u00e0 Giudiziaria, un albergo e un edificio ex Case popolari di Cosenza sottoposti da tempo a sequestro. Nel periodo in cui erano vacanti, considerato il freddo davvero insopportabile dello scorso inverno, l\u2019Associazione \u201cPrendocasa\u201d, ha aperto i suoi cancelli per collocarvi un folto gruppo di senza tetto. Tra essi, alcuni immigrati, tra cui donne e bambini e numerosi cittadini di Cosenza che per vari motivi legati all\u2019assenza di lavoro e altro, si sono ritrovati senza pi\u00f9 nulla. Parliamo anche di imprenditori.<\/p>\n<p style=\"font-weight: 400;\"><strong>Oggi, Padre Santo, la Giustizia che deve compiere il suo corso, deve operare lo sfratto. Questi fratelli e sorelle, saranno sottoposti alle sevizie e alla crudelt\u00e0 di un sistema impreparato a gestire queste crisi umanitarie.<\/strong>\u00a0E non mi riferisco solo alla nostra Citt\u00e0, ma all\u2019Europa tutta. I servizi sociali del Comune di Cosenza, non riescono a gestire l\u2019emergenza abitativa che in citt\u00e0 si vive da anni. Gli Enti Locali che dovrebbero essere \u201cresponsabili\u201d, dovrebbero affrontate con maturit\u00e0 e risolvere con intelligenza evangelica le emergenze che colpiscono gli ultimi. La politica sembra avere altre priorit\u00e0: luci e festini colorati, posti su un albero che non ha pi\u00f9 radice, poich\u00e9 a Cosenza, tra grandi opere di cementificazione, \u00e8 stata abbandonata anche la Citt\u00e0 Storica e la sua umanit\u00e0. La invito a riflettere, Padre Santo, insieme a tutti noi laici impegnati a portare testimonianza nella societ\u00e0 civile, sulla recente indagine a cura della Procura della Repubblica di Cosenza che espone un dato davvero drammatico: moltissimi cittadini di Cosenza \u2013 ci comunica &#8211; sono sotto usura non per acquistare auto di lusso o lussuosi appartamenti, ma per fare la spesa.<\/p>\n<p style=\"font-weight: 400;\">I dati di questa inchiesta mostrano il vero volto della Citt\u00e0 di Cosenza che, dietro la maschera barocca di una cementificazione massiva, inutile e priva di senso, nasconde il dramma dell\u2019assoluta povert\u00e0 di tanti e non tiene conto di un dato: una Citt\u00e0, una vera Citt\u00e0, \u00e8 tale se cresce e matura insieme alla sua umanit\u00e0. La stessa indagine della Procura della Repubblica di Cosenza, proprio ieri 28 Giugno 2018, ha indotto l\u2019autorevole stampa a titolare\u00a0<strong>\u201cCosenza, sotto usura per mangiare\u201d.\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">Una realt\u00e0, questa, che mostra le dicotomie cui \u00e8 sottoposta la stessa Giustizia che, con un braccio deve sgomberare i poveri, gli ultimi, i bisognosi, e con l\u2019altro braccio scrive la verit\u00e0:\u00a0<strong>tantissimi cittadini sono sotto usura per fare un poco di spesa.<\/strong>\u00a0Ma non pu\u00f2 fare diversamente, perch\u00e9 assistere gli ultimi non \u00e8 compito della Giustizia ma della politica.<\/p>\n<p style=\"font-weight: 400;\">Vede, Padre Santo, sappiamo tutti bene che Lei sta facendo molto in questa direzione e crediamo che, dopo la giornata con noi vissuta nella \u201cSpianata di Sibari\u201d,\u00a0<strong>Lei debba tornare nella terra di San Francesco di Paola, questa volta a Cosenza,\u00a0\u00a0per aiutarci a riflettere sul senso del fare politica.\u00a0<\/strong>Gi\u00e0, perch\u00e9 prima di tutti, \u00e8 compito della politica occuparsi seriamente di chi \u00e8 senza un tetto nella Citt\u00e0 nella quale, un\u2019ampia percentuale di case sono completamente vuote. Valga questo nostro invito, perch\u00e9 Lei possa accoglierlo e portare speranza nella Citt\u00e0 pi\u00f9 povera della Calabria.<strong>\u00a0<\/strong>Intanto, Santit\u00e0, le chiedo di fare tutto il possibile perch\u00e9 il Padre Arcivescovo di Cosenza Bisignano\u00a0<strong>S. E. Mons. Francesco Nol\u00e8,<\/strong>\u00a0che seguiamo con piena fiducia,\u00a0<strong>possa intervenire sull\u2019Amministrazione comunale della Citt\u00e0 di Cosenza,<\/strong>\u00a0<strong>perch\u00e9 essa affronti e risolva ragionevolmente il problema creatosi.<\/strong>\u00a0Gi\u00e0 da tempo il Padre Arcivescovo \u00e8 stato profeta. Nel comunicato stampa della CEI dell\u2019Aprile 2018 che indica quante opere buone sono state attuate dalle Diocesi italiane con i fondi dell\u20198&#215;1000, si riporta la seguente frase: \u201cLe opere di modernizzazione urbana, come l\u2019imponente ponte di Calatrava, in realt\u00e0 non incidono sulla povert\u00e0 dei cittadini, dai giovani con contratti a termine ai padri separati. E\u2019 ora di aprirci agli altri &#8211; ha ricordato mons. Nol\u00e9 &#8211; e di dire: Io ci sono\u201d.<strong>\u00a0<\/strong>Pieni di fiducia, rimaniamo in attesa, invocando per tutti questi nostri fratelli e sorelle la Sua Benedizione Apostolica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sembra una partita di ping &#8211; pong, con un andirivieni &#8220;dell&#8217;ultima parola ce l&#8217;ho solo io&#8221; che mette i brividi, a colpi di legge dello Stato. Rimane tanta solidariet\u00e0&#8230;<\/p>\n","protected":false},"author":37,"featured_media":95071,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-95070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95070"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95071"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}