{"id":95190,"date":"2018-07-04T11:00:31","date_gmt":"2018-07-04T09:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/uccisa-mentre-era-appartata-in-unauto-4-persone-fermate-tra-cui-il-killer\/"},"modified":"2023-01-16T18:55:47","modified_gmt":"2023-01-16T17:55:47","slug":"225806-uccisa-mentre-era-appartata-in-unauto-4-persone-fermate-tra-cui-il-killer","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/225806-uccisa-mentre-era-appartata-in-unauto-4-persone-fermate-tra-cui-il-killer\/","title":{"rendered":"VIDEO &#8211; Uccisa mentre era appartata in un&#8217;auto, 4 persone fermate tra cui il killer"},"content":{"rendered":"<h4>L&#8217;operazione di questa mattina \u00e8 stata ribattezzata \u201cDe Bello Gallico\u201d ed ha fatto luce sull\u2019omicidio della donna uccisa in macchina a Gallico nel mese di marzo.<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Il blitz della Squadra mobile disposto dalla Direzione Distrettuale Antimafia di Reggio Calabria ha portato all&#8217;esecuzione di quattro provvedimenti di fermo e sono in corso anche numerose perquisizioni. I quattro soggetti sono ritenuti responsabili, a vario titolo, di <strong>omicidio e tentato omicidio pluriaggravati,<\/strong> associazione mafiosa, detenzione e porto in luogo pubblico di armi da fuoco clandestine, danneggiamento aggravato mediante esplosione di colpi di arma da fuoco, furto e detenzione illegale di segni distintivi e oggetti in uso ai Corpi di Polizia, tutti aggravati dalla metodologia mafiosa. L&#8217;operazione \u201cDe Bello Gallico\u201d ha consentito di individuare l\u2019esecutore materiale dell\u2019omicidio di<strong> Fortunata Fortugno, 48 anni,<\/strong><em>\u00a0(nel riquadro in alto)<\/em> che fu uccisa con un colpo di pistola alla testa la sera del 16 marzo mentre era appartata con<strong> Demetrio Logiudice,<\/strong> di 53 anni, che rimase ferito ad una spalla, a bordo di un\u2019autovettura, in uno spazio a ridosso del torrente Gallico.<\/p>\n<h3>Il vero obiettivo del killer era Logiudice<\/h3>\n<p>L\u2019inchiesta \u201cDe Bello Gallico\u201d avrebbe accertato come il vero obiettivo del killer, che entr\u00f2 in azione la sera del 16 marzo scorso sul torrente Gallico, non era la donna assassinata ma Demetrio Logiudice che stava con lei in macchina, ritenuto vicino agli ambienti della potente clan Tegano che opera nella zona nord della citt\u00e0 di Reggio Calabria, coinvolto in operazioni antimafia che in passato hanno colpito la suddetta cosca della \u2018ndrangheta reggina.<\/p>\n<h3>Analizzati oltre 70 impianti di videosorveglianza<\/h3>\n<p>Un faticoso lavoro di estrapolazione, studio e analisi delle immagini di una settantina di impianti di videosorveglianza pubblica e privata; cos\u00ec gli investigatori della sezione omicidi della Squadra Mobile di Reggio Calabria sono arrivati ad individuare la macchina che il killer aveva utilizzato per raggiungere il luogo in cui si erano appartati i due amanti, effettuare un primo sopralluogo e successivamente compiere l\u2019agguato in cui fu uccisa freddamente la donna e fu ferito gravemente l\u2019uomo. <strong>Centinaia di ore di filmati<\/strong> passati sotto lente hanno permesso agli investigatori della Polizia di Stato di ricostruire le fasi dell\u2019appuntamento delle vittime, del sopralluogo, dell\u2019agguato e della fuga del killer, nonch\u00e9 della corsa verso l\u2019ospedale del ferito a bordo della macchina, con la donna colpita a morte.<\/p>\n<h4>GUARDA IL VIDEO<\/h4>\n<p><iframe loading=\"lazy\" title=\"Operazione De Bello Gallico\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/1kXv2CibQ40?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h3>L&#8217;auto del killer e l intercettazioni ambientali<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-225847 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/audi-killer-fortunata-fortugno-lo-giudice.jpg\" alt=\"\" width=\"413\" height=\"255\" title=\"\">Attraverso il confronto dei moltissimi filmati dei diversi impianti di video sorveglianza, i poliziotti della Squadra Mobile sono riusciti ad individuare <strong>l\u2019Audi A3 Sportback<\/strong> utilizzata dal sicario la sera del 16 marzo per compiere l\u2019agguato. Tutti gli accertamenti effettuati al riguardo, hanno dimostrato che la macchina era utilizzata esclusivamente da <strong>Paolo Chindemi, ventottenne<\/strong> di Gallico. Le intercettazioni ambientali disposte dalla Dda di Reggio Calabria, hanno consentito di raccogliere ulteriori e pregnanti elementi che, in combinazione con i dati acquisiti dagli impianti di video sorveglianza, con riferimento al mezzo utilizzato dal killer per compiere l\u2019agguato, sono andati a comporre un quadro indiziario grave, preciso e concordante a carico di Chindemi, quale esecutore materiale dell\u2019efferato delitto, che \u00e8 stato fermato questa notte ed \u00e8 figlio di Pasquale Chindemi, assassinato tre mesi prima a Gallico nel corso di un agguato.<\/p>\n<h3>I 4 provvedimenti di fermo<\/h3>\n<p>Nell\u2019ambito dell\u2019inchiesta \u201cDe Bello Gallico\u201d, gli investigatori della Squadra Mobile hanno ricostruito l\u2019assetto organizzativo ed operativo di un emergente gruppo mafioso, legato alla \u2018ndrangheta e dedito al compimento di reati contro la persona e il patrimonio, composto da <strong>Paolo Chindemi<\/strong> (esecutore materiale dell\u2019omicidio di Fortunata Fortugno e del tentato omicidio di Demetrio Logiudice) dallo zio <strong>Mario Chindemi<\/strong>\u00a0di 50 anni, da<strong> Santo Pellegrino<\/strong> di 32 anni e da<strong> Ettore Corrado Bilardi<\/strong> detto \u201cPietro\u201d di 66 anni, tutti sottoposti a fermo di indiziato di delitto per associazione mafiosa.<\/p>\n<p>Le intercettazioni ambientali hanno dimostrato che lo scopo fondamentale del sodalizio era quello di affermare a Gallico la propria leadership criminale conquistando spazi sempre pi\u00f9 ampi con l\u2019uso delle armi nelle azioni volte ad assumere il controllo delle attivit\u00e0 estorsive in danno di imprenditori e commercianti del luogo e ad eliminare esponenti delle fazioni contrapposte. Ad alcuni componenti del gruppo mafioso \u00e8 contestato un atto intimidatorio perpetrato a Gallico lo scorso 22 maggio, mediante l\u2019esplosione di alcuni colpi di fucile contro le serrande di due garage di un condominio di cinque piani.<\/p>\n<h4>Nella base del gruppo:\u00a0 armi, un giubbotto antiproiettile e divise della DIA<\/h4>\n<p>Gli investigatori della Squadra Mobile alcuni giorni fa, hanno scoperto durante un servizio di perlustrazione notturna, in alcuni luoghi periferici di Gallico superiore, la base logistica del sodalizio, composta da un\u2019esistente struttura in muratura, all\u2019interno della quale i poliziotti hanno rinvenuto e sequestrato<strong> una pistola semiautomatica calibro 7.65 mm, marca \u201cJ.P. Sauer&amp;SohnSuhl\u201d,<\/strong> modello \u201c1913\u201d, con matricola, completa di caricatore e 10 cartucce marca \u201cG.F.L.\u201d dello stesso calibro; un revolver, con tamburo a 6 camere di cartuccia, calibro 38 SP, privo di marca e matricola, completa di 6 cartucce marca &#8220;G.F.L.&#8221; dello stesso calibro; quattro casacche (fratini o pettorine) in tessuto di colore blu, riportante su entrambi i lat<strong>i la dicitura &#8220;DIA Direzione Investigativa Antimafia&#8221;<\/strong>; un giubbotto antiproiettile di colore blue, privo di qualsiasi contrassegno identificativo; tre passamontagna tipo \u201cmefisto\u201d e una batteria 12V 7Ah marca &#8220;Yamada&#8221; alla quale era applicato, con nastro adesivo isolante, un ricevitore marca \u201cAtecnica\u201d mod. D Multi 2 CH. Nel corso di precedenti perquisizioni, gli operatori della Squadra Mobile, avevano individuato e sequestrato anche alcuni motoveicoli che gli indagati &#8211; costituendo un gruppo di fuoco &#8211; avevano rubato per compiere azioni delittuose.<\/p>\n<h4>Il profilo di Bilardi<\/h4>\n<p>Tra i soggetti fermati\u00a0 dalla Polizia di Stato di Reggio Calabria spicca il nome di <strong>Ettore Corrado Bilardi, pericoloso pregiudicato<\/strong> che ha scontato lunghi anni di detenzione per <strong>omicidio<\/strong>, genero del boss storico della \u2018ndrangheta reggina don Mico (Domenico) Tripodo, assassinato nel 1977 all\u2019interno del carcere di Poggioreale a Napoli su mandato della cosca De Stefano; nonch\u00e9 cognato di\u00a0 Venanzio Tripodo, genero di\u00a0 Sebastiano Romeo, patriarca della storica famiglia di \u2018ndrangheta di San Luca\u00a0 (Stacchi).\u00a0 Attraverso l\u2019opera di mediazione di Bilardi, i membri del sodalizio di Gallico hanno stretto relazioni con esponenti di affermate e potenti cosche della \u2018ndrangheta operanti nei mandamenti tirrenico e ionico della provincia di Reggio Calabria.<\/p>\n<h3 style=\"text-align: center;\">I particolari delle indagini &#8211; VIDEO &#8211; INTERCETTAZIONI<\/h3>\n<h4 style=\"text-align: center;\"><span style=\"color: #ff6600;\">Clicca in basso per approfondire<\/span><\/h4>\n<h2 style=\"text-align: center;\"><!--nextpage--><\/h2>\n<p>&nbsp;<\/p>\n<p>Erano da poco passate le 22.30 il 16 marzo scorso quando\u00a0un uomo e una donna attinti da colpi d\u2019arma da fuoco si erano presentati in ospedale. Fortunata Fortugno per\u00f2 era gi\u00e0 morta mentre Lo Giudice presentava una ferita alla spalla. Dalle prime ricostruzioni era emerso che la coppia, seduta sul sedile posteriore del fuoristrada dell\u2019uomo, si trovava in una zona isolata prossima al torrente Gallico dell\u2019omonimo quartiere di Reggio Calabria, quando ad un certo punto \u00e8 arrivata un&#8217;auto, a velocit\u00e0 moderata, dalla quale \u00e8 sceso il killer che ha sparato contro i due amanti,\u00a0 due ai quattro colpi di arma da fuoco uno dei quali ha raggiunto la donna alla testa e un altro, l\u2019uomo alla spalla.<\/p>\n<p>Logiudice nonostante la ferita avrebbe messo in moto e guidato fino in ospedale mentre il killer avrebbe esploso contro il mezzo altri colpi d&#8217;0arma da fuoco. La corsa disperata verso l\u2019ospedale per\u00f2 non \u00e8 servita perch\u00e8 Fortunata Fortugno \u00e8 arrivata cadavere al pronto soccorso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-225850 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/conferenza-stampa-omicidio-fortugno-fortunata-03.jpg\" alt=\"\" width=\"441\" height=\"295\" title=\"\">Logiudice a quel punto unico testimone del delitto, non \u00e8 riuscito a fornire indicazioni tali da individuare l\u2019esecutore materiale dell\u2019omicidio o i mandanti anche se, l\u2019ambito criminale in cui esso era maturato, le modalit\u00e0 esecutive tipicamente mafiose e la personalit\u00e0 dell\u2019uomo, vittima dell\u2019agguato, con precedenti di polizia per associazione mafiosa, non poteva non essere riconducibile a contesti di criminalit\u00e0 organizzata. Per questo motivo gli inquirenti hanno subito orientato le indagini sul fatto che il vero obiettivo del killer fosse proprio Logiudice.<\/p>\n<p>In un primo momento per\u00f2 gli inquirenti non avrebbero avuto elementi tecnici e testimoniali e cos\u00ec hanno iniziato un lavoro imponente di acquisizione delle immagini riprese da circa 70 impianti di video sorveglianza pubblica e privata presenti nei luoghi prossimi e meno prossimi a quello in cui era stato perpetrato l\u2019efferato delitto.<\/p>\n<p>L\u2019accurata analisi dell\u2019impressionante mole di immagini acquisite nei giorni immediatamente successivi al duplice delitto dagli impianti di video sorveglianza &#8211; per un totale di <strong>diverse centinaia di ore<\/strong> di filmati passati letteralmente sotto lente dagli inquirenti &#8211; e i riscontri ottenuti dai servizi di osservazione e controllo del territorio, hanno consentito agli investigatori della Sezione Omicidi della Squadra Mobile non solo di ricostruire le fasi dell\u2019incontro delle vittime, ma anche di individuare in un\u2019Audi A3 Sportback, in uso esclusivo a Paolo Chindemi, l\u2019autovettura utilizzata dal killer la sera del 16 marzo per compiere prima il sopralluogo e subito dopo l\u2019agguat.<\/p>\n<p>Le immagini hanno permesso di ricostruire la fase dell\u2019appuntamento dei due amanti, la fase del sopralluogo, dell\u2019agguato e della fuga dell\u2019attentatore, nonch\u00e9 la corsa verso l\u2019ospedale del soggetto ferito a bordo della macchina con la donna esanime. Poi le molteplici attivit\u00e0 tecniche di intercettazione ambientale locale e veicolare hanno consentito di raccogliere ulteriori e pregnanti elementi che, in combinazione con quelli gi\u00e0 acquisiti dagli impianti di video sorveglianza con riferimento al mezzo utilizzato dal killer per compiere l\u2019agguato, andavano a comporre un quadro indiziario grave, preciso e concordante a carico di Chindemi, quale esecutore materiale dell\u2019efferato delitto.<\/p>\n<h4>Intercettazioni ambientali<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-225851 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/intercettazioni-omicidio-fortugno-fortunata-.jpg\" alt=\"\" width=\"357\" height=\"211\" title=\"\">Nel corso di una conversazione ambientale captata in macchina, gli indagati, tra cui Paolo Chindemi,\u00a0facevano riferimento alla circostanza che la donna si stava voltando per guardare indietro quando \u00e8 stata colpita, al fatto che la stessa sia morta per colpa dell\u2019uomo con cui era in macchina, al quale aveva sostanzialmente fatto da scudo, salvandogli la vita.\u00a0In un\u2019altra conversazione ambientale, Chindemi riferiva inoltre (e pertanto confessava) di aver commesso un omicidio.<\/p>\n<h4><span style=\"color: #ff0000;\">GUARDA IL VIDEO &#8211; la sera dell&#8217;agguato e le intercettazioni<\/span><\/h4>\n<p><iframe loading=\"lazy\" title=\"L&#039;omicidio e le intercettazioni\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/5r6VUA2XJHk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Un gruppo mafioso e armato<\/h4>\n<p>L\u2019inchiesta sul duplice fatto di sangue ha portato alla luce anche l\u2019esistenza di un emergente gruppo mafioso, aderente alla \u2018ndrangheta, dedito alla consumazione di delitti contro la persona e il patrimonio composto da Paolo Chindemi, Mario Chindemi , Santo Pellegrino e Ettore Corrado Bilardi detto \u201cPietro\u201d. Una consorteria facente capo ai due Chindemi, nata per affermare la propria leadership criminale, conquistando spazi sempre pi\u00f9 ampi nel territorio di Gallico, anche con l\u2019uso delle armi, pianificando azioni volte ad assumere il controllo delle attivit\u00e0 estorsive in danno di imprenditori e commercianti del luogo e ad eliminare esponenti delle fazioni contrapposte.<\/p>\n<p>Le indagini hanno anche fatto luce anche su un atto intimidatorio posto in essere dal gruppo Chindemi, lo scorso 23 maggio, mediante l\u2019esplosione di alcuni colpi di fucile contro le serrande di due garage di un condominio di cinque piani a Gallico. E ancora lo\u00a0scorso 19 giugno, durante una perlustrazione notturna di alcuni luoghi isolati, utilizzati dai Chindemi come basi logistiche per le attivit\u00e0 delittuose del gruppo, gli investigatori della Squadra Mobile hanno ritrovato armi e addirittura quattro casacche in tessuto di colore blu, riportante su entrambi i lati la dicitura \u201cDIA Direzione Investigativa Antimafia\u201d.<\/p>\n<h4>Bilardi, personaggio di alta caratura criminale<\/h4>\n<p>Milita nel gruppo Chindemi anche\u00a0un pregiudicato di elevato spessore criminale ovvero Ettore Corrado Bilardi, gi\u00e0 condannato a lunghi anni di reclusione per omicidio, genero del boss storico della \u2018ndrangheta di Reggio Calabria don Mico (Domenico) Tripodo, assassinato nel 1977 all\u2019interno del carcere di Poggioreale su mandato dei De Stefano, nonch\u00e9 cognato di Venanzio Tripodo genero di Sebastiano Romeo, patriarca della storica famiglia di \u2018ndrangheta di San Luca (RC) intesa \u201cI Stacchi\u201d. Gli appartenenti al gruppo Chindemi &#8211; attraverso l\u2019opera di qualificata mediazione del Bilardi &#8211; hanno intessuto relazioni con esponenti di affermate cosche della \u2018ndrangheta operanti nei mandamenti tirrenico e ionico della provincia di Reggio Calabria.<\/p>\n<h3>I reati contestati ai quattro soggetti<\/h3>\n<p>&#8211; Paolo Chindemi risponde del delitto di omicidio e tentato omicidio pluriaggravato anche dalle modalit\u00e0 mafiose (omicidio Fortunata Fortugno e tentato omicidio Demetrio Logiudice) e di detenzione e porto della pistola utilizzata per commetterlo;<br \/>\n&#8211; Paolo Chindemi, Mario\u00a0Chindemi, Santo Pellegrino e Bilardi Ettore Corrado sono accusati di associazione mafiosa; detenzione e porto in luogo pubblico di armi da fuoco (pistole, revolver e fucili, clandestini e comuni da sparo) aggravati dalla modalit\u00e0 mafiose; detenzione illegale di segni distintivi e oggetti in uso ai Corpi di Polizia (quattro casacche della DIA e un giubbotto antiproiettile) aggravati dalle modalit\u00e0 mafiose; furto di motocicli aggravato anche dalle modalit\u00e0 mafiose.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;operazione di questa mattina \u00e8 stata ribattezzata \u201cDe Bello Gallico\u201d ed ha fatto luce sull\u2019omicidio della donna uccisa in macchina a Gallico nel mese di marzo.<\/p>\n","protected":false},"author":22,"featured_media":95191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-95190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95190"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95191"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}