{"id":95252,"date":"2018-07-05T13:18:04","date_gmt":"2018-07-05T11:18:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/endometriosi-il-dolore-invisibile-spiegato-dal-chirurgo-e-da-una-sua-paziente\/"},"modified":"2023-01-16T18:55:52","modified_gmt":"2023-01-16T17:55:52","slug":"226012-endometriosi-il-dolore-invisibile-spiegato-dal-chirurgo-e-da-una-sua-paziente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/226012-endometriosi-il-dolore-invisibile-spiegato-dal-chirurgo-e-da-una-sua-paziente\/","title":{"rendered":"Endometriosi, il dolore \u2018invisibile\u2019 spiegato dal chirurgo e da una sua paziente"},"content":{"rendered":"<h4>\u201cTra le cause sono convinto vi sia l\u2019inquinamento\u201d afferma il professor Giuseppe Crovini che si occupa di endometriosi da oltre trenta anni. Nella sua carriera ha trattato oltre mille casi e creato un centro specializzato tra i pi\u00f9 all\u2019avanguardia d\u2019Italia<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>FIDENZA (PR) &#8211; Una malattia che colpisce una donna su dieci in et\u00e0 fertile. L\u2019endometriosi, patologia spesso sconosciuta, ha conseguenze inimmaginabili sulla vita delle pazienti. \u201cA darmi il buongiorno la mattina sono i dolori, \u2013 spiega una trentacinquenne che ne soffre da circa venti anni \u2013 non la sveglia. E\u2019 come se avessi nel corpo tanti piccoli folletti: alcuni impegnati a squarciarmi il ventre con delle forbici, altri a sbriciolarmi la schiena con uno scalpello. Chi ha partorito sostiene che siano uguali alle fitte del travaglio. La differenza \u00e8 che non durano qualche ora, ma giorni, settimane, mesi. <strong>Lavorare diventa un incubo, si spera di arrivare a fine giornata imbottendosi di antidolorifici senza dover chiedere permessi, ferie, malattia<\/strong>. Impossibile poter pianificare una serata o una gita fuori porta perch\u00e9 il dolore ti annienta (fisicamente e psicologicamente) e il tempo libero \u00e8 l\u2019unica occasione in cui si pu\u00f2 star male senza dare troppe giustificazioni. Questa \u00e8 la normalit\u00e0. Poi ci sono i \u2018periodi caldi\u2019, quelli in cui ti ritrovi ricoverata in ospedale, allettata per interventi chirurgici invasivi o emorragie che ti portano a perdere sangue per lunghe settimane.<\/p>\n<p>&nbsp;<\/p>\n<p>Chi non vive quotidianamente i tuoi disagi neanche immagina questo inferno in quanto \u2018da fuori\u2019 la malattia non si vede. Esteticamente siamo infatti donne normalissime, in piena forma\u201d. A chiarirlo \u00e8 un veterano della materia: <strong>il Professor Giuseppe Crovini. Da oltre trenta anni si occupa di endometriosi. Ha iniziato nel 1981 ad esercitare la<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-226038 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/crovini-giuseppe-329x280.jpg\" alt=\"\" width=\"329\" height=\"280\" title=\"\"> professione e dal 2002 ha diretto il reparto di Ostetricia e Ginecologia dell\u2019Ospedale di Vaio a Fidenza, in provincia di Parma<\/strong>, trasformandolo in uno dei centri d\u2019eccellenza pi\u00f9 all\u2019avanguardia d\u2019Italia per le donne affette da endometriosi. Da poco pi\u00f9 di un mese \u00e8 in pensione, ma non cessa di dare il suo contributo nel migliorare la qualit\u00e0 di vita delle sue pazienti. Ha assistito all\u2019evoluzione dell\u2019approccio terapeutico alla patologia e formato un\u2019equipe specializzata che continuer\u00e0 ad affiancare per trattare i casi pi\u00f9 complessi. \u201cL&#8217;endometriosi \u00e8 una patologia invalidante \u2013 spiega il Professore Crovini &#8211; in quanto il dolore \u00e8 il sintomo fondamentale che ci porta alla diagnosi. La patogenesi \u00e8 ancora controversa in quanto il reflusso mestruale \u00e8 sicuramente la causa iniziale.<\/p>\n<p>&nbsp;<\/p>\n<p>Un fenomeno che \u00e8 stato dimostrato essere presente nella maggior parte delle donne di cui solo una modesta percentuale sviluppa endometriosi. <strong>Negli ultimi anni si \u00e8 valutato come possibile causa l&#8217;inquinamento ambientale (di cui personalmente sono convinto), i pesticidi, i derivati del catrame, ecc.<\/strong> Oggi i numeri delle donne affette da endometriosi sono aumentati, ma solo perch\u00e9 si conosce di pi\u00f9 rispetto a trent&#8217;anni fa. Negli anni Ottanta \u2013 ricorda il Professore Crovini &#8211; l&#8217;unica terapia che si conosceva per l\u2019endometriosi era quella chirurgica. Negli anni grazie al Prof. Vercellini, che per pi\u00f9 di 20 anni ha sostenuto la terapia farmacologica con progesterone, \u00e8 possibile integrare le due teorie. Non credo che siano aumentati i casi di endometriosi, ma sicuramente \u00e8 aumentata la conoscenza dell&#8217;endometriosi. Nel nostro reparto sono state trattate circa un migliaio di casi. I pi\u00f9 complessi su cui mi sono trovato ad intervenire sono stati i noduli del setto retto-vaginale e intestinali, per capirci l&#8217;endometriosi del comparto posteriore. Collaborer\u00f2 ancora con la mia equipe poich\u00e9 la direzione dell&#8217;ospedale mi ha permesso, tramite un contratto a titolo gratuito, di poter accedere in sala operatoria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cTra le cause sono convinto vi sia l\u2019inquinamento\u201d afferma il professor Giuseppe Crovini che si occupa di endometriosi da oltre trenta anni. Nella sua carriera ha trattato oltre mille casi e creato un centro specializzato tra i pi\u00f9 all\u2019avanguardia d\u2019Italia<\/p>\n","protected":false},"author":18,"featured_media":95253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,52],"tags":[],"class_list":["post-95252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95252"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95253"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}