{"id":9527,"date":"2012-12-12T14:59:53","date_gmt":"2012-12-12T13:59:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9527"},"modified":"2023-01-17T13:42:41","modified_gmt":"2023-01-17T12:42:41","slug":"4215-le-telecamere-di-linea-blu-sulla-costa-ionica-crotonese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4215-le-telecamere-di-linea-blu-sulla-costa-ionica-crotonese\/","title":{"rendered":"Le telecamere di &#8220;Linea Blu&#8221; sulla costa ionica crotonese"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211; L&#8217;ultima puntata di &#8220;Linea Blu&#8221;, la popolare trasmissione di RaiUno condotta da Donatella Bianchi, sara&#8217; dedicata alla Calabria, ed in particolare modo, alla costa ionica<\/p>\n<p>  <!--more-->  <\/p>\n<p>compresa tra Le Castella e Ciro&#8217; Marina. L&#8217;iniziativa e&#8217; stata presentata oggi nel corso di una conferenza stampa che si e&#8217; svolta a Catanzaro, nella sede della presidenza della Giunta regionale. Presenti l&#8217;assessore regionale all&#8217;Ambiente, Francesco Pugliano, il responsabile della sede Rai Calabria, Demetrio Crucitti, la conduttrice Donatella Bianchi, il direttore generale del Dipartimento regionale al Turismo, Raffaele Rio. La puntata, l&#8217;ultima di questa stagione, andra&#8217; in onda sabato alle 14,30. &#8220;Il mare della Calabria &#8211; ha detto Pugliano &#8211; sara&#8217; al centro dell&#8217;attenzione, protagonista della puntata con la possibilita&#8217; per la Regione di avere nuovi spunti e nuove idee per il futuro. Con 780 chilometri di costa, con storia e tradizioni, occorre risvegliare la cultura del mare e trasferirla alle nuove generazioni. Nel tratto dell&#8217;Area marina protetta di Isola Capo Rizzuto, protagonista della puntata, abbiamo un museo di flora e fauna, e oltre agli sforzi economici per superare i difetti strutturali dobbiamo avere un grande impegno per recuperare il rapporto con il mare e con la coscienza ambientale&#8221;. Per Donatella Bianchi &#8220;la puntata di sabato e&#8217; un omaggio alla Calabria, dove mancavamo da qualche tempo, e dove speriamo di tornare per riaprire la prossima edizione. Ci saranno molti spunti su cui riflettere &#8211; ha aggiunto la conduttrice &#8211; perche&#8217; troppo spesso dimentichiamo il valore aggiunto del mare e come le politiche di conservazione e gestione non possono essere disgiunte&#8221;.<\/p>\n<p>Fonte AGI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;ultima puntata di &#8220;Linea Blu&#8221;, la popolare trasmissione di RaiUno condotta da Donatella Bianchi, sara&#8217; dedicata alla Calabria, ed in particolare modo, alla costa ionica<\/p>\n","protected":false},"author":22,"featured_media":9528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9527"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9528"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}