{"id":95391,"date":"2018-07-08T10:19:09","date_gmt":"2018-07-08T08:19:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-cane-morde-bimbo-di-4-anni-i-proprietari-sappiamo-che-e-aggressivo\/"},"modified":"2023-01-16T18:56:00","modified_gmt":"2023-01-16T17:56:00","slug":"226480-cosenza-cane-morde-bimbo-di-4-anni-i-proprietari-sappiamo-che-e-aggressivo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/226480-cosenza-cane-morde-bimbo-di-4-anni-i-proprietari-sappiamo-che-e-aggressivo\/","title":{"rendered":"Cosenza, cane morde bimbo di 4 anni: i proprietari &#8220;sappiamo che \u00e8 aggressivo&#8221;"},"content":{"rendered":"<h4>E&#8217; accaduto venerd\u00ec sera su corso Mazzini, durante la visita ai dinosauri. Il proprietario che ha tentato di dileguarsi rintracciata spiega che il cane \u00e8 difficile, proviene da un canile e ha morso anche lei e il figlio per cui \u00e8 normale che sia accaduto<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Pubblichiamo la lettera ricevuta dalla madre del bambino con la richiesta di rimanere in anonimato &#8211; scrive la signora &#8211; &#8220;per via dell\u2019atteggiamento minaccioso che hanno avuto i proprietari del cane&#8221;<\/p>\n<p>\u00abVorrei che il tutto restasse in ANONIMO . Venerdi sera decido di portare i bimbi ad ammirare i magnifici dinosauri piazzati sul Corso. Arrivati a piazza Bilotti i bambini hanno iniziato a giocare con altri bimbi e mio figlio in particolare con un bimbo, e fin qui tutto tranquillo, fino a quando il compagno di merenda del mio piccolo si incammina verso un tavolino dove era seduta la mamma con un cane di media taglia di fianco , dimenticando un gioco che mio figlio gentilmente e prontamente \u00e8 andato a restituire. Arrivato al tavolino e ad un metro dal cane succede che lo stesso cane si fionda sul mio piccolo azzannandolo alla coscia destra. Il bambino terrorizzato e dolorante corre verso di me con la gamba morsa.<\/p>\n<p>La proprietaria si alza di tutta fretta e scappa via, io sconvolta non riesco a muovermi potete immaginare il piccolo come piangeva \u00a0per paura e dolore. Mio cognato rincorre la signora e riesce a reperire nominativo e numero di telefono. Inizia la corsa in ospedale dove mio figlio viene immediatamente visitato e medicato. Qui mi viene richiesto se mi avessero dato un libretto sanitario,per capire se l animale fosse vaccinato ma ovviamente non ho nulla. La mattina succesiva alla nottataccia passata in ospedale contatto subito la signora chiedendo i documenti della bestia, inizialmente \u00e8 disponibile a darmeli, ma poi mi chiama nel pomeriggio dicendo che lei era andata tranquillamente al mare e che la salute di mio figlio poteva aspettare fino a luned\u00ec. Dopo di cio&#8217; sono seguite una serie di telefonate dove insisto per avere il libretto. Ma nulla lei \u00e8 al mare tranquilla. Durante le telefonate Mi conferma che il cane \u00e8 un cane difficile che proviene dal canile che spesso ha morso lei, ha morso anche il figlio, e che quindi era normale quello che era accuduto perch\u00e9 \u00a0il cane \u00e8 aggressivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-226483 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/image1-207x280.jpg\" alt=\"\" width=\"207\" height=\"280\" title=\"\">Vengo anche chiamata dal marito che in tono minaccioso mi dice che io non sapevo chi fosse lui. Questo \u00e8 cio che potrebbe accadere a chi vorrebbe fare una passeggiata tranquilla in una sera d estate. Sono molto indignata per il comportamento dei proprietari, MA ANDR\u00d2 FINO IN FONDO, PERCH\u00c9 LA SALUTE DI MIO FIGLIO VALE MOLTO DI PI\u00d9 DI UNA PASSEGGIATA AL MARE. Si chiede tanto rispetto per gli animali, ed io fino ad oggi ne ho sempre avuto, ma anche la nostra tranquillit\u00e0 non deve essere un optional. Un invito per chi conosce le proprie bestie abbiate la bont\u00e0 di utilizzare museruole e guinzaglio, quello che \u00e8 accaduto a me sarebbe potuto accadere a chiunque. Mio figlio dovr\u00e0 fare una cura antibiotica e restare in osservazione per un po di tempo. Morale della favola io ho perso la mia tranquillit\u00e0 e mio figlio pure\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; accaduto venerd\u00ec sera su corso Mazzini, durante la visita ai dinosauri. Il proprietario che ha tentato di dileguarsi rintracciata spiega che il cane \u00e8 difficile, proviene da un canile e ha morso anche lei e il figlio per cui \u00e8 normale che sia accaduto<\/p>\n","protected":false},"author":21,"featured_media":95392,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-95391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95391"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95392"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}