{"id":95448,"date":"2018-07-12T04:00:31","date_gmt":"2018-07-12T02:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/exit-deviazioni-in-arte-e-musica-edoardo-leo-in-scena-al-castello-svevo\/"},"modified":"2023-01-16T18:56:05","modified_gmt":"2023-01-16T17:56:05","slug":"226721-exit-deviazioni-in-arte-e-musica-edoardo-leo-in-scena-al-castello-svevo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/226721-exit-deviazioni-in-arte-e-musica-edoardo-leo-in-scena-al-castello-svevo\/","title":{"rendered":"&#8216;Exit. Deviazioni in arte e musica&#8217;. Edoardo Leo in scena al Castello Svevo"},"content":{"rendered":"<h4><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">Dopo il concerto del pianista internazionale Roberto Cacciapaglia, <b>oggi\u00a0<\/b>sar\u00e0 l\u2019istrionico attore e regista romano\u00a0<b>Edoardo Leo<\/b>\u00a0a calcare il palco\u00a0in occasione della seconda edizione di \u201c<b>Exit. Deviazioni in arte e musica<\/b>\u201d.<\/span><\/span><br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">COSENZA -\u00c9 con la rassegna culturale organizzata da\u00a0<b>Piano B<\/b>, per garantire una via di fuga dalla realt\u00e0 e osservare il mondo secondo un altro ritmo, che la citt\u00e0, a partire dalle 21, ospiter\u00e0 il pregiato reading-spettacolo di Leo, dal titolo \u201c<b>Ti racconto una storia. Letture semiserie e tragicomiche<\/b>\u201d. Attraverso le improvvisazioni musicali di\u00a0<b>Jonis Bascir<\/b>, il secondo appuntamento di \u201c<b>Exit<\/b>\u201d porter\u00e0 in scena tutti gli appunti, le suggestioni, le letture e i pensieri che l\u2019attore di pellicole e fiction di successo ha raccolto dall\u2019inizio della sua carriera ad oggi.\u00a0<\/span><\/span><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">Non si tratta, pertanto, di un canonico e tradizionale allestimento teatrale: vent\u2019anni di ritagli, ricordi e aneddoti animeranno la serata e racconteranno spaccati di vita umana coniugando parole a melodie. Sotto il cielo stellato di una straordinaria location, appunto il\u00a0<b>castello federiciano<\/b>, si dar\u00e0 voce non solo ai racconti e ai monologhi di celebri scrittori (Benni, Calvino, Marquez, Eco, Piccolo\u2026) ma anche ad articoli di giornale, brani e testi di giovani autori contemporanei e dello stesso Edoardo Leo.<\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-226723 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/image1-locandina-edoardo-leo-246x400.jpg\" alt=\"\" width=\"246\" height=\"400\" title=\"\"><\/p>\n<p><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">Gi\u00e0 vincitore di numerosi premi (recentemente ha ritirato il Nastro d\u2019Argento come personaggio dell\u2019anno 2018) e diretto da importanti\u00a0\u00a0maestri della settima arte, tra cui\u00a0<b>Ettore Scola, Woody Allen, Sydney Sibilla\u00a0<\/b>e<b>\u00a0Paolo Genovese<\/b>, Leo omagger\u00e0 l\u2019oralit\u00e0 delle storie e il piacere di raccontarle. Nell\u2019epoca dove il tempo scorre veloce, lo spettacolo in questione restituir\u00e0 intimi momenti di convivialit\u00e0 e confronto, senza dimenticare comicit\u00e0 e risate che certamente coinvolgeranno il pubblico cosentino.\u00a0<\/span><\/span><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">Quello di Leo, dunque, si inserisce pienamente nel cartellone di \u201c<b>Exit<\/b>\u201d, abbracciandone l\u2019idea portante. Al pari della fortunata rassegna, \u201c<b>Ti racconto una storia<\/b>\u201d cambia forma e contenuto ogni volta in base allo spazio e all\u2019occasione, senza tuttavia perdere il desiderio di far ridere e pensare insieme e regalare emozioni uniche. Tutto pronto, insomma, per una serata all\u2019insegna del dialogo tra diverse espressioni artistiche che si intrecciano a quello della contemporaneit\u00e0 e tradizione.\u00a0<\/span><\/span><span class=\"ox-4f21626bcc-m_4669613671240395794font\"><span class=\"ox-4f21626bcc-m_4669613671240395794size\">Non rimane che partecipare per riscoprire la pi\u00f9 antica delle forme di comunicazione, il teatro di parola, immersa in una dimensione magica.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il concerto del pianista internazionale Roberto Cacciapaglia, oggi\u00a0sar\u00e0 l\u2019istrionico attore e regista romano\u00a0Edoardo Leo\u00a0a calcare il palco\u00a0in occasione della seconda edizione di \u201cExit. Deviazioni in arte e musica\u201d.<\/p>\n","protected":false},"author":20,"featured_media":95449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-95448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95448"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95449"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}