{"id":95584,"date":"2018-07-12T11:00:12","date_gmt":"2018-07-12T09:00:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pirata-della-strada-uccide-19enne-sulla-106-arrestato-salma-sara-rimpatriata\/"},"modified":"2023-01-16T18:56:14","modified_gmt":"2023-01-16T17:56:14","slug":"227212-pirata-della-strada-uccide-19enne-sulla-106-arrestato-salma-sara-rimpatriata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/227212-pirata-della-strada-uccide-19enne-sulla-106-arrestato-salma-sara-rimpatriata\/","title":{"rendered":"Pirata della strada uccide 19enne sulla 106, arrestato. Salma sar\u00e0 rimpatriata"},"content":{"rendered":"<h4>La tragedia risale al 14 giugno, e l\u2019investitore \u00e8 stato arrestato per omicidio stradale. La vittima, un ragazzo di appena 19 anni<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Sar\u00e0 rimpatriata nei prossimi giorni nel suo Paese per il funerale e per darle degna sepoltura la salma di <strong>Jallow Banna, 19enne,<\/strong> scampato al dramma della guerra civile in Gambia che ha trovato la morte in Italia, a Corigliano, sulla Statale 106, investito da un pirata della strada che lo ha lasciato agonizzante sull\u2019asfalto. L&#8217;automobilista tra l&#8217;altro non aveva l&#8217;assicurazione al mezzo. Una tragica vicenda che ha commosso e sollevato allo stesso tempo indignazione. Per far rimpatriare la salma \u00e8 intervenuto Studio 3A, societ\u00e0 specializzata a livello nazionale nella valutazione delle responsabilit\u00e0 in ogni tipologia di sinistro, a tutela dei diritti dei cittadini, e partner legale dell\u2019Associazione Basta Vittime Sulla Strada Statale 106.<\/p>\n<p>Il terribile incidente si \u00e8 verificaot il 14 giugno, alle 21.30, all\u2019altezza del km 16 della \u201cStatale della morte\u201d, nel territorio di Corigliano, dove il gambiano era ospite in una struttura di accoglienza. Il ragazzo procedeva in sella ad una bici quand\u2019\u00e8 stato tamponato da quella che si sarebbe poi scoperto essere un\u2019Alfa Romeo 147 condotta da <strong>Rosario Docimo, 23 anni,<\/strong> di Corigliano Rossano: un impatto tremendo. Il 19enne \u00e8 stato investito dal lato anteriore destro della vettura, \u00e8 stato sbalzato sul parabrezza e ha impattato anche contro la portiera destra, finendo esanime sull\u2019asfalto. I suoi traumi erano troppo gravi ed \u00e8 deceduto poche ore dopo il ricovero all\u2019ospedale di Rossano.<\/p>\n<p>Il<strong> 23enne anzich\u00e9 fermarsi a prestargli soccorso, \u00e8 fuggito<\/strong> lasciandolo morente sul ciglio della strada. Sono stati i carabinieri di Corigliano Calabro, i primi a intervenire sul posto e a soccorrere <strong>Banna<\/strong>, a rintracciare dopo sole 24 ore l\u2019auto pirata grazie a un tenace lavoro di ricerca partendo dalla campionatura di alcune parti della carrozzeria staccatesi con il colpo e ritrovate in loco. I militari sono risaliti al proprietario, il padre del ventitreenne, e quindi al figlio, che usava abitualmente la vettura e che \u00e8 subito crollato, ammettendo le sue responsabilit\u00e0 e anche tutte le operazioni messe in atto per coprire il misfatto, con l\u2019aiuto della compagna e del fratello. I quali, oltre ad avergli fatto nascondere la macchina, <strong>risultata puntualmente distrutta nella parte anteriore destra<\/strong> e con ancora le tracce di sangue: dovranno rispondere a loro volta di omissione di soccorso. Docimo, che peraltro aveva gi\u00e0 precedenti specifici per reati in materia di Codice della Strada, oltre che contro la persona e il patrimonio, \u00e8 stato arrestato con le pesanti accuse di omicidio stradale e omissione di soccorso, su disposizione del Pubblico Ministero della Procura di Castrovillari, dott.ssa Angela Continisio, che coordina le indagini e che ha subito aperto un procedimento penale a carico dell\u2019investitore, ordinando anche l\u2019autopsia sulla salma di Banna.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-227217 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/banna.jpg\" alt=\"\" width=\"326\" height=\"191\" title=\"\">Una nuova brutta pagina che ha colpito tutta la comunit\u00e0, a cominciare dagli altri profughi e dagli operatori del centro di accoglienza. E sono stati proprio uno dei responsabili della struttura e un cugino della vittima, che opera come mediatore culturale, a chiedere a Studio 3A, tramite il consulente personale Luigi Cisonna, di occuparsi del caso e di assistere i familiari del giovane, che ha un fratello in Italia, mentre la mamma e le sorelle vivono in Gambia. Studio 3A seguir\u00e0 tutte le fasi del procedimento penale e si batter\u00e0 anche per ottenere un equo risarcimento per i familiari di Jallow Banna per la grave perdita subita: un\u2019impresa complicata dal fatto che la vettura non \u00e8 assicurata e che ci si dovr\u00e0 rapportare con le procedure notoriamente \u201cestenuanti\u201d del Fondo Vittime della strada.<strong> Grazie anche all\u2019aiuto del consolato del Gambia in Italia<\/strong>, \u00e8 stata recuperata tutta la documentazione necessaria dei familiari del ragazzo che vivono nel Paese africano, e poi si \u00e8 proceduto al finanziamento del rimpatrio della salma del ragazzo, che era a disposizione gi\u00e0 da un paio di settimane all\u2019obitorio dell\u2019ospedale di Corigliano e che nei prossimi giorni potr\u00e0 finalmente fare ritorno nella sua terra natale per ricevere l\u2019ultimo saluto e per riposare in pace. Ma in attesa di una giustizia che dovr\u00e0 essere esemplare.<\/p>\n<p>In riferimento al rimpatrio della salma l\u2019Associazione <strong>\u201cBasta Vittime Sulla Strada Statale 106\u201d<\/strong> ha espresso grande apprezzamento: ora la mamma di Jallow Banna e le amate sorelle potranno riavere il corpo del ragazzo che dalla sua morte ha determinato l\u2019inizio di un calvario di dolore in questa Famiglia gi\u00e0 piena di grandi difficolt\u00e0. La scelta di Studio 3A, infine, secondo l\u2019Associazione, sotto il profilo umano e non solo, \u00e8 meritevole e degna di nota ma concorre anche a rendere pi\u00f9 apprezzato il rapporto di partnership ormai instaurato con questa realt\u00e0 che opera \u2013 come di evince da questo caso \u2013 con finalit\u00e0 ed intendi virtuosi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tragedia risale al 14 giugno, e l\u2019investitore \u00e8 stato arrestato per omicidio stradale. La vittima, un ragazzo di appena 19 anni<\/p>\n","protected":false},"author":21,"featured_media":95585,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-95584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95584"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95585"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}